{"id":97318,"date":"2025-09-24T09:19:30","date_gmt":"2025-09-24T13:19:30","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97318"},"modified":"2025-09-24T09:19:30","modified_gmt":"2025-09-24T13:19:30","slug":"prefeitura-de-cuiaba-realiza-duas-audiencias-publicas-para-discutir-orcamento","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeitura-de-cuiaba-realiza-duas-audiencias-publicas-para-discutir-orcamento\/","title":{"rendered":"Prefeitura de Cuiab\u00e1 realiza duas audi\u00eancias p\u00fablicas para discutir or\u00e7amento"},"content":{"rendered":"<p data-end=\"306\" data-start=\"111\">A Prefeitura de Cuiab\u00e1, por interm\u00e9dio da Secretaria Municipal de Planejamento, realiza na quinta-feira (25) duas audi\u00eancias p\u00fablicas para discutir a elabora\u00e7\u00e3o da Lei Or\u00e7ament\u00e1ria Anual (LOA).<\/p>\n<p data-end=\"594\" data-start=\"308\">A primeira audi\u00eancia ser\u00e1 realizada \u00e0s 9h, no audit\u00f3rio do Cuiab\u00e1 Prev, localizado na Rua S\u00e3o Benedito, n\u00ba 645, bairro Lixeira. A segunda ocorrer\u00e1 no audit\u00f3rio da Escola Municipal Ranulpho Paes de Barros, situada na Rua Deputado Celso Mendes Quintela, s\/n, bairro Jardim Santa Isabel.<\/p>\n<p data-end=\"839\" data-start=\"596\">A LOA \u00e9 a lei que estima a receita e fixa as despesas do munic\u00edpio para o ano de 2026. Antes de ser encaminhada para vota\u00e7\u00e3o dos vereadores, o que ocorre tradicionalmente em dezembro, cabe ao Poder Executivo estimular a participa\u00e7\u00e3o popular.<\/p>\n<p data-end=\"1127\" data-start=\"841\">A Lei Or\u00e7ament\u00e1ria Anual define o valor que caber\u00e1 a cada uma das secretarias municipais para a execu\u00e7\u00e3o de pol\u00edticas p\u00fablicas em 2026. Nesse contexto, est\u00e1 inclu\u00eddo o debate sobre os recursos destinados \u00e0 educa\u00e7\u00e3o, sa\u00fade, habita\u00e7\u00e3o, infraestrutura, assist\u00eancia social e outras \u00e1reas.<\/p>\n<p data-end=\"1475\" data-start=\"1129\">\u201c\u00c9 um compromisso do prefeito Abilio Brunini trabalhar o or\u00e7amento pautado nos crit\u00e9rios de transpar\u00eancia e legalidade. A participa\u00e7\u00e3o popular no debate da formula\u00e7\u00e3o do or\u00e7amento \u00e9 importante para o avan\u00e7o social e econ\u00f4mico, pois \u00e9 a oportunidade de o cidad\u00e3o contribuir com a gest\u00e3o\u201d, ressalta o secret\u00e1rio de Planejamento, Nivaldo Carvalho.<\/p>\n<p data-end=\"1779\" data-start=\"1477\">Ap\u00f3s a realiza\u00e7\u00e3o das audi\u00eancias, a \u00edntegra do conte\u00fado ser\u00e1 disponibilizada no canal do YouTube da Prefeitura de Cuiab\u00e1. A popula\u00e7\u00e3o poder\u00e1 enviar sugest\u00f5es e contribui\u00e7\u00f5es at\u00e9 o dia 26 de agosto pelo e-mail\u00a0<a rel=\"noopener\" data-end=\"1712\" data-start=\"1686\">orcamento@cuiaba.mt.gov.br<\/a>\u00a0e tamb\u00e9m pelo WhatsApp da Ouvidoria, no n\u00famero (65) 9 9263-9779.<\/p>\n<p data-end=\"2068\" data-start=\"1781\">#PraCegoVer<br data-end=\"1795\" data-start=\"1792\" \/>A foto mostra o secret\u00e1rio de Planejamento, Nivaldo Carvalho, vestido com traje social, concedendo entrevista a ve\u00edculos de comunica\u00e7\u00e3o. O ambiente \u00e9 o plen\u00e1rio da C\u00e2mara Municipal de Cuiab\u00e1. Ao fundo, \u00e9 poss\u00edvel visualizar mesas pretas e cadeiras estofadas na cor preta.<\/p>\n<p data-end=\"2068\" data-start=\"1781\">\n<p data-end=\"2068\" data-start=\"1781\">Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 Foto:\u00a0 Erlan Aquino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por interm\u00e9dio da Secretaria Municipal de Planejamento, realiza na quinta-feira (25) &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97318"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97318\/revisions"}],"predecessor-version":[{"id":97320,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97318\/revisions\/97320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97319"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}