{"id":97386,"date":"2025-09-25T10:47:58","date_gmt":"2025-09-25T14:47:58","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97386"},"modified":"2025-09-25T10:47:58","modified_gmt":"2025-09-25T14:47:58","slug":"espaco-cidadania-da-almt-nao-tera-atendimento-na-sexta-feira-26","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/espaco-cidadania-da-almt-nao-tera-atendimento-na-sexta-feira-26\/","title":{"rendered":"Espa\u00e7o Cidadania da ALMT n\u00e3o ter\u00e1 atendimento na sexta-feira (26)"},"content":{"rendered":"<p>Para aprimorar os servi\u00e7os oferecidos \u00e0 popula\u00e7\u00e3o, os servidores que atuam no Espa\u00e7o Cidadania da Assembleia Legislativa de Mato Grosso (ALMT), setor composto pela Ouvidoria, Politec, Defensoria P\u00fablica e Procon, receber\u00e3o treinamento, nesta sexta-feira (26), sobre o tema Desdobramentos da Estrat\u00e9gia, n\u00edveis t\u00e1tico e operacional, do projeto Governan\u00e7a P\u00fablica. Dessa forma, n\u00e3o haver\u00e1 atendimento ao p\u00fablico nesse dia.<\/p>\n<p>A ouvidora da ALMT, Uecileny Rodrigues Fernandes, explicou que o encontro ser\u00e1 fundamental para envolver todos os servidores na an\u00e1lise dos pontos fortes, fragilidades, dificuldades e necessidades de melhoria do setor. O objetivo \u00e9 consolidar essas informa\u00e7\u00f5es em um documento orientador, que servir\u00e1 de refer\u00eancia para a defini\u00e7\u00e3o de um cronograma de a\u00e7\u00f5es.<\/p>\n<p>\u201cA implementa\u00e7\u00e3o do sistema de governan\u00e7a no setor p\u00fablico \u00e9 crucial para garantir efici\u00eancia, transpar\u00eancia e responsabilidade na gest\u00e3o dos recursos, al\u00e9m de fortalecer a confian\u00e7a da popula\u00e7\u00e3o no trabalho realizado, otimizar a execu\u00e7\u00e3o de pol\u00edticas p\u00fablicas e contribuir para o desenvolvimento social\u201d, disse a gestora.<\/p>\n<p>Ela refor\u00e7ou ainda que, como o setor recebe grande demanda da parte externa, foi necess\u00e1rio suspender o atendimento nesse dia espec\u00edfico, garantindo a participa\u00e7\u00e3o integral da equipe no processo da constru\u00e7\u00e3o coletiva. \u201cA partir da pr\u00f3xima segunda-feira (29), o atendimento volta ao normal\u201d, garantiu Uecileny.<\/p>\n<p><strong>Treinamento &#8211;\u00a0<\/strong>Numa a\u00e7\u00e3o da Mesa Diretora da Assembleia Legislativa de Mato Grosso (ALMT), os servidores participam do workshop Desdobramentos da Estrat\u00e9gia, n\u00edvel t\u00e1tico e operacional, do projeto Governan\u00e7a P\u00fablica. O treinamento que est\u00e1 sendo feito por setores, come\u00e7ou no dia 22 e segue at\u00e9 2 de outubro, das 8h \u00e0s 17h, no audit\u00f3rio Milton Figueiredo, da ALMT, sob a coordena\u00e7\u00e3o da Secretaria de Controle Interno.<\/p>\n<p>J\u00e1 participaram v\u00e1rios servidores, inclusive os da Secretaria-Geral, do Planejamento Estrat\u00e9gico e das Superintend\u00eancias de Contratos e de Licita\u00e7\u00e3o. Todas as unidades administrativas ser\u00e3o contempladas com o treinamento, ministrado pela contadora, doutora e mestra em administra\u00e7\u00e3o e controladoria Cleane Ramos, da Companhia Brasileira de Governan\u00e7a, de Fortaleza (CE).<\/p>\n<p>Newton Gomes Evangelista, secret\u00e1rio de Controle Interno, destacou a import\u00e2ncia da participa\u00e7\u00e3o dos servidores da ALMT no treinamento, que faz parte da segunda fase do projeto Governan\u00e7a.\u00a0 A etapa anterior foi voltada \u00e0 elabora\u00e7\u00e3o do Planejamento Estrat\u00e9gico 2025-2030.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>ALMT\u00a0 |\u00a0 \u00a0Foto:\u00a0 <i>FABLICIO RODRIGUES\/ALMT<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para aprimorar os servi\u00e7os oferecidos \u00e0 popula\u00e7\u00e3o, os servidores que atuam no Espa\u00e7o Cidadania da &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97387,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Os atendimentos do Procon, da Defensoria P\u00fablica e da Politec ser\u00e3o retomados na pr\u00f3xima segunda-feira (29)","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97386"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97386\/revisions"}],"predecessor-version":[{"id":97388,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97386\/revisions\/97388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97387"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}