{"id":97412,"date":"2025-09-29T12:04:42","date_gmt":"2025-09-29T16:04:42","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97412"},"modified":"2025-09-29T12:04:42","modified_gmt":"2025-09-29T16:04:42","slug":"trecho-da-av-presidente-marques-e-interditado-para-obras-de-esgoto","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/trecho-da-av-presidente-marques-e-interditado-para-obras-de-esgoto\/","title":{"rendered":"Trecho da Av. Presidente Marques \u00e9 interditado para obras de esgoto"},"content":{"rendered":"<p>A partir de segunda-feira (29), o trecho da Av. Presidente Marques, compreendido entre a Av. Get\u00falio Vargas e a Av. Isaac P\u00f3voas, ser\u00e1 interditado temporariamente pela Secretaria Municipal de Mobilidade Urbana e Seguran\u00e7a P\u00fablica, em atendimento a uma solicita\u00e7\u00e3o da Concession\u00e1ria \u00c1guas Cuiab\u00e1, para execu\u00e7\u00e3o de obras de rede de esgoto. A previs\u00e3o \u00e9 de que o servi\u00e7o seja finalizado em 5 dias e o tr\u00e1fego restabelecido.<\/p>\n<p>Os motoristas dever\u00e3o se atentar para novas alternativas. Quem estiver na Av. Presidente Marques, ao chegar na Av. Get\u00falio Vargas dever\u00e1 virar \u00e0 direita, depois a primeira quadra a esquerda acessando a Av. S\u00e3o Sebasti\u00e3o, a pr\u00f3xima \u00e0 esquerda e chegar\u00e1 na Av. Isaac P\u00f3voas, para continuidade do seu percurso.<\/p>\n<p>J\u00e1 os motoristas que trafegam pela Av. Get\u00falio Vargas, ao chegar na Av. Presidente Marques, dever\u00e3o seguir uma quadra a frente, entrar a esquerda na S\u00e3o Sebasti\u00e3o e depois a esquerda novamente para chegar na Isaac P\u00f3voas.<\/p>\n<p>O tr\u00e2nsito pela Rua 24 de Outubro, que cruza a Av. Presidente Marques, bem ao meio da quadra que estar\u00e1 em obras, n\u00e3o sofrer\u00e1 altera\u00e7\u00e3o. \u201cPoder\u00e3o cruzar a Avenida normalmente\u201d, pontuou o supervisor de interdi\u00e7\u00f5es da Semob, Reginaldo Leonel.<\/p>\n<p>Agentes de tr\u00e2nsito e transporte estar\u00e3o dando suporte para minimizar poss\u00edveis impactos no fluxo dos ve\u00edculos.<\/p>\n<p>#PraCegoVer<\/p>\n<p>A imagem mostra um agente de tr\u00e2nsito uniformizado com a camiseta da Semob, com a m\u00e3o levantada em sinal de pare, de frente para um ve\u00edculo. Em primeiro plano na foto est\u00e1 uma motocicleta, tamb\u00e9m da Semob.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Rennan Oliveira<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de segunda-feira (29), o trecho da Av. Presidente Marques, compreendido entre a Av. &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97413,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97412"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97412\/revisions"}],"predecessor-version":[{"id":97414,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97412\/revisions\/97414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97413"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}