{"id":97599,"date":"2025-10-06T10:04:47","date_gmt":"2025-10-06T14:04:47","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97599"},"modified":"2025-10-06T10:04:47","modified_gmt":"2025-10-06T14:04:47","slug":"mato-grosso-tem-4-062-presos-trabalhando-em-atividades-internas-e-extramuros","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mato-grosso-tem-4-062-presos-trabalhando-em-atividades-internas-e-extramuros\/","title":{"rendered":"Mato Grosso tem 4.062 presos trabalhando em atividades internas e extramuros"},"content":{"rendered":"<p>A ressocializa\u00e7\u00e3o de pessoas privadas de liberdade conta com diversas frentes de trabalho em Mato Grosso e emprega, atualmente, 4.062 homens e mulheres do regime fechado e semiaberto, tanto em unidades prisionais quanto em trabalho externo, conforme estabelece a Lei de Execu\u00e7\u00e3o Penal.<\/p>\n<p>Do n\u00famero total de presos trabalhando, 2.200 deles atuam em atividades extramuros remuneradas na iniciativa privada e em \u00f3rg\u00e3os p\u00fablicos municipais e estaduais. Os contratos de trabalho externo s\u00e3o intermediados pela Funda\u00e7\u00e3o Nova Chance, autarquia estadual que atua no processo de reinser\u00e7\u00e3o de pessoas privadas de liberdade e tamb\u00e9m de egressos do sistema prisional.<\/p>\n<p>O secret\u00e1rio de Justi\u00e7a de Mato Grosso, Vitor Hugo Bruzulato, enfatiza que o investimento em qualifica\u00e7\u00e3o profissional e em trabalho para os reeducandos tem se consolidado como um caminho eficaz para colaborar na reinser\u00e7\u00e3o social e reduzir a reincid\u00eancia criminal. \u201cO trabalho e o estudo dentro do sistema prisional n\u00e3o s\u00e3o apenas uma forma de ocupar o tempo da pessoa presa, mas sim pilares que colaboram com a dignidade e oferecem perspectivas reais de futuro\u201d, explica o secret\u00e1rio.<\/p>\n<picture data-fileentryid=\"74056000\"><source srcset=\"\/o\/adaptive-media\/image\/74056000\/Thumbnail-1024x1024\/Imagem4.jpg?t=1755876306146\" media=\"(max-width:720px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/sejus\/imagem4-jpg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p>Vale destacar que para trabalhar em atividades extramuros, entre outros requisitos previstos na Lei de Execu\u00e7\u00e3o Penal brasileira, a pessoa presa em regime fechado deve j\u00e1 ter sido condenada. Ou seja, presos provis\u00f3rios n\u00e3o podem atuar em atividades externas. Para atuar em trabalho\u00a0extramuro, o reeducando passa pela avalia\u00e7\u00e3o de uma comiss\u00e3o multidisciplinar da unidade prisional onde est\u00e1 custodiado. Essa avalia\u00e7\u00e3o \u00e9 encaminhada \u00e0 Vara de Execu\u00e7\u00e3o Penal da comarca local, a quem compete a autoriza\u00e7\u00e3o para o trabalho\u00a0extramuro.<\/p>\n<p>O gestor da Sejus lembra que Mato Grosso \u00e9 um dos estados brasileiros que mais possui legisla\u00e7\u00f5es que estimulam a contrata\u00e7\u00e3o de m\u00e3o de obra de pessoas presas e de egressos do Sistema Penitenci\u00e1rio, a exemplo do Programa Vida Nova, institu\u00eddo pela lei estadual 11.640\/2021, que prev\u00ea a concess\u00e3o de espa\u00e7os p\u00fablicos destinados \u00e0 finalidade de emprego de m\u00e3o de obra de reeducandos. Um dos primeiros estabelecimentos penais a contar com um parque industrial, conforme prev\u00ea o Vida Nova, est\u00e1 em constru\u00e7\u00e3o no entorno da Penitenci\u00e1ria Dr. Osvaldo Florentino Ferreira, em Sinop.<\/p>\n<picture data-fileentryid=\"74850784\"><source srcset=\"\/o\/adaptive-media\/image\/74850784\/Thumbnail-1024x1024\/WhatsApp+Image+2025-09-29+at+19.44.00+%282%29.jpeg?t=1759189606183\" media=\"(max-width:996px)\" \/><img decoding=\"async\" src=\"https:\/\/www.sejus.mt.gov.br\/documents\/d\/sejus\/whatsapp-image-2025-09-29-at-19-44-00-2-jpeg?imageThumbnail=3\" alt=\"\" \/><\/picture>\n<p>\u201cA instala\u00e7\u00e3o desse parque industrial com f\u00e1brica de artefatos de concreto e uma serralheira permitir\u00e1 ampliar significativamente a oferta de trabalho remunerado \u00e0 popula\u00e7\u00e3o prisional de Sinop e regi\u00e3o, promovendo n\u00e3o apenas ocupa\u00e7\u00e3o laboral, mas tamb\u00e9m qualifica\u00e7\u00e3o profissional e gera\u00e7\u00e3o de renda\u201d, comentou Vitor Hugo.<\/p>\n<p>Outro exemplo de emprego remunerado a presos em regime fechado est\u00e1 na f\u00e1brica de artefatos de concreto e serralheria de uma empresa de constru\u00e7\u00e3o, instalada anexa \u00e0 Penitenci\u00e1ria Central do Estado, em Cuiab\u00e1. No local, 109 presos trabalham diariamente na confec\u00e7\u00e3o de estruturas pr\u00e9-moldadas. Os produtos fabricados no local s\u00e3o empregados na constru\u00e7\u00e3o de casas, escolas e tamb\u00e9m unidades prisionais no estado.<\/p>\n<picture data-fileentryid=\"74935638\"><source srcset=\"\/o\/adaptive-media\/image\/74935638\/Thumbnail-1024x1024\/WhatsApp+Image+2025-09-19+at+12.49.24.jpeg?t=1759530631365\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/sejus\/whatsapp-image-2025-09-19-at-12-49-24-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p>A nova unidade prisional de Barra do Gar\u00e7as, para 432 vagas, \u00e9 constru\u00edda com m\u00e3o de obra de pessoas presas. Toda a estrutura pr\u00e9-moldada da nova unidade \u00e9 feita na f\u00e1brica da PCE e depois transportada at\u00e9 a cidade do Araguaia, onde \u00e9 instalada por outro grupo de reeducandos daquela cidade, que trabalham na montagem da estrutura.<\/p>\n<p>Na Penitenci\u00e1ria Feminina Ana Maria do Couto May, tamb\u00e9m na capital, 50 mulheres custodiadas trabalham em duas f\u00e1bricas instaladas no complexo da unidade prisional. As f\u00e1bricas produzem parafusos e bobinas para transformadores el\u00e9tricos.<\/p>\n<p><strong>Projeto Reinserir<\/strong><\/p>\n<p>O presidente da Funda\u00e7\u00e3o Nova Chance, Winkler de Freitas Teles lembra de outra lei do Estado, criada em 2020, instituindo o Programa Estadual de Reinser\u00e7\u00e3o de Pessoas Egressas do Sistema Prisional, que possibilita a contrata\u00e7\u00e3o para o mercado de trabalho formal.<\/p>\n<p>Podem participar do Programa Reinserir, pessoas jur\u00eddicas que estejam em condi\u00e7\u00f5es legais de exerc\u00edcio e que satisfa\u00e7am integralmente as condi\u00e7\u00f5es previstas conforme a lei. \u201cPara participar, o egresso deve ter cumprido integralmente sua pena em at\u00e9 um ano e estar no regime aberto ou em livramento condicional. E a empresa que contrata essa m\u00e3o de obra de egressos fortalece a responsabilidade social e auxilia o Estado na redu\u00e7\u00e3o da reincid\u00eancia criminal\u201d, aponta o presidente da Funac.<\/p>\n<picture data-fileentryid=\"74935936\"><source srcset=\"\/o\/adaptive-media\/image\/74935936\/Thumbnail-1024x1024\/Curso+costura.jpg?t=1759531917768\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/sejus\/curso-costura-jpg-1?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p><strong>Trabalho intramuro<\/strong><\/p>\n<p>Dentro das unidades prisionais de Mato Grosso h\u00e1, atualmente, 1.862 presos trabalhando, de acordo com levantamento da Coordenadoria de Educa\u00e7\u00e3o, Trabalho e Alternativas Penais da Secretaria de Justi\u00e7a.<\/p>\n<picture data-fileentryid=\"74056008\"><source srcset=\"\/o\/adaptive-media\/image\/74056008\/Thumbnail-1024x1024\/WhatsApp+Image+2025-08-21+at+13.19.16.jpeg?t=1755876359476\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/sejus\/whatsapp-image-2025-08-21-at-13-19-16-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p>Entre os 36 diferentes tipos de postos de trabalho dentro dos pres\u00eddios h\u00e1 marcenarias, projetos de horticultura, f\u00e1bricas de artefatos de concreto, padarias, jardinagem, serralheiras, reforma de bicicletas, al\u00e9m de oficinas de artesanato de imagens sacras e croch\u00ea e pintura de telas. Os presos tamb\u00e9m atuam nos servi\u00e7os internos, como na limpeza das unidades e distribui\u00e7\u00e3o de alimenta\u00e7\u00e3o.<\/p>\n<p>Os espa\u00e7os proporcionam atividade laboral aos reeducandos e tamb\u00e9m contribuem no processo de ressocializa\u00e7\u00e3o, conforme estabelece a Lei de Execu\u00e7\u00e3o Penal. \u201cE ao se dedicarem a uma atividade produtiva ou aos estudos, os custodiados t\u00eam chances concretas de um futuro diferente, de produzir algo \u00fatil, de contribuir para a sociedade ou de se dedicar ao aprendizado e de resgate da autoestima\u201d, observo a secret\u00e1ria adjunta de Administra\u00e7\u00e3o Penitenci\u00e1ria, Herm\u00ednia Brito.<\/p>\n<p>Uma das oficinas instaladas na Penitenci\u00e1ria Major Eldo de S\u00e1 Corr\u00eaa, em Rondon\u00f3polis, j\u00e1 qualificou dezenas de presos. Na padaria-escola, um grupo de reeducandos participa, continuamente, de cursos profissionalizantes, desde produ\u00e7\u00e3o de p\u00e3es de diversos tipos \u00e0 confec\u00e7\u00e3o de bolos e doces. Promovidos pelo Senac-MT, os cursos ensinam as t\u00e9cnicas de produ\u00e7\u00e3o e tamb\u00e9m no\u00e7\u00f5es de empreendedorismo.<\/p>\n<picture data-fileentryid=\"74935509\"><source srcset=\"\/o\/adaptive-media\/image\/74935509\/Thumbnail-1024x1024\/WhatsApp+Image+2025-08-22+at+10.48.14+%282%29.jpeg?t=1759529187599\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/sejus\/whatsapp-image-2025-08-22-at-10-48-14-2-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n<p>A pedagoga da penitenci\u00e1ria de Rondon\u00f3polis, Creuza Rosa Ribeiro, explica que a padaria \u00e9 um espa\u00e7o n\u00e3o apenas de produ\u00e7\u00e3o de alimentos, mas de conhecimento que \u00e9 multiplicado entre os reeducandos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ressocializa\u00e7\u00e3o de pessoas privadas de liberdade conta com diversas frentes de trabalho em Mato &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97600,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"N\u00famero demonstra o compromisso do Estado em oferecer oportunidades para que reeducandos se tornem protagonistas de suas pr\u00f3prias hist\u00f3rias de recome\u00e7o","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97599"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97599\/revisions"}],"predecessor-version":[{"id":97601,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97599\/revisions\/97601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97600"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}