{"id":97675,"date":"2025-10-09T14:38:19","date_gmt":"2025-10-09T18:38:19","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97675"},"modified":"2025-10-09T14:38:19","modified_gmt":"2025-10-09T18:38:19","slug":"sefaz-e-amm-realizam-primeiro-encontro-do-comite-gestor-regional-da-reforma-tributaria","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/sefaz-e-amm-realizam-primeiro-encontro-do-comite-gestor-regional-da-reforma-tributaria\/","title":{"rendered":"Sefaz e AMM realizam primeiro encontro do Comit\u00ea Gestor Regional da Reforma Tribut\u00e1ria"},"content":{"rendered":"<p>Foi realizado nesta quarta-feira (8.10) o primeiro encontro do Grupo de Coordena\u00e7\u00e3o Estrat\u00e9gica, componente do Comit\u00ea Gestor Regional da Reforma Tribut\u00e1ria, criado para acompanhar e propor a\u00e7\u00f5es relacionadas \u00e0 implanta\u00e7\u00e3o das mudan\u00e7as no sistema tribut\u00e1rio em Mato Grosso. O grupo \u00e9 formado por representantes da Secretaria de Estado de Fazenda (Sefaz-MT), da Associa\u00e7\u00e3o Mato-grossense dos Munic\u00edpios (AMM) e de prefeituras de diferentes regi\u00f5es do estado.<\/p>\n<p>&nbsp;<\/p>\n<p>Com a Reforma Tribut\u00e1ria, que est\u00e1 em fase de implanta\u00e7\u00e3o no pa\u00eds, os atuais impostos sobre o consumo, cobrados pelos Estados (ICMS) e Munic\u00edpios (ISS), ser\u00e3o unificados, passando a existir apenas o Imposto sobre Bens e Servi\u00e7os (IBS). Essa mudan\u00e7a vai exigir uma reestrutura\u00e7\u00e3o das administra\u00e7\u00f5es tribut\u00e1rias e dos processos de arrecada\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>O secret\u00e1rio de Fazenda, Rog\u00e9rio Gallo, destacou a import\u00e2ncia da atua\u00e7\u00e3o conjunta entre Estado e munic\u00edpios para garantir uma transi\u00e7\u00e3o segura e equilibrada.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cO novo sistema tribut\u00e1rio exigir\u00e1 coopera\u00e7\u00e3o, planejamento e di\u00e1logo permanente. A cria\u00e7\u00e3o deste comit\u00ea \u00e9 um passo fundamental para que Mato Grosso esteja preparado para essa nova realidade fiscal, reduzindo riscos e assegurando que Estado e munic\u00edpios mantenham sua capacidade de investimento e presta\u00e7\u00e3o de servi\u00e7os \u00e0 popula\u00e7\u00e3o\u201d, afirmou Gallo.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante o encontro, foram apresentados os objetivos e a estrutura do comit\u00ea, que conta com um grupo de coordena\u00e7\u00e3o estrat\u00e9gica e dois grupos t\u00e9cnicos compostos por representantes da Sefaz e dos munic\u00edpios. Esses grupos ser\u00e3o respons\u00e1veis por analisar os impactos da Reforma no ICMS e no ISS, avaliar os reflexos na arrecada\u00e7\u00e3o e na distribui\u00e7\u00e3o das receitas, al\u00e9m de propor diretrizes conjuntas para garantir uma transi\u00e7\u00e3o eficiente e equilibrada ao novo modelo tribut\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p>O presidente da AMM, Leonardo Bortolin, destacou o protagonismo de Mato Grosso ao integrar Estado e munic\u00edpios para discutir a implanta\u00e7\u00e3o da Reforma Tribut\u00e1ria. Para ele, o trabalho desenvolvido pelo comit\u00ea gestor ser\u00e1 essencial para preparar as prefeituras diante do novo sistema tribut\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cMato Grosso \u00e9 pioneiro ao unir o Estado e os munic\u00edpios em um espa\u00e7o de di\u00e1logo que permite o levantamento de diagn\u00f3sticos, a elabora\u00e7\u00e3o de um plano de trabalho e, principalmente, a orienta\u00e7\u00e3o t\u00e9cnica aos gestores municipais. Sempre dou um exemplo que come\u00e7ou um jogo em que as regras n\u00e3o est\u00e3o claras, ent\u00e3o acredito que este comit\u00ea regional \u00e9 um passo fundamental para preparar os munic\u00edpios para redu\u00e7\u00e3o dos impactos negativos da reforma tribut\u00e1ria\u201d, afirmou o presidente da AMM.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m representantes da Secretaria de Fazenda, pelo Governo do Estado, e da AMM, comp\u00f5em o Grupo de Coordena\u00e7\u00e3o Estrat\u00e9gica representantes dos munic\u00edpios de Cuiab\u00e1, V\u00e1rzea Grande, Sinop, Sapezal e Primavera do Leste.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Comit\u00ea Gestor Regional<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>A cria\u00e7\u00e3o do comit\u00ea foi formalizada por meio de um Termo de Coopera\u00e7\u00e3o T\u00e9cnica assinado em abril deste ano entre a Sefaz e a AMM, com o objetivo de fortalecer a integra\u00e7\u00e3o institucional entre o Estado e os munic\u00edpios diante das mudan\u00e7as trazidas pela Reforma Tribut\u00e1ria. A parceria busca alinhar entendimentos, promover a capacita\u00e7\u00e3o dos servidores p\u00fablicos e manter um canal permanente de di\u00e1logo e coopera\u00e7\u00e3o sobre o novo sistema.<\/p>\n<p>&nbsp;<\/p>\n<p>A cria\u00e7\u00e3o e atua\u00e7\u00e3o desse comit\u00ea refor\u00e7am o compromisso de Mato Grosso em atuar de forma conjunta e planejada para assegurar a efici\u00eancia, a equidade e a transpar\u00eancia na implementa\u00e7\u00e3o da Reforma Tribut\u00e1ria no estado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Luiz Leite\/Sefaz-MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi realizado nesta quarta-feira (8.10) o primeiro encontro do Grupo de Coordena\u00e7\u00e3o Estrat\u00e9gica, componente do &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97676,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Grupo vai acompanhar e propor a\u00e7\u00f5es para auxiliar o Estado e os munic\u00edpios na implanta\u00e7\u00e3o do novo sistema tribut\u00e1rio","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97675"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97675\/revisions"}],"predecessor-version":[{"id":97677,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97675\/revisions\/97677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97676"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}