{"id":97696,"date":"2025-10-10T09:54:04","date_gmt":"2025-10-10T13:54:04","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97696"},"modified":"2025-10-10T09:54:04","modified_gmt":"2025-10-10T13:54:04","slug":"sema-apresenta-iniciativas-que-promovem-desenvolvimento-economico-conservacao-e-inclusao-social","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/sema-apresenta-iniciativas-que-promovem-desenvolvimento-economico-conservacao-e-inclusao-social\/","title":{"rendered":"Sema apresenta iniciativas que promovem desenvolvimento econ\u00f4mico, conserva\u00e7\u00e3o e inclus\u00e3o social"},"content":{"rendered":"<p>Mato Grosso j\u00e1 atingiu 88,3% da meta estipulada at\u00e9 2030 referente \u00e0 explora\u00e7\u00e3o por manejo florestal sustent\u00e1vel. Dos 6 milh\u00f5es de hectares almejados, o estado j\u00e1 alcan\u00e7ou 5,3 mi, assegurando o correto uso dos recursos naturais e a implementa\u00e7\u00e3o de modelo produtivo sustent\u00e1vel. Esse foi apenas um dos resultados apresentados pela Secretaria de Estado de Meio Ambiente (Sema-MT), nesta quinta-feira (9.10), no semin\u00e1rio Pr\u00e9-Cop 30, realizado em Bras\u00edlia.<\/p>\n<p>A secret\u00e1ria de Estado de Meio Ambiente, Mauren Lazzaretti, tamb\u00e9m destacou que Mato Grosso mant\u00e9m 60% de seu territ\u00f3rio preservado, mesmo sendo l\u00edder em produ\u00e7\u00e3o, conciliando desenvolvimento econ\u00f4mico, conserva\u00e7\u00e3o ambiental e inclus\u00e3o social. Ela ressaltou que o total de \u00e1rea preservada em MT \u00e9 superior \u00e0 soma dos territ\u00f3rios da Dinamarca, Reino Unido e Nova Zel\u00e2ndia.<\/p>\n<p>Foram apresentados ainda os resultados obtidos em rela\u00e7\u00e3o ao licenciamento, regulariza\u00e7\u00e3o ambiental, recupera\u00e7\u00e3o de \u00e1reas degradadas, integra\u00e7\u00e3o lavoura e pecu\u00e1ria, fiscaliza\u00e7\u00e3o, monitoramento, entre outros temas. \u201cTodas as a\u00e7\u00f5es e programas desenvolvidos em Mato Grosso est\u00e3o alinhados com as 12 a\u00e7\u00f5es priorit\u00e1rias voltadas \u00e0 neutraliza\u00e7\u00e3o das emiss\u00f5es de gases de efeito estufa (carbono neutro) at\u00e9 2035\u201d, explicou Lazzaretti.<\/p>\n<p>A secret\u00e1ria destacou tamb\u00e9m a execu\u00e7\u00e3o do projeto \u201cTodos pelo Araguaia\u201d. Uma iniciativa que visa apoiar os produtores rurais na regi\u00e3o do Araguaia para restaura\u00e7\u00e3o de \u00e1rea de recarga de aqu\u00edfero e \u00e1reas de preserva\u00e7\u00e3o permanente. Nos dias 22 e 23 de outubro, a Sema inicia em Barra do Gar\u00e7as o segundo lote (420 hectares) de \u00e1reas a serem recuperadas.<\/p>\n<p>As a\u00e7\u00f5es e programas implementados no estado, segundo ela, t\u00eam o envolvimento direto do Instituto PCI (Produzir, Conserva e Incluir) e de outros parceiros. \u201cA estrat\u00e9gia PCI \u00e9 motivo de orgulho para Mato Grosso, pois traduz este movimento que o estado tem feito para incluir as pessoas em uma solu\u00e7\u00e3o que concilie produ\u00e7\u00e3o e concilia\u00e7\u00e3o\u201d, acrescentou.<\/p>\n<p>Em meio a uma plateia com a participa\u00e7\u00e3o de representantes de outros pa\u00edses, a secret\u00e1ria de Estado de Meio Ambiente fez quest\u00e3o de ressaltar que a preserva\u00e7\u00e3o de 60% do territ\u00f3rio mato-grossense contribui com a qualidade ambiental n\u00e3o apenas da Amaz\u00f4nia e do Brasil, mas do mundo inteiro.<\/p>\n<p>Segundo ela, Mato Grosso tamb\u00e9m tem avan\u00e7ado no cumprimento do C\u00f3digo Florestal. Atualmente, dos 60% de \u00e1reas preservadas, mais de 35% est\u00e3o localizadas em propriedades rurais, que s\u00e3o as reservas legais e \u00e1reas de preserva\u00e7\u00e3o permanentes.<\/p>\n<p>\u201cEstamos fazendo a nossa parte, estabelecendo estrat\u00e9gias que se consolidam em pol\u00edticas p\u00fablicas e s\u00e3o incorporadas na matriz produtiva dos setores e tamb\u00e9m pela sociedade civil, nos projetos que s\u00e3o conduzidos. Mato Grosso tem a sua matriz e a solu\u00e7\u00e3o n\u00e3o passa por embargos econ\u00f4micos, mas pela valoriza\u00e7\u00e3o do produto produzido dentro da legalidade\u201d, afirmou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 |\u00a0 Foto:\u00a0 Assessoria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mato Grosso j\u00e1 atingiu 88,3% da meta estipulada at\u00e9 2030 referente \u00e0 explora\u00e7\u00e3o por manejo &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97697,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"A\u00e7\u00f5es e programas desenvolvidos em Mato Grosso est\u00e3o alinhados com as 12 a\u00e7\u00f5es priorit\u00e1rias do Carbono Neutro 2035","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97696"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97696\/revisions"}],"predecessor-version":[{"id":97698,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97696\/revisions\/97698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97697"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}