{"id":97737,"date":"2025-10-13T11:40:02","date_gmt":"2025-10-13T15:40:02","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97737"},"modified":"2025-10-13T11:40:02","modified_gmt":"2025-10-13T15:40:02","slug":"seplag-promove-ii-simposio-de-compras-publicas-em-formato-online","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/seplag-promove-ii-simposio-de-compras-publicas-em-formato-online\/","title":{"rendered":"Seplag promove II Simp\u00f3sio de Compras P\u00fablicas em formato online"},"content":{"rendered":"<p>A Secretaria de Planejamento e Gest\u00e3o (Seplag-MT) realizar\u00e1, nos dias 6 e 7 de novembro de 2025, o II Simp\u00f3sio de Compras P\u00fablicas, evento que reunir\u00e1 servidores do Poder Executivo Estadual que atuem diretamente na \u00e1rea de compras. As inscri\u00e7\u00f5es iniciam nesta segunda-feira (13.10) e seguem abertas at\u00e9 4 de novembro. S\u00e3o oferecidas 1000 vagas.<\/p>\n<p>A programa\u00e7\u00e3o ser\u00e1 totalmente online e tem como objetivo fortalecer a capacita\u00e7\u00e3o dos profissionais que lidam com processos licitat\u00f3rios, contratos e aquisi\u00e7\u00f5es p\u00fablicas, com foco nas boas pr\u00e1ticas, na aplica\u00e7\u00e3o da nova Lei de Licita\u00e7\u00f5es e Contratos Administrativos (Lei n\u00ba 14.133\/2021) e do Decreto Estadual n\u00ba 1.525 de 2022, em especial, com compras sustent\u00e1veis.<\/p>\n<p>Para o secret\u00e1rio de Planejamento e Gest\u00e3o, Bas\u00edlio Bezerra, o evento \u00e9 uma oportunidade para os servidores expandirem seus conhecimentos.<br \/>\n\u201cO II Simp\u00f3sio de Compras P\u00fablicas refor\u00e7a o compromisso do Governo de Mato Grosso com a capacita\u00e7\u00e3o cont\u00ednua dos servidores e a moderniza\u00e7\u00e3o da gest\u00e3o p\u00fablica. A \u00e1rea de compras \u00e9 estrat\u00e9gica para garantir a boa aplica\u00e7\u00e3o dos recursos p\u00fablicos e a efici\u00eancia na presta\u00e7\u00e3o de servi\u00e7os \u00e0 popula\u00e7\u00e3o. Por isso, investir em conhecimento e promover o di\u00e1logo sobre temas como a nova Lei de Licita\u00e7\u00f5es e as compras sustent\u00e1veis \u00e9 fundamental para construirmos uma administra\u00e7\u00e3o cada vez mais transparente, t\u00e9cnica e alinhada \u00e0s melhores pr\u00e1ticas de governan\u00e7a\u201d, destacou o secret\u00e1rio da Seplag.<\/p>\n<p>Segundo a secret\u00e1ria adjunta de Aquisi\u00e7\u00f5es Governamentais da Seplag, Katiene Pinheiro, o Simp\u00f3sio representa uma oportunidade para o aprimoramento da administra\u00e7\u00e3o p\u00fablica. \u201cO evento promove a troca de conhecimentos, pr\u00e1ticas inovadoras e o debate sobre os desafios enfrentados no processo de compras governamentais. O Simp\u00f3sio \u00e9 fundamental para capacitar os servidores, fortalecendo sua expertise, trazendo inclusive as oficinas para demonstra\u00e7\u00e3o de forma pr\u00e1tica as contrata\u00e7\u00f5es, contribuindo para a transpar\u00eancia, efici\u00eancia e responsabilidade na gest\u00e3o dos recursos p\u00fablicos, resultando em benef\u00edcios diretos para a sociedade\u201d, informou Katiene Pinheiro.<\/p>\n<p>A abertura do simp\u00f3sio est\u00e1 marcada para \u00e0s 8h do dia 6, com a fala das autoridades e, em seguida, duas palestras principais. A primeira tem como palestrante a secret\u00e1ria adjunta de Aquisi\u00e7\u00f5es Governamentais, Katiene Pinheiro, e abordar\u00e1 o tema \u201cCompras P\u00fablicas na Perspectiva da Lei n\u00ba 14.133\/2021 e do Decreto Estadual n\u00ba 1.525\/2022\u201d, destacando as mudan\u00e7as trazidas pelo novo marco legal. J\u00e1 a segunda palestra ser\u00e1 ministrada pela procuradora do Estado, Dra. Julyana Lanes, e ter\u00e1 como tema \u201cCompras P\u00fablicas Sustent\u00e1veis\u201d, discutindo estrat\u00e9gias e instrumentos para incorporar crit\u00e9rios ambientais, sociais e econ\u00f4micos nos processos de aquisi\u00e7\u00e3o do setor p\u00fablico.<\/p>\n<p>No per\u00edodo da tarde, nos dias 6 e 7 de novembro, ser\u00e3o realizadas oficinas pr\u00e1ticas voltadas ao aperfei\u00e7oamento t\u00e9cnico dos participantes. Entre os temas, est\u00e3o \u201cComo elaborar o ETP, TR e DFD e utilizar o SIAG\u201d, com as servidoras da Secretaria Adjunta de Aquisi\u00e7\u00f5es Governamentais (SAAG), Kely Z\u00f3ccoli e Bruna do Prado; \u201cComo fazer a gest\u00e3o e fiscaliza\u00e7\u00e3o de contratos\u201d, ministrada pelo auditor do estado, Orlando Estvens; e \u201cComo fazer pesquisa de pre\u00e7os\u201d, conduzida pelos servidores da SAAG, Paulo Menezes e Jiancarlo de Souza Leoncio.<\/p>\n<p>O Simp\u00f3sio se consolida como um espa\u00e7o de aprendizado e troca de experi\u00eancias entre servidores, contribuindo para o aprimoramento das pr\u00e1ticas de gest\u00e3o e transpar\u00eancia nas compras p\u00fablicas do Estado.<\/p>\n<p><strong>SERVI\u00c7O<\/strong><br \/>\nO que? II Simp\u00f3sio de Compras P\u00fablicas<br \/>\nQuando? De 6 a 7 de novembro de 2025<br \/>\nInscri\u00e7\u00f5es: De 13 de outubro a 04 de novembro de 2025 [<a href=\"http:\/\/capacitacoes.controladoria.mt.gov.br\/curso\/4473\/II-SIMPOSIO-DE-COMPRAS-PUBLICAS-TURMA-01-\">acesse aqui<\/a>]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Divulga\u00e7\u00e3o Seplag-MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Planejamento e Gest\u00e3o (Seplag-MT) realizar\u00e1, nos dias 6 e 7 de novembro &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97738,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Evento ser\u00e1 realizado nos dias 6 e 7 de novembro e as inscri\u00e7\u00f5es v\u00e3o at\u00e9 04 de novembro","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97737"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97737\/revisions"}],"predecessor-version":[{"id":97739,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97737\/revisions\/97739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97738"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}