{"id":97747,"date":"2025-10-13T11:50:21","date_gmt":"2025-10-13T15:50:21","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97747"},"modified":"2025-10-13T11:50:21","modified_gmt":"2025-10-13T15:50:21","slug":"almt-aprova-leis-que-fortalecem-politicas-de-prevencao-e-diagnostico-do-cancer-de-mama","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/almt-aprova-leis-que-fortalecem-politicas-de-prevencao-e-diagnostico-do-cancer-de-mama\/","title":{"rendered":"ALMT aprova leis que fortalecem pol\u00edticas de preven\u00e7\u00e3o e diagn\u00f3stico do c\u00e2ncer de mama"},"content":{"rendered":"<p>A Assembleia Legislativa de Mato Grosso (ALMT) tem atuado de forma efetiva no enfrentamento ao c\u00e2ncer de mama, com a aprova\u00e7\u00e3o de quatro leis estaduais que ampliam as a\u00e7\u00f5es de preven\u00e7\u00e3o, diagn\u00f3stico e conscientiza\u00e7\u00e3o sobre a doen\u00e7a.<\/p>\n<p>As normas complementam a Lei Federal n\u00ba 13.733\/2018, que instituiu a campanha Outubro Rosa em todo o pa\u00eds, e refor\u00e7am o compromisso do Parlamento estadual com a sa\u00fade e o bem-estar das mulheres mato-grossenses.<\/p>\n<p>A\u00a0<a href=\"https:\/\/www.al.mt.gov.br\/norma-juridica\/urn:lex:br;mato.grosso:estadual:lei.ordinaria:2012-06-19;9757\/gerar-pdf-redacao\" target=\"_blank\" rel=\"noopener noreferrer\">Lei n\u00ba 9.757\/2012<\/a>\u00a0institui a campanha Outubro Rosa em Mato Grosso e inclui o m\u00eas de outubro no calend\u00e1rio oficial do estado, durante o qual devem ser realizadas a\u00e7\u00f5es voltadas \u00e0 conscientiza\u00e7\u00e3o sobre a preven\u00e7\u00e3o prim\u00e1ria e secund\u00e1ria da doen\u00e7a, incluindo palestras, mobiliza\u00e7\u00f5es e atividades educativas.<\/p>\n<p>Al\u00e9m disso, a legisla\u00e7\u00e3o define o dia 26 como o Dia Estadual de Preven\u00e7\u00e3o ao C\u00e2ncer de Mama e prev\u00ea a divulga\u00e7\u00e3o dos direitos garantidos pela Lei Federal n\u00ba 11.664\/2008, que trata da preven\u00e7\u00e3o e do tratamento do c\u00e2ncer de mama e do colo do \u00fatero pelo Sistema \u00danico de Sa\u00fade (SUS).<\/p>\n<p>J\u00e1 a\u00a0<a href=\"https:\/\/www.al.mt.gov.br\/norma-juridica\/urn:lex:br;mato.grosso:estadual:lei.ordinaria:2022-03-30;11705\/gerar-pdf-redacao\" target=\"_blank\" rel=\"noopener noreferrer\">Lei n\u00ba 11.705\/2022<\/a>\u00a0determina prioridade na realiza\u00e7\u00e3o de mamografias para mulheres de 40 a 70 anos com hist\u00f3rico familiar de c\u00e2ncer de mama ou presen\u00e7a de n\u00f3dulos, tanto na rede p\u00fablica quanto na privada.<\/p>\n<p>A norma tamb\u00e9m assegura atendimento preferencial \u00e0quelas que realizam acompanhamento peri\u00f3dico ou que estejam em tratamento oncol\u00f3gico, mediante prescri\u00e7\u00e3o m\u00e9dica.<\/p>\n<p>A\u00a0<a href=\"https:\/\/www.al.mt.gov.br\/norma-juridica\/urn:lex:br;mato.grosso:estadual:lei.ordinaria:2025-04-22;12854\/gerar-pdf-redacao\" target=\"_blank\" rel=\"noopener noreferrer\">Lei n\u00ba 12.854\/2025<\/a>\u00a0assegura \u00e0s mulheres com mama densa o direito de realizar o exame de resson\u00e2ncia magn\u00e9tica associada \u00e0 mamografia nas unidades p\u00fablicas de sa\u00fade ou conveniadas integrantes do SUS.<\/p>\n<p>Por fim, a\u00a0<a href=\"https:\/\/www.al.mt.gov.br\/norma-juridica\/urn:lex:br;mato.grosso:estadual:lei.ordinaria:2021-06-09;11413\/gerar-pdf-redacao\" target=\"_blank\" rel=\"noopener noreferrer\">Lei n\u00ba 11.413\/2021<\/a>\u00a0cria o Programa de Exame de Mamografia M\u00f3vel (Mam\u00f3vel) para levar unidades m\u00f3veis de mamografia a diferentes munic\u00edpios, priorizando o atendimento de mulheres entre 50 e 69 anos e regi\u00f5es com menor cobertura de exames.<\/p>\n<p>A iniciativa busca ainda fortalecer a rede de diagn\u00f3stico e tratamento, garantindo acompanhamento \u00e0s pacientes que apresentarem altera\u00e7\u00f5es nos exames.<\/p>\n<p>O c\u00e2ncer de mama \u00e9 o segundo tipo mais comum entre as mulheres no Brasil e representa a principal causa de mortalidade feminina por tumores.<\/p>\n<p>A m\u00e9dica Larissa Chiuchi descobriu a doen\u00e7a em 2017, aos 35 anos, durante exames preparat\u00f3rios para um procedimento de fertiliza\u00e7\u00e3o.<\/p>\n<p>Na \u00e9poca, ela mantinha uma rotina exaustiva de trabalho, dormia pouco, alimentava-se mal e atribu\u00eda o cansa\u00e7o frequente e a perda de peso \u00e0 correria do dia a dia. Al\u00e9m disso, estava h\u00e1 dois anos sem ir ao ginecologista, sem realizar os exames preventivos e n\u00e3o mantinha o h\u00e1bito de fazer o autoexame.<\/p>\n<p>Seu tratamento incluiu cirurgia de mastectomia total (retirada completa) das duas mamas, quimioterapia e uso de bloqueador hormonal por cinco anos. Nesse per\u00edodo, mudou seus h\u00e1bitos: passou a se alimentar melhor, priorizar o sono, retomar atividades f\u00edsicas e fortalecer o corpo e a mente.<\/p>\n<p>H\u00e1 sete anos ela est\u00e1 em remiss\u00e3o e continua realizando exames de acompanhamento, mantendo os cuidados com a sa\u00fade. Para que outras mulheres n\u00e3o passem pelo que passou, ela destaca a import\u00e2ncia de campanhas de conscientiza\u00e7\u00e3o e de leis voltadas \u00e0 preven\u00e7\u00e3o e ao enfrentamento da doen\u00e7a.<\/p>\n<p>\u201cEu acho muito importantes as campanhas e as leis, exatamente por trazerem mais consci\u00eancia sobre a doen\u00e7a e mostrarem caminhos para o diagn\u00f3stico e o tratamento. Quando a gente fala sobre o assunto, outras mulheres passam a se cuidar mais, a prestar aten\u00e7\u00e3o aos sinais do corpo e a procurar ajuda m\u00e9dica mais cedo. Quanto antes come\u00e7ar a se tratar, maiores s\u00e3o as chances de cura\u201d, salienta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>ALMT\u00a0 \u00a0|\u00a0 Foto:\u00a0 <i>EQUIPE CRIA\u00c7\u00c3O\/ALMT<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Assembleia Legislativa de Mato Grosso (ALMT) tem atuado de forma efetiva no enfrentamento ao &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97748,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Normas ampliam a\u00e7\u00f5es de conscientiza\u00e7\u00e3o e garantem prioridade em exames e maior precis\u00e3o no diagn\u00f3stico pela rede p\u00fablica","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97747"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97747\/revisions"}],"predecessor-version":[{"id":97749,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97747\/revisions\/97749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97748"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}