{"id":97770,"date":"2025-10-15T08:28:59","date_gmt":"2025-10-15T12:28:59","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97770"},"modified":"2025-10-15T08:28:59","modified_gmt":"2025-10-15T12:28:59","slug":"4a-edicao-da-revista-educacao-ct-sera-lancada-na-abertura-da-22a-snct-em-mato-grosso","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/4a-edicao-da-revista-educacao-ct-sera-lancada-na-abertura-da-22a-snct-em-mato-grosso\/","title":{"rendered":"4\u00aa edi\u00e7\u00e3o da Revista Educa\u00e7\u00e3o C&#038;T ser\u00e1 lan\u00e7ada na abertura da 22\u00aa SNCT em Mato Grosso"},"content":{"rendered":"<p>A Secretaria de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (Seciteci) abrir\u00e1 a 22\u00aa Semana Nacional de Ci\u00eancia e Tecnologia (SNCT) com um convite duplo: ver a ci\u00eancia de perto, nos estandes, oficinas e demonstra\u00e7\u00f5es, e levar a ci\u00eancia para casa, com o lan\u00e7amento da 4\u00aa Revista Cient\u00edfica Educa\u00e7\u00e3o C&amp;T. A apresenta\u00e7\u00e3o da nova edi\u00e7\u00e3o da revista ser\u00e1 realizada no dia 22 de outubro, no Centro de Eventos do Pantanal, logo ap\u00f3s a abertura da SNCT.<\/p>\n<p>\u201cA revista Educa\u00e7\u00e3o C&amp;T j\u00e1 virou tradi\u00e7\u00e3o na Seciteci; \u00e9 um instrumento que valida e visibiliza o conhecimento cient\u00edfico produzido em Mato Grosso\u201d, afirma o secret\u00e1rio Allan Kardec. \u201cNesta edi\u00e7\u00e3o, s\u00e3o 550 p\u00e1ginas e 36 artigos organizados nos eixos tem\u00e1ticos do ano, com a participa\u00e7\u00e3o de mais de 90 autores\u201d, completa.<\/p>\n<p>A chamada p\u00fablica desta edi\u00e7\u00e3o bateu recorde: 114 autores submeteram 47 trabalhos, 17,5% a mais que em 2024 (quando foram 40). Os artigos selecionados comp\u00f5em um dossi\u00ea que dialoga diretamente com o debate contempor\u00e2neo: Intelig\u00eancia Artificial, Educa\u00e7\u00e3o e Trabalho: Desafios e Oportunidades para o Desenvolvimento Sustent\u00e1vel.<\/p>\n<p>A editora adjunta F\u00e1tima Possamai, coordenadora de Regula\u00e7\u00e3o e Supervis\u00e3o da Educa\u00e7\u00e3o Superior da Seciteci, sublinha o papel formativo do peri\u00f3dico: \u201cA revista Educa\u00e7\u00e3o C&amp;T tem aproximado ci\u00eancia, tecnologia e inova\u00e7\u00e3o do cotidiano, fortalecendo a cultura cient\u00edfica no estado\u201d.<\/p>\n<p>A diversidade institucional tamb\u00e9m cresceu nesta edi\u00e7\u00e3o: trabalhos de todas as Institui\u00e7\u00f5es P\u00fablicas de Ensino Superior de MT, al\u00e9m de institui\u00e7\u00f5es privadas, governamentais, de Educa\u00e7\u00e3o B\u00e1sica e Profissional. No total, 36 institui\u00e7\u00f5es assinam os textos, sendo 10 de fora de Mato Grosso, distribu\u00eddas em seis estados.<\/p>\n<p>A revista foi criada em 2022, com o prop\u00f3sito de popularizar ci\u00eancia com rigor e qualificar decis\u00f5es de gestores, docentes, estudantes e ecossistemas de inova\u00e7\u00e3o. Publica artigos cient\u00edficos com foco em pr\u00e1ticas pedag\u00f3gicas, experimentos replic\u00e1veis, dados para pol\u00edticas p\u00fablicas, al\u00e9m de apresentar resultados de pesquisas cient\u00edficas desenvolvidas em diferentes institui\u00e7\u00f5es. Os textos deste ano est\u00e3o distribu\u00eddos nos seguintes eixos: IA na Educa\u00e7\u00e3o; IA na Ci\u00eancia e Pesquisa; IA e Agricultura 4.0; Desafios \u00c9ticos e Sociais da IA.<\/p>\n<p>\u201cQueremos que a publica\u00e7\u00e3o mostre os dados cient\u00edficos, provoque novas reflex\u00f5es e a ofere\u00e7a caminhos para desafios da nossa contemporaneidade. \u00c9 mais uma materializa\u00e7\u00e3o e populariza\u00e7\u00e3o da ci\u00eancia desenvolvida na Seciteci\u201d, pontua Allan Kardec.<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 Foto:\u00a0 Ascom Seciteci<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (Seciteci) abrir\u00e1 a 22\u00aa Semana Nacional de Ci\u00eancia &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97771,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Apresenta\u00e7\u00e3o acontecer\u00e1 em 22 de outubro, no Centro de Eventos do Pantanal, em Cuiab\u00e1","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97770"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97770\/revisions"}],"predecessor-version":[{"id":97772,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97770\/revisions\/97772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97771"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}