{"id":97871,"date":"2025-10-23T15:00:32","date_gmt":"2025-10-23T19:00:32","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97871"},"modified":"2025-10-23T15:00:32","modified_gmt":"2025-10-23T19:00:32","slug":"impasse-no-cade-prolonga-cenario-de-inseguranca-para-produtores-de-soja-e-empresas-do-setor","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/impasse-no-cade-prolonga-cenario-de-inseguranca-para-produtores-de-soja-e-empresas-do-setor\/","title":{"rendered":"Impasse no Cade prolonga cen\u00e1rio de inseguran\u00e7a para produtores de soja e empresas do setor"},"content":{"rendered":"<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\">O futuro da Morat\u00f3ria da Soja permanece sem solu\u00e7\u00e3o definida no Conselho Administrativo de Defesa Econ\u00f4mica (Cade), \u00f3rg\u00e3o respons\u00e1vel por analisar poss\u00edveis pr\u00e1ticas anticoncorrenciais no pa\u00eds. O processo segue em pauta, e produtores e tradings do setor aguardam um posicionamento claro sobre quem ficar\u00e1 com a relatoria do caso, uma decis\u00e3o crucial para entender os pr\u00f3ximos cap\u00edtulos desse acordo ambiental, que pro\u00edbe a compra de soja origin\u00e1ria de \u00e1reas desmatadas na Amaz\u00f4nia ap\u00f3s 2008.<\/p>\n<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\">O impasse teve novo cap\u00edtulo nesta quarta-feira (22.10), durante sess\u00e3o plen\u00e1ria marcada por diverg\u00eancias entre conselheiros. O conselheiro Jos\u00e9 Levi, que no julgamento do dia 30 de setembro defendeu a prorroga\u00e7\u00e3o da suspens\u00e3o da Morat\u00f3ria s\u00f3 a partir de 1\u00ba de janeiro de 2026, argumentou que, tendo obtido maioria no voto, deveria assumir a relatoria do processo. Na pr\u00e1tica, o voto de Levi d\u00e1 margem para as partes envolvidas, produtores, tradings, governos e entidades ambientais, negociarem ajustes ou propor novo acordo at\u00e9 o fim de 2025, mantendo as atuais regras em vigor por mais um ano.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u6e146204dbbbac9288a5f9320623a12b-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Emirados \u00c1rabes ajudam o Brasil a bater recorde na venda de ovos<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\">Depois da decis\u00e3o anterior, a secretaria do Cade chegou a transferir a relatoria para Levi, mas uma ata retificadora publicada logo depois devolveu a fun\u00e7\u00e3o ao conselheiro Carlos Jaques, que votou pela suspens\u00e3o imediata da Morat\u00f3ria.<\/p>\n<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\">Na sess\u00e3o desta semana, Levi pediu novamente \u00e0 presid\u00eancia do Cade que seu despacho fosse votado pelo plen\u00e1rio, mas o presidente Gustavo Augusto impediu o andamento e suspendeu a discuss\u00e3o, aumentando o clima de incerteza.<\/p>\n<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\">A falta de defini\u00e7\u00e3o preocupa o setor, principalmente porque sem relator oficial todo o andamento do processo pode ser revisto ou travado, dificultando a defesa das tradings e dos produtores. Para a Associa\u00e7\u00e3o Brasileira das Ind\u00fastrias de \u00d3leos Vegetais (Abiove), o procedimento adotado pelo Cade prejudica o direito de defesa e aumenta os riscos de inseguran\u00e7a jur\u00eddica para quem movimenta o mercado de soja nacional.<\/p>\n<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\">Na pr\u00e1tica, o entendimento mais recente do conselho estabelece que a suspens\u00e3o do acordo ambiental s\u00f3 seja v\u00e1lida a partir de 2026. O setor considera que, nesse per\u00edodo, h\u00e1 espa\u00e7o para negociar novos formatos para o acordo da Morat\u00f3ria, de modo a afastar acusa\u00e7\u00f5es de cartel e dar seguran\u00e7a jur\u00eddica \u00e0s opera\u00e7\u00f5es comerciais. No entanto, enquanto o Cade n\u00e3o resolve a disputa interna sobre a relatoria, permanece o receio de mudan\u00e7as repentinas ou de decis\u00f5es tomadas sem consenso entre produtores, empresas e autoridades p\u00fablicas.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u0b8de1bd32a451f1030fa367104a0168-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Agroneg\u00f3cio encerra o ano com 78 novos mercados em 39 pa\u00edses<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:pb-2\">Para o produtor, o recado \u00e9 de aten\u00e7\u00e3o. Vale acompanhar as pr\u00f3ximas sess\u00f5es do Cade, pois do desfecho desse julgamento pode depender o modelo de comercializa\u00e7\u00e3o da soja na Amaz\u00f4nia e o futuro das pol\u00edticas ambientais aplicadas ao setor. At\u00e9 que haja uma decis\u00e3o oficial e definitiva, a Morat\u00f3ria segue valendo, com possibilidade de negocia\u00e7\u00e3o nos pr\u00f3ximos meses.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/pensaragro.com.br\/indefinicao-no-cade-prolonga-cenario-de-inseguranca-para-produtores-de-soja-e-empresas\/\">Pensar Agro<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O futuro da Morat\u00f3ria da Soja permanece sem solu\u00e7\u00e3o definida no Conselho Administrativo de Defesa &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97872,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-97871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agro_cfnews"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97871"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97871\/revisions"}],"predecessor-version":[{"id":97873,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97871\/revisions\/97873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97872"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}