{"id":97926,"date":"2025-10-27T09:57:00","date_gmt":"2025-10-27T13:57:00","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97926"},"modified":"2025-10-28T10:08:28","modified_gmt":"2025-10-28T14:08:28","slug":"sinfra-ja-deu-ordem-de-servico-para-recuperacao-de-230-km-de-asfalto-na-mt-140","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/sinfra-ja-deu-ordem-de-servico-para-recuperacao-de-230-km-de-asfalto-na-mt-140\/","title":{"rendered":"Sinfra j\u00e1 deu ordem de servi\u00e7o para recupera\u00e7\u00e3o de 230 km de asfalto na MT-140"},"content":{"rendered":"<p>A Secretaria de Estado de Infraestrutura e Log\u00edstica (Sinfra) j\u00e1 deu ordem de servi\u00e7o para recupera\u00e7\u00e3o de 230,2 quil\u00f4metros da MT-140. Outros 79,1 quil\u00f4metros ter\u00e3o a recupera\u00e7\u00e3o autorizada nas pr\u00f3ximas semanas. O valor total do investimento ser\u00e1 de R$ 130 milh\u00f5es.<\/p>\n<p>O trecho de 309 quil\u00f4metros que ser\u00e1 recuperado passa pelos munic\u00edpios de Campo Verde, Chapada dos Guimar\u00e3es, Nova Brasil\u00e2ndia, Planalto da Serra, Ros\u00e1rio Oeste, Santa Rita do Trivelato, Sorriso e Nova Ubirat\u00e3.<\/p>\n<p>Ap\u00f3s o asfaltamento da MT-140, entregue em 2024, ligando a regi\u00e3o de Sorriso at\u00e9 Campo Verde, a rodovia se tornou um corredor log\u00edstico, paralelo \u00e0 BR-163.<\/p>\n<p>\u201cDepois do asfaltamento da MT-140, que tamb\u00e9m contemplou a constru\u00e7\u00e3o de tr\u00eas pontes sobre os Rios Teles Pires, Piabas e Beija Flor, e com as obras de duplica\u00e7\u00e3o da BR-163, o tr\u00e1fego na MT-140 aumentou muito, principalmente vindo dos munic\u00edpios de Nova Ubirat\u00e3 e Boa Esperan\u00e7a do Norte. Cerca de mil carretas passam por ela todos os dias, fazendo com que haja o desgaste natural do asfalto, em alguns pontos espec\u00edficos. Estamos fazendo a manuten\u00e7\u00e3o para garantir a seguran\u00e7a dos motoristas e a durabilidade das pistas\u201d, explicou o secret\u00e1rio de Infraestrutura e Log\u00edstica de Mato Grosso, Marcelo Oliveira.<\/p>\n<p>O secret\u00e1rio pontuou que a rodovia faz parte do Lote 6, que ir\u00e1 para leil\u00e3o na Bolsa de Valores de S\u00e3o Paulo, a B3, na pr\u00f3xima semana. Junto com trechos das MTs-020, 225, 244 e 251, o lote tem 634 quil\u00f4metros de extens\u00e3o e passa pelos munic\u00edpios de Sinop, Sorriso, Vera, Planalto da Serra, Campo Verde, Ros\u00e1rio Oeste, Santa Carmem, Santa Rita do Trivelato e Chapada dos Guimar\u00e3es.<\/p>\n<p>A concess\u00e3o ser\u00e1 de 30 anos e a empresa vencedora do leil\u00e3o ficar\u00e1 obrigada a fazer a opera\u00e7\u00e3o e manuten\u00e7\u00e3o, al\u00e9m de novos investimentos na rodovia.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 |\u00a0 \u00a0Foto:\u00a0 Christiano Antonucci\/Secom-MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Infraestrutura e Log\u00edstica (Sinfra) j\u00e1 deu ordem de servi\u00e7o para &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97927,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"No total, 309 km da rodovia ser\u00e3o recuperados, com investimento de R$ 130 milh\u00f5es","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97926"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97926\/revisions"}],"predecessor-version":[{"id":97928,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97926\/revisions\/97928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97927"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}