{"id":97929,"date":"2025-10-27T10:08:31","date_gmt":"2025-10-27T14:08:31","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=97929"},"modified":"2025-10-28T10:09:37","modified_gmt":"2025-10-28T14:09:37","slug":"ses-orienta-municipios-sobre-cuidados-com-a-saude-da-populacao-negra","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/ses-orienta-municipios-sobre-cuidados-com-a-saude-da-populacao-negra\/","title":{"rendered":"SES orienta munic\u00edpios sobre cuidados com a sa\u00fade da popula\u00e7\u00e3o negra"},"content":{"rendered":"<section id=\"content\" class=\"\">\n<div id=\"main-content\" class=\"layout-content portlet-layout\" role=\"main\">\n<div class=\"lfr-layout-structure-item-basic-component-html lfr-layout-structure-item-bda1c57d-ebfb-7ab5-34ae-f5ebeccc3ede \">\n<div id=\"fragment-8b42afae-e7ee-fa2f-93be-853497ece135\">\n<div class=\"component-html\" data-lfr-editable-id=\"element-html\" data-lfr-editable-type=\"html\">\n<div class=\"container-fluid viewNoticia mt-4 mb-5\">\n<div class=\"container mt-5\">\n<div class=\"row justify-content-md-center\">\n<div class=\"col-sm-11 conteudo\">\n<p>A Secretaria de Estado de Sa\u00fade (SES-MT) publicou uma nota t\u00e9cnica que recomenda aos gestores e \u00e0s equipes t\u00e9cnicas municipais de Mato Grosso a inclus\u00e3o de a\u00e7\u00f5es, metas e indicadores voltados \u00e0 sa\u00fade da popula\u00e7\u00e3o negra e quilombola nos Planos Municipais de Sa\u00fade 2026-2029 e nos Planos Plurianuais (PPAs).<\/p>\n<p>A publica\u00e7\u00e3o pode ser comemorada nesta segunda-feira (27.10), o Dia Nacional de Mobiliza\u00e7\u00e3o Pr\u00f3-Sa\u00fade da Popula\u00e7\u00e3o Negra.<\/p>\n<p>O documento, elaborado em conjunto com a Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz) e a Superintend\u00eancia Estadual do Minist\u00e9rio da Sa\u00fade de Mato Grosso, pode ser acessado\u00a0<a href=\"https:\/\/www.saude.mt.gov.br\/storage\/files\/q2kVGr0ovzG3wEqDliGuKa2X3dcSaOMuqhLpruTx.pdf\">no site da Secretaria de Estado de Sa\u00fade<\/a>.<\/p>\n<p>Conforme o documento, o planejamento dos munic\u00edpios deve ser alinhado \u00e0s diretrizes da Pol\u00edtica Nacional de Sa\u00fade Integral da Popula\u00e7\u00e3o Negra (PNSIPN), pol\u00edtica p\u00fablica do Minist\u00e9rio da Sa\u00fade para o combate de desigualdades e do racismo no Sistema \u00danico de Sa\u00fade (SUS).<\/p>\n<p>\u201cA nota t\u00e9cnica visa provocar uma reflex\u00e3o sobre os indicadores de sa\u00fade em Mato Grosso, com um olhar especial no recorte racial, para subsidiar a constru\u00e7\u00e3o de Planos Municipais de Sa\u00fade e Planos Plurianuais que contemplem a\u00e7\u00f5es estrat\u00e9gicas para a promo\u00e7\u00e3o da sa\u00fade da popula\u00e7\u00e3o negra\u201d, afirmou o secret\u00e1rio adjunto de Aten\u00e7\u00e3o e Vigil\u00e2ncia \u00e0 Sa\u00fade da SES, Juliano Melo.<\/p>\n<p>De acordo com a coordenadora de Promo\u00e7\u00e3o e Humaniza\u00e7\u00e3o da Sa\u00fade, Rosiene Pires, os dados epidemiol\u00f3gicos de Mato Grosso evidenciam desigualdades significativas, o que refor\u00e7a a necessidade de a\u00e7\u00f5es concretas, pois a popula\u00e7\u00e3o negra \u00e9 a mais atingida em diversos indicadores de sa\u00fade.<\/p>\n<p>\u201cAs disparidades s\u00e3o um reflexo do racismo estrutural, das desigualdades socioecon\u00f4micas e das barreiras no acesso aos servi\u00e7os de sa\u00fade, que se manifestam em piores condi\u00e7\u00f5es de moradia, nutri\u00e7\u00e3o inadequada e condi\u00e7\u00f5es sanit\u00e1rias\u201d, informa a coordenadora.<\/p>\n<p>A Secretaria recomenda que as prefeituras incorporem indicadores desagregados por ra\u00e7a e cor nos PPAs, metas espec\u00edficas para redu\u00e7\u00e3o de disparidades na mortalidade infantil e materna e na incid\u00eancia de doen\u00e7as.<\/p>\n<p>\u201cSugerimos que todos os sistemas municipais incluam o campo ra\u00e7a\/cor at\u00e9 o ano de 2027. Para essa a\u00e7\u00e3o ser efetiva, tamb\u00e9m \u00e9 necess\u00e1rio qualificar as equipes no preenchimento do quesito ra\u00e7a\/cor, estimular a autodeclara\u00e7\u00e3o quilombola e analisar dados desagregados sobre acesso, interna\u00e7\u00f5es e \u00f3bitos\u201d, acrescentou Rosiene.<\/p>\n<p>H\u00e1 ainda metas recomendadas para melhorar o monitoramento da Pol\u00edtica Nacional e fortalecer a\u00e7\u00f5es de preven\u00e7\u00e3o, diagn\u00f3stico e tratamento de doen\u00e7as que afetam desproporcionalmente a popula\u00e7\u00e3o negra e quilombola, como hipertens\u00e3o, diabetes, hansen\u00edase, anemia falciforme, tuberculose, s\u00edfilis e HIV\/AIDS.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/section>\n<div class=\"container-fluid\"><\/div>\n<div><\/div>\n<div>MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Paula Fr\u00f3es | Governo da Bahia<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Sa\u00fade (SES-MT) publicou uma nota t\u00e9cnica que recomenda aos gestores &hellip;<\/p>\n","protected":false},"author":4,"featured_media":97930,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-97929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Planejamento do Estado e dos munic\u00edpios deve ser alinhado \u00e0s diretrizes da Pol\u00edtica Nacional de Sa\u00fade Integral da Popula\u00e7\u00e3o Negra","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=97929"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97929\/revisions"}],"predecessor-version":[{"id":97931,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/97929\/revisions\/97931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/97930"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=97929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=97929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}