{"id":98082,"date":"2025-11-06T14:56:42","date_gmt":"2025-11-06T18:56:42","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98082"},"modified":"2025-11-10T12:38:05","modified_gmt":"2025-11-10T16:38:05","slug":"setasc-abre-inscricoes-para-sorteio-do-camarote-dos-autistas-no-jogo-do-cuiaba-contra-goias","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/setasc-abre-inscricoes-para-sorteio-do-camarote-dos-autistas-no-jogo-do-cuiaba-contra-goias\/","title":{"rendered":"Setasc abre inscri\u00e7\u00f5es para sorteio do Camarote dos Autistas no jogo do Cuiab\u00e1 contra Goi\u00e1s"},"content":{"rendered":"<p>A Secretaria de Estado de Assist\u00eancia Social e Cidadania (Setasc) abriu inscri\u00e7\u00f5es para o sorteio que levar\u00e1, de forma gratuita, portadores da Carteira de Identifica\u00e7\u00e3o do Autista a um camarote da Arena Pantanal. O sorteio \u00e9 v\u00e1lido para a partida do Cuiab\u00e1 Esporte Clube contra o Goi\u00e1s, que ocorre na pr\u00f3xima sexta-feira (7.11), \u00e0s 20h30.<\/p>\n<p>A partida \u00e9 v\u00e1lida pela 36\u00aa rodada do Campeonato Brasileiro da S\u00e9rie B. Os interessados podem se inscrever at\u00e9 \u00e0s 9h da manh\u00e3 da quinta-feira (6), por meio de formul\u00e1rio disponibilizado no site da Setasc &#8211;\u00a0<a href=\"https:\/\/carteiradoautista.setasc.mt.gov.br\/\">clique aqui para se inscrever<\/a>. Um dos campos a serem preenchidos requer o n\u00famero da Carteira de Identifica\u00e7\u00e3o do Autista.<\/p>\n<p>O sorteio est\u00e1 previsto para quinta-feira (6), logo ap\u00f3s o encerramento das inscri\u00e7\u00f5es, a partir dos nomes inscritos no formul\u00e1rio. Ap\u00f3s a realiza\u00e7\u00e3o do sorteio, a equipe da Setasc verifica se o sorteado est\u00e1 inscrito na Carteira de Identifica\u00e7\u00e3o do Autista. Caso n\u00e3o esteja, um novo sorteio ser\u00e1 realizado para ocupar a vaga aberta.<\/p>\n<p>Al\u00e9m da confirma\u00e7\u00e3o da inscri\u00e7\u00e3o na Carteira de Identifica\u00e7\u00e3o do Autista, \u00e9 necess\u00e1rio fazer o cadastro no FacePass para ter acesso \u00e0 Arena Pantanal.<\/p>\n<p><strong>Carteira de Identifica\u00e7\u00e3o do Autista<\/strong><\/p>\n<p>O documento \u00e9 emitido de forma gratuita pela Setasc e cont\u00e9m informa\u00e7\u00f5es espec\u00edficas e qualificadas da pessoa com Transtorno do Espectro Autista (TEA), o contato de emerg\u00eancia e, caso haja, informa\u00e7\u00f5es de seu representante legal\/cuidador.<\/p>\n<p>O cadastro da Carteira de Identifica\u00e7\u00e3o do Autista \u00e9 realizado pelo aplicativo MT Cidad\u00e3o, na modalidade digital e\/ou f\u00edsica (impressa). O prazo para a emiss\u00e3o da carteira digital \u00e9 de cinco dias a contar do envio da documenta\u00e7\u00e3o via aplicativo, an\u00e1lise e aprova\u00e7\u00e3o pela equipe da Setasc. J\u00e1 para a emiss\u00e3o da carteira f\u00edsica, o prazo \u00e9 de at\u00e9 30 dias.<\/p>\n<p>Mais informa\u00e7\u00f5es podem ser obtidas pelos telefones (65) 98421-4080 \/ (65) 3613-5711 ou no site da Setasc.<\/p>\n<p><strong>FacePass\u00a0<\/strong><\/p>\n<p>O cadastramento facial para a entrada na Arena Pantanal \u00e9 gerido pelo aplicativo FacePass Brasil, empresa respons\u00e1vel pela implanta\u00e7\u00e3o e desenvolvimento do sistema de reconhecimento facial no est\u00e1dio. Para se cadastrar, o usu\u00e1rio deve preencher os formul\u00e1rios com informa\u00e7\u00f5es pessoais e de endere\u00e7o. O cadastro \u00e9 feito no site:\u00a0<a href=\"https:\/\/facepassbrasil.com.br\/cadastrar-se\">facepassbrasil.com.br\/cadastrar-se\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 Foto:\u00a0 Jo\u00e3o Reis\/Setasc-MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Assist\u00eancia Social e Cidadania (Setasc) abriu inscri\u00e7\u00f5es para o sorteio &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98083,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-98082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Idealizada pela primeira-dama Virginia Mendes, a\u00e7\u00e3o leva pessoas com Transtorno do Espectro Autista (TEA) para camarote da Arena Pantanal","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98082"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98082\/revisions"}],"predecessor-version":[{"id":98084,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98082\/revisions\/98084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98083"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}