{"id":98101,"date":"2025-11-05T14:32:41","date_gmt":"2025-11-05T18:32:41","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98101"},"modified":"2025-11-05T14:32:41","modified_gmt":"2025-11-05T18:32:41","slug":"prefeitura-realiza-mutirao-do-cadastro-unico-no-distrito-nossa-senhora-da-guia","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeitura-realiza-mutirao-do-cadastro-unico-no-distrito-nossa-senhora-da-guia\/","title":{"rendered":"Prefeitura realiza Mutir\u00e3o do Cadastro \u00danico no distrito Nossa Senhora da Guia"},"content":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por meio da Secretaria Municipal de Assist\u00eancia Social, Direitos Humanos e Inclus\u00e3o, realiza neste s\u00e1bado (8), das 8h \u00e0s 15h, o Mutir\u00e3o do Cadastro \u00danico, no distrito Nossa Senhora da Guia. A a\u00e7\u00e3o acontecer\u00e1 na Igreja Assembleia de Deus, localizada na Rua Vicente Figueiredo, e visa facilitar o acesso dos cuiabanos aos servi\u00e7os socioassistenciais e de sa\u00fade.<\/p>\n<p>O evento conta com o apoio da Secretaria Municipal de Sa\u00fade e da Secretaria de Estado de Assist\u00eancia Social e Cidadania (SETASC) e das duas equipes dos postos de sa\u00fade da regi\u00e3o. Al\u00e9m disso, tamb\u00e9m haver\u00e1 palestras da equipe E Multi. A iniciativa refor\u00e7a o compromisso da gest\u00e3o municipal em levar pol\u00edticas p\u00fablicas at\u00e9 as comunidades mais distantes do centro da capital, garantindo que fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade possam atualizar seus dados e manter o acesso a programas sociais.<\/p>\n<p>A secret\u00e1ria municipal de Assist\u00eancia Social, Direitos Humanos e Inclus\u00e3o, H\u00e9lida Vilela, destacou a import\u00e2ncia da mobiliza\u00e7\u00e3o e convidou os moradores a participarem. \u201cManter o Cadastro \u00danico atualizado \u00e9 fundamental para que as fam\u00edlias continuem recebendo os benef\u00edcios dos programas sociais do Governo Federal e da Prefeitura. Muitas vezes, a falta de atualiza\u00e7\u00e3o pode fazer com que o cidad\u00e3o perca direitos importantes. Por isso, estamos levando essa a\u00e7\u00e3o at\u00e9 a comunidade, para facilitar e garantir o atendimento a todos\u201d, enfatizou H\u00e9lida.<\/p>\n<p>Al\u00e9m dos atendimentos do Cadastro \u00danico, o mutir\u00e3o tamb\u00e9m contar\u00e1 com uma s\u00e9rie de servi\u00e7os gratuitos voltados \u00e0 sa\u00fade e cidadania.<\/p>\n<p><strong>Servi\u00e7os dispon\u00edveis durante o mutir\u00e3o:<\/strong><\/p>\n<p>Atualiza\u00e7\u00e3o e novos cadastros no Cadastro \u00danico;<\/p>\n<p>Aferi\u00e7\u00e3o de press\u00e3o arterial e teste de glicemia;<\/p>\n<p>Aplica\u00e7\u00e3o de vacinas;<\/p>\n<p>Pesagem obrigat\u00f3ria do Bolsa Fam\u00edlia;<\/p>\n<p>Inscri\u00e7\u00f5es para o programa Casamento Aben\u00e7oado.<\/p>\n<p>A a\u00e7\u00e3o busca aproximar os servi\u00e7os p\u00fablicos da popula\u00e7\u00e3o, promover inclus\u00e3o social e garantir que mais fam\u00edlias cuiabanas tenham seus direitos assegurados.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de\u00a0 Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Erlan Aquino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por meio da Secretaria Municipal de Assist\u00eancia Social, Direitos Humanos e &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98102,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-98101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98101"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98101\/revisions"}],"predecessor-version":[{"id":98103,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98101\/revisions\/98103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98102"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}