{"id":98163,"date":"2025-11-11T17:00:11","date_gmt":"2025-11-11T21:00:11","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98163"},"modified":"2025-11-11T17:00:11","modified_gmt":"2025-11-11T21:00:11","slug":"seduc-reforca-dialogo-com-professores-e-estudantes-em-visitas-tecnicas-no-polo-sinop","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/seduc-reforca-dialogo-com-professores-e-estudantes-em-visitas-tecnicas-no-polo-sinop\/","title":{"rendered":"Seduc refor\u00e7a di\u00e1logo com professores e estudantes em visitas t\u00e9cnicas no Polo Sinop"},"content":{"rendered":"<p>A Secretaria de Estado de Educa\u00e7\u00e3o de Mato Grosso (Seduc-MT) promove a partir desta ter\u00e7a-feira (11.11) at\u00e9 quinta-feira (13), a 10\u00aa etapa do programa Giro pelas Escolas MT, que leva a equipe t\u00e9cnica e o secret\u00e1rio de Educa\u00e7\u00e3o Alan Porto a uma s\u00e9rie de visitas a escolas estaduais e municipais do Polo Regional de Sinop.<\/p>\n<p>De acordo com o secret\u00e1rio, mais do que uma agenda administrativa, o giro tem se consolidado como uma rota de escuta, di\u00e1logo e presen\u00e7a, pilares que v\u00eam aproximando a gest\u00e3o estadual da realidade das salas de aula.<\/p>\n<p>\u201cA escola \u00e9 o cora\u00e7\u00e3o da Educa\u00e7\u00e3o, e \u00e9 l\u00e1 que as coisas acontecem. Estar presente, olhar nos olhos dos professores e ouvir os estudantes faz toda a diferen\u00e7a. Essa escuta qualificada \u00e9 o que direciona nossos investimentos e pol\u00edticas p\u00fablicas\u201d, destacou.<\/p>\n<p>Durante as visitas, Alan Porto e a equipe da Seduc participam de encontros com gestores escolares, professores, estudantes e servidores administrativos. A ideia \u00e9 compreender as demandas locais, identificar solu\u00e7\u00f5es conjuntas e compartilhar boas pr\u00e1ticas que fortalecem o processo de ensino e aprendizagem.<\/p>\n<p>Nesta etapa, o secret\u00e1rio visita escolas como S\u00e3o Crist\u00f3v\u00e3o, Vida Nova e Dom Bosco, em Lucas do Rio Verde; Cristiano Ara\u00fajo Pires, em Boa Esperan\u00e7a do Norte; 19 de Dezembro, em Nova Ubirat\u00e3; Jos\u00e9 Domingos Fraga e Ign\u00e1cio Schevinski\/Seciteci, em Sorriso; Nossa Senhora Aparecida, em Santa Carmem; e a Escola C\u00edvico-Militar Perp\u00e9tuo Socorro, em Vera, entre outras unidades.<\/p>\n<p>\u201cA escuta ativa \u00e9 um instrumento de gest\u00e3o e tamb\u00e9m um gesto de respeito. Cada professor e cada aluno t\u00eam uma hist\u00f3ria, e \u00e9 ouvindo essas hist\u00f3rias que conseguimos construir pol\u00edticas mais justas e eficazes\u201d, acrescentou o secret\u00e1rio.<\/p>\n<p>Desde o in\u00edcio de 2025, o Giro pelas Escolas MT j\u00e1 percorreu as Diretorias Regionais de Matup\u00e1, Barra do Gar\u00e7as, Pontes e Lacerda, Tangar\u00e1 da Serra, Rondon\u00f3polis, Confresa, Alta Floresta e Ju\u00edna, alcan\u00e7ando centenas de educadores, estudantes e gestores.<\/p>\n<p>A meta \u00e9 chegar, at\u00e9 dezembro, \u00e0s 13 regionais de educa\u00e7\u00e3o.<\/p>\n<p>Em cada local, segundo a Seduc, o roteiro inclui visitas t\u00e9cnicas, reuni\u00f5es pedag\u00f3gicas e rodas de conversa, sempre com foco no aprimoramento da aprendizagem, da infraestrutura e do bem-estar da comunidade escolar.<\/p>\n<p>\u201cA educa\u00e7\u00e3o se transforma quando o di\u00e1logo \u00e9 constante. \u00c9 no contato direto, no olho no olho, que entendemos o que precisa melhorar e celebramos o que est\u00e1 dando certo. Esse \u00e9 o verdadeiro sentido do Giro pelas Escolas\u201d, refor\u00e7ou Alan Porto.<\/p>\n<p>As pr\u00f3ximas etapas est\u00e3o previstas para os polos de Diamantino, C\u00e1ceres e na Dire\u00e7\u00e3o Metropolitana de Educa\u00e7\u00e3o, em Cuiab\u00e1.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Dacio Carvalho | Seduc-MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Educa\u00e7\u00e3o de Mato Grosso (Seduc-MT) promove a partir desta ter\u00e7a-feira &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98164,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"At\u00e9 dezembro, o programa de escuta ativa ter\u00e1 passado pelas 13 Diretorias Regionais de Educa\u00e7\u00e3o do estado","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98163"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98163\/revisions"}],"predecessor-version":[{"id":98165,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98163\/revisions\/98165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98164"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}