{"id":98169,"date":"2025-11-11T17:04:48","date_gmt":"2025-11-11T21:04:48","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98169"},"modified":"2025-11-11T17:04:48","modified_gmt":"2025-11-11T21:04:48","slug":"secel-vai-selecionar-organizacao-da-sociedade-civil-para-execucao-do-forum-de-bibliotecas-publicas-de-mato-grosso","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/secel-vai-selecionar-organizacao-da-sociedade-civil-para-execucao-do-forum-de-bibliotecas-publicas-de-mato-grosso\/","title":{"rendered":"Secel vai selecionar Organiza\u00e7\u00e3o da Sociedade Civil para execu\u00e7\u00e3o do F\u00f3rum de Bibliotecas P\u00fablicas de Mato Grosso"},"content":{"rendered":"<p>A Secretaria de Estado de Cultura, Esporte e Lazer (Secel) publicou, nesta segunda-feira (10.11), o edital que visa selecionar uma Organiza\u00e7\u00e3o da Sociedade Civil (OSC) para execu\u00e7\u00e3o do \u201cVII F\u00f3rum de Bibliotecas P\u00fablicas de Mato Grosso\u201d. Com investimento de R$ 300 mil, o chamamento p\u00fablico est\u00e1 com inscri\u00e7\u00f5es abertas at\u00e9 o dia 20 de novembro.<\/p>\n<p>O evento, que ser\u00e1 realizado em Cuiab\u00e1, busca fortalecer o Sistema Estadual de Bibliotecas P\u00fablicas, ampliar o acesso \u00e0 leitura, ao livro e \u00e0 informa\u00e7\u00e3o e consolidar as bibliotecas como espa\u00e7os de cultura, cidadania e inclus\u00e3o social.<\/p>\n<p>Sob regime de m\u00fatua coopera\u00e7\u00e3o com a Secel, a programa\u00e7\u00e3o deve abranger atividades de aprendizado e de integra\u00e7\u00e3o das bibliotecas p\u00fablicas dos munic\u00edpios mato-grossenses. \u00c0 OSC selecionada caber\u00e1 as a\u00e7\u00f5es de gest\u00e3o, produ\u00e7\u00e3o, infraestrutura, log\u00edstica e programa\u00e7\u00e3o t\u00e9cnica, art\u00edstica e cultural do F\u00f3rum.<\/p>\n<p>A primeira etapa do chamamento p\u00fablico envolve a an\u00e1lise e sele\u00e7\u00e3o t\u00e9cnica, cujos crit\u00e9rios incluem dados do portf\u00f3lio do proponente, como capacidade operacional e curr\u00edculo dos profissionais envolvidos, e detalhamento da proposta.<\/p>\n<p>Ap\u00f3s a fase de sele\u00e7\u00e3o t\u00e9cnica, as institui\u00e7\u00f5es pr\u00e9-selecionadas dever\u00e3o encaminhar a documenta\u00e7\u00e3o de habilita\u00e7\u00e3o jur\u00eddica e fiscal, o Plano de Trabalho e demais documentos obrigat\u00f3rios.<\/p>\n<p>Podem participar do chamamento p\u00fablico pessoas jur\u00eddicas sem fins lucrativos que comprovem as instru\u00e7\u00f5es disponibilizadas no item de Documenta\u00e7\u00e3o Obrigat\u00f3ria do edital (<a href=\"https:\/\/www.secel.mt.gov.br\/documents\/362998\/75585466\/ANEXO+III+-+DOCUMENTA%C3%87%C3%83O+OBRIGAT%C3%93RIA.pdf\/08a3cb3a-f635-a410-baff-c8d1f6275a9a?t=1762815607836\">anexo III<\/a>).<\/p>\n<p>Para se inscrever, a OSC interessada deve enviar o formul\u00e1rio de Inscri\u00e7\u00e3o\/Plano de Trabalho e demais anexos exigidos para inscri\u00e7ao, devidamente preenchidos e em formato PDF, ao e-mail protocolo@secel.mt.gov.br. Todas as orienta\u00e7\u00f5es est\u00e3o descritas no edital dispon\u00edvel na p\u00e1gina\u00a0<a href=\"https:\/\/www.secel.mt.gov.br\/editais-cultura1\">www.secel.mt.gov.br\/editais-cultura1<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Servi\u00e7o |\u00a0<\/strong>Edital VII F\u00f3rum de Bibliotecas P\u00fablicas de Mato Grosso<br \/>\nObjetivo: selecionar OSC para execu\u00e7\u00e3o do evento<br \/>\nPrazo para inscri\u00e7\u00e3o: de 11 a 20 novembro de 2025<br \/>\nAcesso ao edital e documenta\u00e7\u00e3o obrigat\u00f3ria: \u00a0<a href=\"https:\/\/www.secel.mt.gov.br\/w\/edital-13-2025-vii-forum-de-bibliotecas-publicas-de-mt\">link aqui<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Cultura, Esporte e Lazer (Secel) publicou, nesta segunda-feira (10.11), o &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Edital de chamamento p\u00fablico est\u00e1 com inscri\u00e7\u00f5es abertas de 11 a 20 de novembro de 2025","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98169"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98169\/revisions"}],"predecessor-version":[{"id":98171,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98169\/revisions\/98171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98170"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}