{"id":98320,"date":"2025-11-20T10:23:25","date_gmt":"2025-11-20T14:23:25","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98320"},"modified":"2025-11-24T10:27:58","modified_gmt":"2025-11-24T14:27:58","slug":"governador-vai-a-justica-contra-decreto-de-lula-que-amplia-terras-indigenas-em-mt","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/governador-vai-a-justica-contra-decreto-de-lula-que-amplia-terras-indigenas-em-mt\/","title":{"rendered":"Governador vai \u00e0 Justi\u00e7a contra decreto de Lula que amplia terras ind\u00edgenas em MT"},"content":{"rendered":"<p>O governador Mauro Mendes anunciou, nesta ter\u00e7a-feira (18\/11), que o Governo de Mato Grosso ir\u00e1 acionar a Justi\u00e7a contra o decreto do presidente Lula que amplia a demarca\u00e7\u00e3o de terras ind\u00edgenas no estado.<\/p>\n<p>As medidas do presidente foram oficializadas durante a Confer\u00eancia Mundial do Clima (COP 30), em Bel\u00e9m.<\/p>\n<p>Uma dessas terras ind\u00edgenas \u00e9 a Manoki, tradicionalmente reconhecida com cerca de 46 mil hectares, e que teve sua \u00e1rea ampliada para aproximadamente 250 mil hectares, segundo dados divulgados pelo pr\u00f3prio governo federal.<\/p>\n<p>De acordo com o governador, a amplia\u00e7\u00e3o desrespeita diretamente o artigo 13 da Lei 14.701, que pro\u00edbe a expans\u00e3o de terras ind\u00edgenas j\u00e1 demarcadas.<\/p>\n<p>Al\u00e9m da Manoki, o governo federal tamb\u00e9m homologou a Terra Ind\u00edgena Uirapuru, com cerca de 21,6 mil hectares, e a Terra Ind\u00edgena Esta\u00e7\u00e3o Parecis, com aproximadamente 2,1 mil hectares, ambas localizadas em regi\u00f5es produtivas de Mato Grosso.<\/p>\n<p>\u201cDeterminei \u00e0 Procuradoria-Geral do Estado que ingresse imediatamente na Justi\u00e7a para barrar essa ilegalidade. N\u00e3o estamos discutindo o direito dos povos ind\u00edgenas, que \u00e9 leg\u00edtimo, mas sim um decreto que afronta a lei, cria inseguran\u00e7a jur\u00eddica e coloca em risco a vida de quem mora e produz nessas \u00e1reas\u201d, afirmou o governador.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u4efa53e3c8a6b21e2e31e08644a87252-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Pol\u00edcia Civil prende quatro pessoas em MT e Goi\u00e1s por tentativa de homic\u00eddio em Rondon\u00f3polis<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>Mauro lembrou que Mato Grosso possui atualmente 73 terras ind\u00edgenas demarcadas, que somam 15 milh\u00f5es de hectares, o equivalente a 16% de todo o territ\u00f3rio estadual.<\/p>\n<p>Ele refor\u00e7ou que o respeito aos povos ind\u00edgenas deve vir acompanhado de pol\u00edticas p\u00fablicas reais, como sa\u00fade, educa\u00e7\u00e3o, assist\u00eancia e infraestrutura, e n\u00e3o apenas de decretos que ampliam territ\u00f3rio sem planejamento e sem di\u00e1logo com as comunidades e com as fam\u00edlias j\u00e1 estabelecidas no local.<\/p>\n<p>O governador tamb\u00e9m destacou que na regi\u00e3o da TI Manoki existem centenas de fam\u00edlias e dezenas de CARs (Cadastros Ambientais Rurais) registrados, alguns deles amparados por decis\u00e3o judicial, o que agrava a situa\u00e7\u00e3o de conflito fundi\u00e1rio.<\/p>\n<p>Al\u00e9m disso, Mauro ressaltou que Mato Grosso \u00e9 um dos estados que mais preservam o meio ambiente, com 60% do territ\u00f3rio protegido, \u00edndice superior ao de diversos pa\u00edses que usualmente cobram a\u00e7\u00f5es ambientais do Brasil.<\/p>\n<p>\u201cMato Grosso faz a sua parte. Preserva, produz e respeita a lei. N\u00e3o \u00e9 criando problema para milhares de brasileiros em pleno evento internacional que vamos avan\u00e7ar. Queremos di\u00e1logo e respeito\u201d, concluiu.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u4ff52d46a2259aef6a3577169e54834a-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Patrulha Maria da Penha prende homem por manter ex-mulher em c\u00e1rcere privado em Tangar\u00e1 da Serra<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte:\u00a0<a href=\"http:\/\/www.secom.mt.gov.br\/w\/governador-vai-%C3%A0-justi%C3%A7a-contra-decreto-de-lula-que-amplia-terras-ind%C3%ADgenas-em-mt#3f257bab-503d-497e-a1c5-d68014ff6a0f\" target=\"_blank\" rel=\"noopener\">Governo MT \u2013 MT<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Mauro Mendes anunciou, nesta ter\u00e7a-feira (18\/11), que o Governo de Mato Grosso ir\u00e1 &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98321,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98320"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98320\/revisions"}],"predecessor-version":[{"id":98322,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98320\/revisions\/98322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98321"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}