{"id":98328,"date":"2025-11-21T11:15:01","date_gmt":"2025-11-21T15:15:01","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98328"},"modified":"2025-11-24T11:17:09","modified_gmt":"2025-11-24T15:17:09","slug":"modelo-implementado-em-mt-para-garantir-producao-regular-de-madeira-nativa-e-referencia-em-nivel-nacional","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/modelo-implementado-em-mt-para-garantir-producao-regular-de-madeira-nativa-e-referencia-em-nivel-nacional\/","title":{"rendered":"Modelo implementado em MT para garantir produ\u00e7\u00e3o regular de madeira nativa \u00e9 refer\u00eancia em n\u00edvel nacional"},"content":{"rendered":"<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">A Secretaria de Estado de Meio Ambiente (Sema-MT) tem implementado mecanismos rigorosos de controle, monitoramento e gest\u00e3o para assegurar que a produ\u00e7\u00e3o de madeira nativa ocorra de forma regular, rastre\u00e1vel e em conformidade com a legisla\u00e7\u00e3o ambiental. O modelo adotado no Estado, que inclui o sistema de monitoramento da cobertura florestal para o manejo, fiscaliza\u00e7\u00e3o e o Sistema de Comercializa\u00e7\u00e3o e Transporte de Produtos Florestais (Sisflora) para rastreabilidade, \u00e9 refer\u00eancia em n\u00edvel nacional e, por isso, o\u00a0<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Governo de Mato Grosso foi\u00a0<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">convidado a apresentar a iniciativa na\u00a0<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">5\u00aa edi\u00e7\u00e3o do eve<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">nto\u00a0<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">\u201cMadeira Sustent\u00e1vel: O futuro do Mercado\u201d,\u00a0<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">realizado na sede da\u00a0<\/span><\/span><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Federa\u00e7\u00e3o das Ind\u00fastrias do Estado da Bahia.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">\u201c<\/span><\/span><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: medium;\">O manejo florestal sustent\u00e1vel se consolida como uma das estrat\u00e9gias mais robustas para manter a floresta em p\u00e9, conservar servi\u00e7os ecossist\u00eamicos e, ao mesmo tempo, gerar renda e desenvolvimento regional\u201d, destacou a secret\u00e1ria de Estado de Meio Ambiente, Mauren Lazzaretti, nesta quarta-feira (19.11), em palestra proferida no evento.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Segundo ela, Mato Grosso conta atualmente com 5,2 milh\u00f5es de hectares em \u00e1reas de manejo florestal e a meta do Programa Carbono Neutro 2035 \u00e9 chegar a seis milh\u00f5es. \u201c<\/span><\/span><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"font-size: medium;\">Trata-se de um recurso florestal renov\u00e1vel, com potencial para impulsionar a bioeconomia de base florestal no pa\u00eds\u201d, acrescentou.<\/span><\/span><\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u716c81212837cdc98e5e292c030fd01a-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Opera\u00e7\u00e3o Toler\u00e2ncia Zero para delitos de tr\u00e2nsito remove 19 motos e flagra 21 condutores sem CNH<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: medium;\">Localizada no munic\u00edpio de Alta Floresta, na divisa entre Mato Grosso e o estado do Par\u00e1, a\u00a0<\/span>Fazenda Vaca Branca \u00e9 um dos exemplos de sucesso em manejo florestal. A pr\u00e1tica come\u00e7ou a ser implementada na propriedade h\u00e1 quatro anos e a primeira \u00e1rea contemplada est\u00e1 em plena regenera\u00e7\u00e3o.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\">Nas \u00e1reas de manejo, o corte das \u00e1rvores \u00e9 feito de maneira seletiva, respeitando o ciclo de vida dos indiv\u00edduos. \u00c1rvores que j\u00e1 cumpriram o seu papel na natureza s\u00e3o colhidas de forma estrat\u00e9gica, minimizando o impacto ambiental e dando espa\u00e7o para que suas filhas possam crescer para prolifera\u00e7\u00e3o da esp\u00e9cie.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\">A secret\u00e1ria de Estado de Meio Ambiente ressalta que, por meio do Sistema de Comercializa\u00e7\u00e3o e Transporte de Produtos Florestais (Sisflora), o \u00f3rg\u00e3o ambiental consegue fazer a rastreabilidade da madeira extra\u00edda nessas \u00e1reas de manejo. Cada indiv\u00edduo possui numera\u00e7\u00e3o \u00fanica dentro do sistema.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\">Durante o evento realizado em Salvador, o<\/span><span style=\"font-family: Arial, sans-serif;\">\u00a0secret\u00e1rio de Estado de Desenvolvimento Econ\u00f4mico de Mato Grosso (Sedec), C\u00e9sar Miranda,\u00a0<\/span><span style=\"font-family: Arial, sans-serif;\">refor\u00e7ou a import\u00e2ncia da pr\u00e1tica do manejo florestal para monetiza\u00e7\u00e3o da natureza.<\/span><\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u99ecb867d260a133e7fde8e6cee6dfdc-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">PM prende dupla por tr\u00e1fico de drogas, apreende 180 por\u00e7\u00f5es de coca\u00edna e duas armas<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p align=\"justify\">\u201c<span style=\"font-family: Arial, sans-serif;\">Mato Grosso \u00e9 um grande produtor de madeira sustent\u00e1vel, o manejo n\u00e3o s\u00f3 preserva, como recupera a floresta. Precisamos continuar utilizando pr\u00e1ticas como esta, para monetizar aquilo que n\u00f3s temos na natureza,\u00a0<\/span><span style=\"font-family: Arial, sans-serif;\">preservando e gerando\u00a0<\/span><span style=\"font-family: Arial, sans-serif;\">emprego e renda\u201d,\u00a0<\/span><span style=\"font-family: Arial, sans-serif;\">afirmou.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial, sans-serif;\">A\u00a0<\/span><span style=\"font-family: Arial, sans-serif;\">5\u00aa edi\u00e7\u00e3o do\u00a0<\/span><span style=\"font-family: Arial, sans-serif;\">evento\u00a0<\/span><span style=\"font-family: Arial, sans-serif;\">\u201cMadeira Sustent\u00e1vel: O futuro do Mercado\u201d\u00a0<\/span><span style=\"font-family: Arial, sans-serif;\">foi promovida pelo F\u00f3rum Nacional das Atividades de Base Florestal (FNBF) e pelo Centro das Ind\u00fastrias Produtoras e Exportadoras de Madeira do Estado de Mato Grosso (Cipem), em parceria com a Federa\u00e7\u00e3o das Ind\u00fastrias do Estado da Bahia (Fieb), Associa\u00e7\u00e3o Brasileira de Entidades Estaduais de Meio Ambiente (Abema) e Sebrae Mato Grosso.<\/span><\/p>\n<p id=\"infocoweb_fonte\" class=\"infocoweb_fonte\">Fonte:\u00a0<a href=\"http:\/\/www.secom.mt.gov.br\/w\/modelo-implementado-em-mt-para-garantir-produ%C3%A7%C3%A3o-regular-de-madeira-nativa-%C3%A9-refer%C3%AAncia-em-n%C3%ADvel-nacional#d498d5b0-b6e3-4513-bce0-360a9a250023\" target=\"_blank\" rel=\"noopener\">Governo MT \u2013 MT<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Meio Ambiente (Sema-MT) tem implementado mecanismos rigorosos de controle, monitoramento &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98329,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98328"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98328\/revisions"}],"predecessor-version":[{"id":98330,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98328\/revisions\/98330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98329"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}