{"id":98331,"date":"2025-11-21T11:17:27","date_gmt":"2025-11-21T15:17:27","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98331"},"modified":"2025-11-24T11:18:37","modified_gmt":"2025-11-24T15:18:37","slug":"entre-penelope-geisa-e-as-redes-sociais-o-cuiabano-eduardo-butakka-fala-de-arte-empreendedorismo-e-futuro-do-cinema-em-mt","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/entre-penelope-geisa-e-as-redes-sociais-o-cuiabano-eduardo-butakka-fala-de-arte-empreendedorismo-e-futuro-do-cinema-em-mt\/","title":{"rendered":"Entre Pen\u00e9lope, Geisa e as redes sociais: O cuiabano Eduardo Butakka fala de arte, empreendedorismo e futuro do cinema em MT"},"content":{"rendered":"<p>Eduardo Butakka \u00e9 um daqueles artistas que carregam o palco, os cen\u00e1rios e a rua dentro de si. Cuiabano, formado em Teatro pela Universidade de Bras\u00edlia e em Publicidade e Propaganda pela UFMT, ele transita entre humor, cr\u00edtica social e experimenta\u00e7\u00f5es no audiovisual com a mesma naturalidade com que observa o cotidiano para criar personagens que se tornaram febre entre os mato-grossenses. Nesta entrevista exclusiva, Butakka revisita sua forma\u00e7\u00e3o, comenta o impacto de ter sido o primeiro mato-grossense indicado ao Pr\u00eamio Multishow de Humor, aborda a responsabilidade pol\u00edtica da arte e revela seus novos projetos \u2014 do audiovisual ao primeiro longa-metragem. Uma conversa franca, divertida e, acima de tudo, profundamente comprometida com a cultura de Mato Grosso.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Veja entrevista:<\/strong><\/p>\n<p><strong>RDM online:<\/strong>\u00a0Eduardo Butakka, primeiramente, voc\u00ea \u00e9 natural de Cuiab\u00e1 e tem forma\u00e7\u00e3o em Teatro pela Universidade de Bras\u00edlia e em Publicidade e Propaganda pela UFMT. Como \u00e9 essa dupla forma\u00e7\u00e3o e como foi a sua atua\u00e7\u00e3o como ator e humorista?<\/p>\n<p><strong>Eduardo:\u00a0<\/strong>Comecei no teatro aos 15 anos, no ensino m\u00e9dio, em um grupo amador do CEFET (Escola T\u00e9cnica Federal), com o Gilberto Nascer, do\u00a0<em>Grupo Pessoal do \u00c2nima<\/em>. Ele foi um divisor de \u00e1guas, me ensinando n\u00e3o apenas a atuar, mas a apreciar a arte. \u201cVoc\u00eas precisam sentar e ver\u201d, dizia. Para ele, consumir arte era t\u00e3o importante quanto produzi-la, pois sem refer\u00eancias o trabalho perde consist\u00eancia.<\/p>\n<p data-start=\"461\" data-end=\"918\">Passei do teatro amador para o profissional, obtendo minha DRT de ator e diretor, participei de festivais e depois me formei na UNB, onde tamb\u00e9m me tornei professor de teatro. Estudei comunica\u00e7\u00e3o por proximidade com criatividade, dramaturgia e escrita. Hoje, a publicidade ajuda a manter minha carreira financeiramente e artisticamente, porque marketing conecta a obra art\u00edstica ao p\u00fablico, mostrando o espet\u00e1culo antes mesmo do ingresso ser comprado.<\/p>\n<p><strong>RDM online:<\/strong>\u00a0Voc\u00ea foi indicado em 2017, primeiro mato-grossense selecionado para o Pr\u00eamio Multishow de Humor. Qual foi o impacto desse reconhecimento na sua carreira e na cena de Mato Grosso?<\/p>\n<p><strong>Eduardo:<\/strong>\u00a0Participar da seletiva com mais de 5 mil candidatos foi muito importante. Fui a Goi\u00e2nia para o teste e, apesar de ir com amigos, fui o \u00fanico selecionado pelo perfil que procuravam. A diretora me elogiou, mas disse: \u201cVoc\u00ea \u00e9 muito bom, mas est\u00e1 longe\u201d. Rio disso hoje, mas era um riso nervoso \u2014 mostra nossa for\u00e7a, vendo artistas locais brilhando nacionalmente.<\/p>\n<p data-start=\"437\" data-end=\"743\">Fiquei lisonjeado, mas tamb\u00e9m sufocado com a expectativa da aprova\u00e7\u00e3o externa. Ser selecionado abre portas e permite contato com artistas de todo o pa\u00eds, como Estevam Nabote, que me ajudou depois. Mas tento n\u00e3o me iludir com a ideia de \u201cprecisar sair daqui\u201d; \u00e9 preciso criar oportunidades aqui mesmo.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u806d4b48e9552842ec7ea807f8a93234-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Hilux capota e deixa quatro feridos em Chapada dos Guimar\u00e3es<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p><strong>RDM online:<\/strong>\u00a0Voc\u00ea criou personagens marcantes como Pen\u00e9lope e Professora Geisa. De onde vieram as inspira\u00e7\u00f5es? E como voc\u00ea faz a transi\u00e7\u00e3o para pap\u00e9is mais s\u00e9rios?<\/p>\n<p><strong>Eduardo:<\/strong>\u00a0Gilberto sempre dizia que o ator \u00e9 um ladr\u00e3o: rouba sem tirar da pessoa. \u00c9 um gesto, um jeito de falar, um trejeito que observamos. O ator \u00e9 um grande observador. Eu era muito introspectivo. Fui desenvolvendo a extrovers\u00e3o com o passar dos anos. E o introspectivo sabe que o mundo \u00e9 mental \u2014 99% \u00e9 mental e 1% \u00e9 o que voc\u00ea mostra.<\/p>\n<p>Essas pessoas me inspiram. Professoras que tive, pessoas que conheci. \u00c9 um Frankenstein de personalidades. Recebo mensagens dizendo: \u201cVoc\u00ea est\u00e1 imitando a professora tal do col\u00e9gio tal?\u201d. Muitas vezes nunca estudei l\u00e1, mas meu objetivo \u00e9 esse, acessar a mem\u00f3ria do p\u00fablico.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RDM online:<\/strong>\u00a0Seus personagens t\u00eam um fundo cr\u00edtico. \u00c9 proposital?<\/p>\n<p><strong>Eduardo:<\/strong>\u00a0N\u00e3o d\u00e1 para separar obra e artista. Os personagens s\u00e3o peda\u00e7os de mim. Uso eles para manifestar meu pensamento pol\u00edtico, ideol\u00f3gico, social. N\u00e3o acredito em arte que n\u00e3o seja verdadeira. Meu papel \u00e9 de cronista do meu tempo. Se n\u00e3o falar sobre pol\u00edtica e sociedade, minha arte vira superficial, estereotipada, riso f\u00e1cil. E se essa \u00e9 minha arma, vou usar.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_741784\" class=\"wp-caption aligncenter\" aria-describedby=\"caption-attachment-741784\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-741784 size-full\" src=\"https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.22.38-e1763764790533.jpeg\" sizes=\"auto, (max-width: 762px) 100vw, 762px\" srcset=\"https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.22.38-e1763764790533.jpeg 762w, https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.22.38-e1763764790533-300x281.jpeg 300w, https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.22.38-e1763764790533-750x704.jpeg 750w\" alt=\"\" width=\"762\" height=\"715\" \/><figcaption id=\"caption-attachment-741784\" class=\"wp-caption-text\">\u00c0 esquerda, Thiago Mour\u00e3o e \u00e0 direita Eduardo Butakka. Foto: Arquivo Pessoal<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>RDM online:<\/strong>\u00a0Tem algu\u00e9m da cultura cuiabana que te inspira?<\/p>\n<p><strong>Eduardo:<\/strong>\u00a0Muitos. Thiago Mour\u00e3o, come\u00e7amos juntos no teatro e me ajudou muito como ele conduz o trabalho dele. Eu tinha um receio de ter essa exposi\u00e7\u00e3o nas redes sociais porque eu sou um artista do palco e ele me ajudou a melhorar v\u00e1rias \u00e2mbitos da minha carreira.<\/p>\n<p>O Nico e Lau, acho muito bacana como eles conseguem ter uma arte sustent\u00e1vel e permanecer tantos anos falando da cultura e dos costumes cuiabanos e o Andr\u00e9 de Luca, e principalmente o Liu Arruda. Eu imitava o Arruda na escola. O cuiabano \u00e9 escrachado \u2014 quem vem de fora pode achar ofensivo, mas n\u00e3o \u00e9. \u00c9 espont\u00e2neo, \u00e9 pureza. Nossa cuiabania est\u00e1 na linguagem, n\u00e3o s\u00f3 no piqui e no pacu seco.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u3c8288adef71e8d244b0c6a15cb68065-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Homem \u00e9 baleado e invade condom\u00ednio para fugir de atiradores em Cuiab\u00e1<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p><strong>RDM online:<\/strong>\u00a0Voc\u00ea j\u00e1 se destacou no audiovisual, premiado nos EUA e \u00cdndia, e ganhou pr\u00eamio de melhor ator em 2022. Como foi essa transi\u00e7\u00e3o?<\/p>\n<p><strong>Eduardo:<\/strong>\u00a0Ainda sofro com isso. Palco e tela s\u00e3o mundos diferentes. Comecei a gravar v\u00eddeos para divulgar shows, e isso virou transm\u00eddia. O teatro \u00e9 ambiente controlado; a internet \u00e9 terra de ningu\u00e9m.<\/p>\n<p>No curta \u201cCeleste\u201d, gravado na pandemia, ganhei meu primeiro pr\u00eamio de ator, em Nova York. Foi uma chancela.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RDM online:<\/strong>\u00a0Ser artista em Mato Grosso ainda \u00e9 dif\u00edcil?<\/p>\n<p><strong>Eduardo:<\/strong>\u00a0Muito. Mato Grosso \u00e9 le\u00e3o para o agro, mas gatinho para a cultura. Somos o maior produtor de gr\u00e3os, mas por que n\u00e3o sermos tamb\u00e9m refer\u00eancia em investimento cultural? Temos capacidade de ter cidade cenogr\u00e1fica, atrair produ\u00e7\u00f5es nacionais. Audiovisual emprega mais que setor t\u00eaxtil e automobil\u00edstico. Cultura gera renda, emprego, autoestima, diminui viol\u00eancia, forma jovens.<\/p>\n<p>Precisamos cuidar da crian\u00e7a antes que chegue ao crime. Cultura e educa\u00e7\u00e3o s\u00e3o o caminho.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RDM online:\u00a0<\/strong>Nas suas apresenta\u00e7\u00f5es, voc\u00ea fala de experi\u00eancias regionais. Como equilibra humor local com o nacional?<\/p>\n<p><strong>Eduardo:<\/strong>\u00a0N\u00e3o separo. O que me toca, eu falo. N\u00e3o caio em temas pol\u00eamicos s\u00f3 porque a internet est\u00e1 falando. Meu processo \u00e9 fluido.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RDM online:<\/strong>\u00a0Voc\u00ea \u00e9 empreendedor, diretor e ator. Qual papel te d\u00e1 mais satisfa\u00e7\u00e3o?<\/p>\n<p><strong>Eduardo:<\/strong>\u00a0Dramaturgo. Gosto de escrever. O teatro concretiza a ideia no palco, mas escrever \u00e9 o que mais me completa.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RDM online:<\/strong>\u00a0Quais projetos voc\u00ea est\u00e1 fomentando hoje?<\/p>\n<p><strong>Eduardo:<\/strong>\u00a0Tenho o projeto \u201cSem Contexto\u201d, selecionado para o Mercado das Ind\u00fastrias Culturais. Vamos produzir v\u00eddeos de humor sob demanda para pequenos neg\u00f3cios, com banco de talentos de atores e roteiristas.<\/p>\n<p>A m\u00e9dio prazo, estou focando no cinema. Com Thiago Mour\u00e3o, estamos buscando financiamento para nosso primeiro longa: \u201cCondom\u00ednio\u201d, sobre um pr\u00e9dio de classe m\u00e9dia cujo cotidiano muda quando um morador de rua acampa na porta. Com humor, discutimos classe, preconceito e a hipocrisia de empurrar problemas para baixo do tapete.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RDM online:<\/strong>\u00a0Qual mensagem voc\u00ea deixa para quem quer ser ator em Mato Grosso?<\/p>\n<p><strong>Eduardo:<\/strong>\u00a0Estudem. Procurem grupos de teatro, procurem diversidade. Arte n\u00e3o \u00e9 homog\u00eanea. Consumam arte, teatro, m\u00fasica, artistas locais. Saiba o que tem no seu bairro, na sua comunidade. \u00c9 por a\u00ed.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_741797\" class=\"wp-caption alignnone\" aria-describedby=\"caption-attachment-741797\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-741797 size-full\" src=\"https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09-1.jpeg\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" srcset=\"https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09-1.jpeg 984w, https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09-1-300x182.jpeg 300w, https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09-1-768x465.jpeg 768w, https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09-1-750x454.jpeg 750w\" alt=\"\" width=\"984\" height=\"596\" \/><figcaption id=\"caption-attachment-741797\" class=\"wp-caption-text\">Foto: Arquivo Pessoal<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_741799\" class=\"wp-caption aligncenter\" aria-describedby=\"caption-attachment-741799\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-741799 size-large\" src=\"https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09-1024x666.jpeg\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" srcset=\"https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09-1024x666.jpeg 1024w, https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09-300x195.jpeg 300w, https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09-768x499.jpeg 768w, https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09-750x488.jpeg 750w, https:\/\/rdmonline.com.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-21-at-17.28.09.jpeg 1080w\" alt=\"\" width=\"800\" height=\"520\" \/><figcaption id=\"caption-attachment-741799\" class=\"wp-caption-text\">Nico e Lau com a personagem Pen\u00e9lope Foto: Arquivo Pessoal<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Eduardo Butakka \u00e9 um daqueles artistas que carregam o palco, os cen\u00e1rios e a rua &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98332,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98331"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98331\/revisions"}],"predecessor-version":[{"id":98333,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98331\/revisions\/98333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98332"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}