{"id":98337,"date":"2025-11-22T11:36:43","date_gmt":"2025-11-22T15:36:43","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98337"},"modified":"2025-11-24T11:38:20","modified_gmt":"2025-11-24T15:38:20","slug":"a-onda-conservadora-que-ameaca-tomar-brasilia","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/a-onda-conservadora-que-ameaca-tomar-brasilia\/","title":{"rendered":"A onda conservadora que amea\u00e7a tomar Bras\u00edlia"},"content":{"rendered":"<p><strong><em>Proje\u00e7\u00e3o indica que o campo conservador teria at\u00e9 38 cadeiras, caso os votos fossem consolidados \u2014 e Bolsonaro promete entrar de cabe\u00e7a na disputa.<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Uma radiografia pol\u00edtica que percorre todos os 26 estados e o Distrito Federal revelou um cen\u00e1rio eletrizante para as elei\u00e7\u00f5es de 2026. Se o pleito fosse hoje, a direita e seus aliados da centro-direita dominariam o Senado Federal com folga, conquistando a maioria das 54 vagas em jogo. O levantamento, baseado em 27 pesquisas recentes de institutos como Real Time Big Data, Paran\u00e1 Pesquisas, Futura Intelig\u00eancia e Verit\u00e1, mostra uma tend\u00eancia clara: o eleitorado brasileiro caminha novamente para um Congresso de perfil conservador.<\/p>\n<p>A an\u00e1lise, amplamente divulgada mergulhou nos n\u00fameros de cada unidade da federa\u00e7\u00e3o e apresentou uma proje\u00e7\u00e3o ousada \u2014 a direita pura, somada \u00e0 centro-direita, poderia chegar a 30 cadeiras, e, com o apoio de Jair Bolsonaro, saltar para 38. Isso configuraria um dom\u00ednio absoluto do Senado, com impacto direto nas vota\u00e7\u00f5es estrat\u00e9gicas da pr\u00f3xima d\u00e9cada.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Norte: Conservadores avan\u00e7am com for\u00e7a<\/strong><\/p>\n<p>Na regi\u00e3o Norte, o dom\u00ednio bolsonarista \u00e9 evidente. No Amap\u00e1, Ra\u00edssa Furlan (Podemos) lidera com 29%, seguida por Randolfe Rodrigues (21%). J\u00e1 em Roraima, a disputa \u00e9 pulverizada, mas os nomes ligados \u00e0 direita \u2014 como Ant\u00f4nio Denarium (PP) e Messias de Jesus (PL) \u2014 aparecem entre os favoritos.<\/p>\n<p>No Acre, o governador Gladson Cameli (PP) abre larga vantagem, com 45,7%, refor\u00e7ando a hegemonia conservadora na regi\u00e3o. Em Tocantins, Vanderlei Barbosa (Republicanos) tamb\u00e9m lidera, enquanto no Par\u00e1 o governador Helder Barbalho (MDB) desponta com 48%, consolidando o campo de centro-esquerda em meio a um oceano de candidaturas de direita.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Nordeste: Equil\u00edbrio tenso e polariza\u00e7\u00e3o acentuada<\/strong><\/p>\n<p>O Nordeste mostra um tabuleiro pol\u00edtico mais dividido. Rui Costa (PT) e Jaques Wagner (PT) mant\u00eam o dom\u00ednio petista na Bahia, com \u00edndices acima dos 40%. No Maranh\u00e3o, Weverton Rocha (PDT) e Roberto Rocha (Republicanos) polarizam a disputa, enquanto no Cear\u00e1 e no Piau\u00ed o embate entre nomes bolsonaristas e lulistas promete ser acirrado at\u00e9 o fim.<\/p>\n<p>Em Alagoas, Renan Calheiros (MDB) segue forte, mas enfrenta concorr\u00eancia de figuras que orbitam entre a direita e o centro, como Alfredo Gaspar (Uni\u00e3o Brasil) e Arthur Lira (PP). Pernambuco e Sergipe, por sua vez, mant\u00eam o tom de indefini\u00e7\u00e3o \u2014 Humberto Costa (PT) e Miguel Coelho (PP) empatam tecnicamente, revelando que a batalha eleitoral nordestina ainda est\u00e1 longe do fim.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"u6f97efab68563efbf967ca835e95c1af-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Show do Guns N\u2019 Roses deve atrair 25 mil turistas e movimentar R$ 400 milh\u00f5es em Cuiab\u00e1<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p><strong>Centro-Oeste: Base bolsonarista consolidada<\/strong><\/p>\n<p>O cora\u00e7\u00e3o pol\u00edtico do bolsonarismo bate forte no Centro-Oeste. No Distrito Federal, Ibaneis Rocha (MDB) aparece \u00e0 frente, seguido de Bia Kicis (PL) \u2014 uma das vozes mais influentes da direita no Congresso.<\/p>\n<p>Em Mato Grosso, Mauro Mendes (Uni\u00e3o Brasil) lidera com folga, enquanto Jana\u00edna Riva (MDB) e Jos\u00e9 Medeiros (PL) figuram entre os mais citados. J\u00e1 no Mato Grosso do Sul, a disputa promete ser uma das mais intensas: Reinaldo Azambuja (PL), Capit\u00e3o Contar (PL) e Nelsinho Trad (PSD) dividem o eleitorado conservador.<\/p>\n<p>Em Goi\u00e1s, o cen\u00e1rio \u00e9 igualmente favor\u00e1vel \u00e0 direita. Gustavo Gayer (PL) desponta com 34,5%, seguido por Gracinha Caiado (Uni\u00e3o Brasil), refor\u00e7ando a for\u00e7a da base bolsonarista no estado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sudeste: Gigantes duelam pelo Senado<\/strong><\/p>\n<p>A regi\u00e3o mais populosa do pa\u00eds apresenta o embate mais emblem\u00e1tico. Em S\u00e3o Paulo, Fernando Haddad (PT) aparece na frente, com 37,8%, seguido de Eduardo Bolsonaro (PL), que registra 32,4%. O duelo entre o ministro petista e o filho do ex-presidente promete ser um dos confrontos mais emblem\u00e1ticos das elei\u00e7\u00f5es de 2026.<\/p>\n<p>No Rio de Janeiro, Fl\u00e1vio Bolsonaro (PL) lidera com 29%, seguido de perto pelo governador Cl\u00e1udio Castro (PL), o que mostra que o cl\u00e3 Bolsonaro ainda mant\u00e9m f\u00f4lego e capilaridade eleitoral. J\u00e1 em Minas Gerais, Mar\u00edlia Campos (PT) e Carlos Viana (Podemos) travam uma disputa apertada, com leve vantagem para o campo progressista.<\/p>\n<p>No Esp\u00edrito Santo, o ex-governador Renato Casagrande (PSB) lidera com 31%, seguido de Paulo Hartung (PSD) \u2014 um nome de centro com boa aceita\u00e7\u00e3o popular.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sul: Reduto consolidado do conservadorismo<\/strong><\/p>\n<p>No Sul, a hegemonia da direita \u00e9 quase absoluta. No Paran\u00e1, Ratinho J\u00fanior (PSD) dispara com 49% das inten\u00e7\u00f5es de voto, e no Rio Grande do Sul, Eduardo Leite (PSD) mant\u00e9m vantagem, mas nomes bolsonaristas como Marcel Van Hattem (Novo) e Marcel Felippe Barros (PL) despontam como alternativas competitivas.<\/p>\n<p>Em Santa Catarina, o cen\u00e1rio chega a ser inusitado: Carlos Bolsonaro (PL) e Caroline de Toni (PL) aparecem na lideran\u00e7a, consolidando o estado como o principal basti\u00e3o do bolsonarismo no pa\u00eds.<\/p>\n<div>\n<div class=\"centered-text-area\">\n<div class=\"centered-text\">\n<div class=\"uac63413743fef9bd203e6e83d2ffeca5-content\"><span class=\"ctaText\">Leia Tamb\u00e9m:<\/span>\u00a0\u00a0<span class=\"postTitle\">Rede de Bancos de Leite Humano registra aumento de 12% no n\u00famero de doadoras em MT<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"ctaButton\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p><strong>A for\u00e7a da direita: Proje\u00e7\u00e3o de dom\u00ednio no Senado<\/strong><\/p>\n<p>Somando os resultados, a pesquisa indica que a direita conquistaria 18 vagas diretamente, enquanto a centro-direita teria 12. O centro pol\u00edtico ficaria com 5, e a esquerda e centro-esquerda somariam 19 cadeiras juntas.<\/p>\n<p>No entanto, ao considerar a possibilidade de uni\u00e3o do campo conservador e apoio direto de Jair Bolsonaro, a proje\u00e7\u00e3o cresce ainda mais: a direita poderia chegar a 38 cadeiras no Senado. Segundo o estudo, bastaria evitar a pulveriza\u00e7\u00e3o dos votos e concentrar o apoio em nomes competitivos.<\/p>\n<p>Entre os destaques da \u201conda conservadora\u201d, aparecem Jos\u00e9 Medeiros (PL-MT), Capit\u00e3o Contar (MS), Rodrigo Valadares (SE) e Marcel Van Hattem (RS). Para os analistas, esses candidatos simbolizam a for\u00e7a de um eleitorado fiel e articulado, que tende a comparecer em peso \u00e0s urnas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Alta rejei\u00e7\u00e3o, mas poder de mobiliza\u00e7\u00e3o<\/strong><\/p>\n<p>O levantamento aponta ainda um dado curioso: embora a direita tenha alta rejei\u00e7\u00e3o (27%), \u00e9 tamb\u00e9m o campo com maior capacidade de mobilizar votos na reta final das campanhas. Em contrapartida, a esquerda apresenta m\u00e9dia de 19% de inten\u00e7\u00e3o de voto inicial e tamb\u00e9m enfrenta forte resist\u00eancia, mas costuma reagir com campanhas mais agressivas e estrat\u00e9gicas.<\/p>\n<p>J\u00e1 os nomes de centro, mesmo partindo de bases menores (15%), carregam o trunfo da baixa rejei\u00e7\u00e3o, podendo surpreender em estados polarizados. \u201cOs candidatos centristas s\u00e3o pragm\u00e1ticos e transitam com facilidade entre os dois polos, o que pode ser decisivo em disputas apertadas\u201d, avaliou a an\u00e1lise.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Conclus\u00e3o: O mapa pol\u00edtico de 2026 j\u00e1 se desenha<\/strong><\/p>\n<p>Se as elei\u00e7\u00f5es fossem hoje, o Brasil assistiria \u00e0 forma\u00e7\u00e3o de um Senado amplamente dominado por vozes conservadoras. A direita, impulsionada pela for\u00e7a simb\u00f3lica do bolsonarismo, tende a crescer e a reconquistar o protagonismo pol\u00edtico perdido ap\u00f3s 2022.<\/p>\n<p>A esquerda, embora enfraquecida em alguns redutos, ainda mant\u00e9m bases s\u00f3lidas no Nordeste e em grandes centros urbanos. Mas, segundo a proje\u00e7\u00e3o, a pr\u00f3xima disputa pelo Senado ser\u00e1 uma das mais ideol\u00f3gicas e polarizadas da hist\u00f3ria recente \u2014 um verdadeiro term\u00f4metro para medir o humor pol\u00edtico do pa\u00eds e antecipar o futuro das for\u00e7as que disputar\u00e3o o Planalto em 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proje\u00e7\u00e3o indica que o campo conservador teria at\u00e9 38 cadeiras, caso os votos fossem consolidados &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98338,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98337"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98337\/revisions"}],"predecessor-version":[{"id":98339,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98337\/revisions\/98339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98338"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}