{"id":98367,"date":"2025-11-24T16:34:03","date_gmt":"2025-11-24T20:34:03","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98367"},"modified":"2025-11-24T16:34:03","modified_gmt":"2025-11-24T20:34:03","slug":"prefeitura-de-cuiaba-realoca-temporariamente-caps-i-do-cpa-iv-para-garantir-continuidade-do-atendimento-em-saude-mental","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeitura-de-cuiaba-realoca-temporariamente-caps-i-do-cpa-iv-para-garantir-continuidade-do-atendimento-em-saude-mental\/","title":{"rendered":"Prefeitura de Cuiab\u00e1 realoca temporariamente CAPS I do CPA IV para garantir continuidade do atendimento em sa\u00fade mental"},"content":{"rendered":"<p>A Secretaria Municipal de Sa\u00fade, por meio da Secretaria-Adjunta de Aten\u00e7\u00e3o Especializada, informa que o Centro de Aten\u00e7\u00e3o Psicossocial \u2013 CAPS I do CPA IV foi temporariamente realocado para assegurar a continuidade dos servi\u00e7os de sa\u00fade mental \u00e0 popula\u00e7\u00e3o da regi\u00e3o Norte de Cuiab\u00e1. A medida excepcional ocorre em raz\u00e3o das condi\u00e7\u00f5es estruturais cr\u00edticas do pr\u00e9dio onde a unidade funcionava, im\u00f3vel pr\u00f3prio que, ao longo dos anos, apresentou graves problemas como rachaduras, infiltra\u00e7\u00f5es e falhas nas redes el\u00e9trica e sanit\u00e1ria.<\/p>\n<p>Os atendimentos passam a ocorrer, de forma excepcional, na USF Jardim Vit\u00f3ria II e na Cl\u00ednica da Fam\u00edlia, no CPA I, ambas dentro do territ\u00f3rio de refer\u00eancia da unidade, garantindo que o cuidado em sa\u00fade mental permane\u00e7a pr\u00f3ximo \u00e0 comunidade atendida.<\/p>\n<p>A decis\u00e3o foi motivada pela necessidade urgente de garantir seguran\u00e7a a usu\u00e1rios e trabalhadores, j\u00e1 que as falhas estruturais comprometiam n\u00e3o apenas o funcionamento adequado do servi\u00e7o, mas representavam risco f\u00edsico aos frequentadores. Al\u00e9m disso, limita\u00e7\u00f5es como a aus\u00eancia de salas climatizadas e espa\u00e7os inadequados para atividades coletivas restringiam a oferta plena dos servi\u00e7os previstos para um CAPS tipo I.<\/p>\n<p>Em 2017, o Minist\u00e9rio P\u00fablico do Estado de Mato Grosso ajuizou A\u00e7\u00e3o Civil P\u00fablica solicitando a reforma completa do im\u00f3vel, com regulariza\u00e7\u00e3o estrutural, sanit\u00e1ria e el\u00e9trica. A interven\u00e7\u00e3o, contudo, n\u00e3o foi executada \u00e0 \u00e9poca, resultando em um passivo que se agravou ao longo do tempo.<\/p>\n<p>Nos \u00faltimos meses, a gest\u00e3o municipal intensificou a busca por alternativas, articulando parcerias com as secretarias de Esporte, Lazer, Cultura, Educa\u00e7\u00e3o e tamb\u00e9m com lideran\u00e7as comunit\u00e1rias, a fim de localizar um im\u00f3vel que atendesse \u00e0s exig\u00eancias t\u00e9cnicas de um CAPS. Contudo, n\u00e3o houve disponibilidade de espa\u00e7o adequado.<\/p>\n<p>Somado a isso, o prazo para utiliza\u00e7\u00e3o dos recursos destinados \u00e0 reforma,\u00a0cuja perda acarretaria preju\u00edzo direto e permanente ao servi\u00e7o, refor\u00e7ou a necessidade da realoca\u00e7\u00e3o imediata da equipe.<\/p>\n<p>A Secretaria Municipal de Sa\u00fade informa que a previs\u00e3o de conclus\u00e3o da reforma \u00e9 de 45 dias, per\u00edodo em que os atendimentos permanecer\u00e3o nas unidades provis\u00f3rias.<\/p>\n<p>A transfer\u00eancia tempor\u00e1ria permite que a obra seja executada com seguran\u00e7a e a unidade possa retornar futuramente ao seu endere\u00e7o original com estrutura segura, modernizada e adequada \u00e0s necessidades da popula\u00e7\u00e3o.<\/p>\n<p>O CAPS I \u00e9 destinado ao atendimento de pessoas adultas com transtornos mentais graves e persistentes, oferecendo acolhimento, terapias individuais e em grupo, busca ativa, visitas domiciliares, atividades terap\u00eauticas e l\u00fadicas, al\u00e9m de suporte \u00e0s fam\u00edlias. A Secretaria Municipal de Sa\u00fade refor\u00e7a que nenhum atendimento ser\u00e1 interrompido durante o per\u00edodo de reforma.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 Foto:\u00a0 Erlan Aquino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal de Sa\u00fade, por meio da Secretaria-Adjunta de Aten\u00e7\u00e3o Especializada, informa que o &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98368,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98367"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98367\/revisions"}],"predecessor-version":[{"id":98369,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98367\/revisions\/98369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98368"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}