{"id":98464,"date":"2025-11-27T14:40:55","date_gmt":"2025-11-27T18:40:55","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98464"},"modified":"2025-11-27T14:40:55","modified_gmt":"2025-11-27T18:40:55","slug":"pesquisadora-desenvolve-linha-de-cosmeticos-e-investe-em-marketing-para-divulgar-empreendimento-com-apoio-da-desenvolve-mt","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/pesquisadora-desenvolve-linha-de-cosmeticos-e-investe-em-marketing-para-divulgar-empreendimento-com-apoio-da-desenvolve-mt\/","title":{"rendered":"Pesquisadora desenvolve linha de cosm\u00e9ticos e investe em marketing para divulgar empreendimento com apoio da Desenvolve MT"},"content":{"rendered":"<p>A carreira acad\u00eamica sempre foi um espa\u00e7o familiar para Wanessa Faria, que dedicou anos \u00e0 pesquisa e \u00e0 cosmetologia. Mas, diante das limita\u00e7\u00f5es do mercado cient\u00edfico no Estado, ela decidiu transformar esse conhecimento acumulado em pr\u00e1tica: empreender na \u00e1rea que, desde cedo, alimentava sua curiosidade e encantamento.<\/p>\n<p>A farmac\u00eautica e cirurgi\u00e3-dentista teve a primeira forma\u00e7\u00e3o em 2011, da gradua\u00e7\u00e3o ao p\u00f3s doutorado e de volta \u00e0s salas de universidade, mas dessa vez como professora, ela construiu uma carreira s\u00f3lida e a est\u00e9tica sempre esteve presente. Mas foi durante o p\u00f3s-doutorado que surgiu o produto que daria nome ao pr\u00f3prio empreendimento.<\/p>\n<p>Desenvolvida a partir de uma pesquisa cient\u00edfica, que resultou em uma patente pr\u00f3pria, a linha Tugani utiliza micropart\u00edculas de extratos de caf\u00e9 verde, ativo com poder antioxidante superior ao da vitamina C. Vegana e clean label, ou seja, formulada com ingredientes mais limpos e transparentes, a cole\u00e7\u00e3o re\u00fane sabonete facial, \u00e1gua micelar, gel creme e roll-on para a \u00e1rea dos olhos. Pensados para o uso diurno, os produtos potencializam a a\u00e7\u00e3o do protetor solar e ajudam a reduzir os danos causados pela radia\u00e7\u00e3o e pela polui\u00e7\u00e3o.<\/p>\n<picture data-fileentryid=\"75815524\"><source srcset=\"\/o\/adaptive-media\/image\/75815524\/Thumbnail-1024x1024\/Meio+Case+Instituto+Tugani.jpeg?t=1764254762370\" media=\"(max-width:1024px)\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/mt\/meio-case-instituto-tugani?imageThumbnail=3\" alt=\"\" width=\"1084\" height=\"813\" \/><\/picture>\nEm 2017, com a portaria que permitia a profiss\u00e3o de farmac\u00eautico atuar na \u00e1rea de injet\u00e1veis na est\u00e9tica, Wanessa deu in\u00edcio \u00e0 2\u00b0 gradua\u00e7\u00e3o em odontologia. \u201cSou farmac\u00eautica e tenho muito orgulho da minha forma\u00e7\u00e3o, mas meu sonho de inf\u00e2ncia sempre foi ser dentista. A odontologia me abriu a oportunidade de aprofundar o estudo da anatomia facial e ampliar meus conhecimentos em est\u00e9tica, al\u00e9m de atuar diretamente na sa\u00fade bucal. Porque, antes de tudo, est\u00e9tica tamb\u00e9m \u00e9 sa\u00fade.\u201d, afirma.<\/p>\n<p>O neg\u00f3cio come\u00e7ou com um CNPJ que carregava o nome da pr\u00f3pria empreendedora. Em 2025, j\u00e1 com a odontologia incorporada aos atendimentos e uma proposta mais ampla, Wanessa transformou a marca em Instituto Tugani. O nome, que nasceu com a linha de cosm\u00e9ticos, vem de um acr\u00f4nimo de tr\u00eas palavras: tu de natural, gan de vegano e ni de org\u00e2nico. Al\u00e9m dos produtos, a cl\u00ednica oferece atendimentos odontol\u00f3gicos, desde est\u00e9tica a implantes, harmoniza\u00e7\u00e3o facial e corporal, spa, terapia corporal, est\u00e9tica facial e terapias combinadas.<\/p>\n<p>Com a cl\u00ednica inaugurada, Wanessa decidiu que era o momento de investir na marca e faz\u00ea-la crescer. Foi assim que, depois de conhecer a Desenvolve MT atrav\u00e9s das redes sociais, ela solicitou o cr\u00e9dito atrav\u00e9s da linha Mulher Empreendedora. Wanessa investiu parte em capital de giro e o restante foi investido em marketing para a linha de cosm\u00e9ticos.<\/p>\n<p>Para a empres\u00e1ria, uma boa comunica\u00e7\u00e3o com o p\u00fablico \u00e9 fundamental para o crescimento e fortalecimento do neg\u00f3cio como marca. \u201cCom o cr\u00e9dito, conseguimos melhorar nossa comunica\u00e7\u00e3o sobre os servi\u00e7os e produtos da cl\u00ednica. Criamos um site com o recurso e tamb\u00e9m organizamos nosso Instagram para divulgar melhor o que oferecemos.\u201d, ressaltou.<\/p>\n<p>Para Wanessa, empreender tamb\u00e9m significa aprender continuamente e buscar apoio para tomar decis\u00f5es mais seguras. Ela refor\u00e7a que muitas mulheres come\u00e7am um neg\u00f3cio \u201cna coragem\u201d, assim como ela fez no in\u00edcio, mas acabam enfrentando desafios que poderiam ser amenizados com orienta\u00e7\u00e3o adequada. \u201cEu mesma comecei me aventurando, sem tanta orienta\u00e7\u00e3o, e acabei passando por muitas dificuldades. Por isso, para quem est\u00e1 come\u00e7ando, \u00e9 fundamental buscar ajuda, adquirir conhecimento e se preparar. Resili\u00eancia, informa\u00e7\u00e3o e um sonho bem estruturado fazem toda a diferen\u00e7a\u201d, afirma.<\/p>\n<p><em>*Com supervis\u00e3o de Livia Rabani.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Paula Luna | Desenvolve MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A carreira acad\u00eamica sempre foi um espa\u00e7o familiar para Wanessa Faria, que dedicou anos \u00e0 &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98465,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Cosm\u00e9ticos veganos e comunica\u00e7\u00e3o profissional fortalecem a marca criada pela pesquisadora mato-grossense.","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98464"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98464\/revisions"}],"predecessor-version":[{"id":98466,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98464\/revisions\/98466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98465"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}