{"id":98527,"date":"2025-12-01T10:08:00","date_gmt":"2025-12-01T14:08:00","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98527"},"modified":"2025-12-01T10:08:00","modified_gmt":"2025-12-01T14:08:00","slug":"tutores-do-muxirum-digital-destacam-resultados-e-o-papel-transformador-da-aprendizagem","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/tutores-do-muxirum-digital-destacam-resultados-e-o-papel-transformador-da-aprendizagem\/","title":{"rendered":"Tutores do Muxirum Digital destacam resultados e o papel transformador da aprendizagem"},"content":{"rendered":"<p dir=\"ltr\">Bolsistas participantes do Projeto Muxirum Digital destacaram como o desenvolvimento das atividades durante as aulas foi transformador tanto para os idosos atendidos quanto para os tutores. Com in\u00edcio em junho de 2025, o projeto, realizado pela Secretaria de Estado de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (Seciteci), atendeu cerca de 180 pessoas e se prepara para a cerim\u00f4nia de formatura de todos os alunos.<\/p>\n<p dir=\"ltr\">Para a execu\u00e7\u00e3o do Projeto, a Seciteci, em parceria com a Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa de Mato Grosso (Fapemat), selecionou e capacitou 21 bolsistas para oferecerem letramento digital a idosos e pessoas em situa\u00e7\u00e3o de vulnerabilidade social. Como \u00e9 o caso da tutora Hozana Gon\u00e7alves, que coordenou as aulas do projeto no munic\u00edpio de Santo Ant\u00f4nio do Leverger e agora evidencia o resultado positivo da iniciativa.<\/p>\n<p dir=\"ltr\">\u201cAqui em Santo Ant\u00f4nio foram 4 meses intensos e finalizamos com o aproveitamento 100%. N\u00f3s ensinamos para as pessoas sobre o meio digital e aprendemos com elas tamb\u00e9m. A quest\u00e3o do celular foi o nosso foco, mas o ambiente de aprendizado oportuniza muitas trocas\u201d, destacou.<\/p>\n<p dir=\"ltr\">Hozana ainda explica que foi poss\u00edvel atender duas turmas, ampliando o alcance do projeto. \u201cPor aqui conseguimos abrir duas turmas que tiveram um excelente aproveitamento. Como a maioria dos estudantes eram da zona rural, conseguimos uma parceria com o \u00f4nibus escolar que trazia os alunos para a escola, o que aumentou o comprometimento de todos\u201d, completou ela.<\/p>\n<p dir=\"ltr\">Para o outro tutor que atuou no munic\u00edpio, Gon\u00e7alo Lima, o projeto Muxirum Digital \u00e9 um bom exemplo de valoriza\u00e7\u00e3o da cidade e tende a se consolidar no munic\u00edpio.<\/p>\n<p dir=\"ltr\">\u201cFoi uma experi\u00eancia gratificante. Na minha turma, especificamente, foi um pouquinho mais diferente, tivemos tr\u00eas gera\u00e7\u00f5es, jovens, adultos e idosos Mas todos conectados com a vontade de aprender. A gente percebeu nos encontros como eles se orgulhavam de terem sido escolhidos para receber o projeto, relatou o professor.<\/p>\n<p dir=\"ltr\"><picture data-fileentryid=\"75832978\"><source srcset=\"\/o\/adaptive-media\/image\/75832978\/Thumbnail-1024x1024\/63beeded-f0c8-434c-b19c-6535bc491331.jpg?t=1764364129659\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secitec.mt.gov.br\/documents\/d\/secitec\/63beeded-f0c8-434c-b19c-6535bc491331-jpg?imageThumbnail=3\" alt=\"\" height=\"267\" \/><\/picture>\nEm Cuiab\u00e1, na regi\u00e3o do CPA III, a tutora Regiane Borges tamb\u00e9m comemorou o sucesso do projeto. \u201cTivemos uma turma cheia do in\u00edcio ao fim das aulas, todas mulheres, curiosas para aprenderem e terem autonomia. Um sentimento que tamb\u00e9m nos motivava, porque trabalhar com idosos \u00e9 uma troca, ensinar, mas tamb\u00e9m aprender\u201d, ressaltou.<\/p>\n<p dir=\"ltr\">Ainda segundo Regiane, ao final do curso, algumas idosas a procuraram para contar que haviam comprado um novo aparelho. \u201c\u00c9 muito gratificante ouvir das alunas que eles compraram um celular novo, porque o antigo n\u00e3o possu\u00eda as fun\u00e7\u00f5es que elas aprenderam aqui. S\u00e3o pessoas que tinham medo de utilizar o celular e agora procuram por um mais moderno\u201d, enfatizou Regiane.<\/p>\n<p dir=\"ltr\">No encerramento do polo no CPA III, o presidente do bairro, Lucas Mota, agradeceu ao Governo do Estado pela realiza\u00e7\u00e3o do projeto na regi\u00e3o. \u201cPara mim, que escuto diariamente as demandas das pessoas aqui do bairro, \u00e9 a maior satisfa\u00e7\u00e3o ver a alegria no olhar dos idosos e ver a Seciteci trazendo esse tipo de trabalho para dentro da nossa comunidade, \u00e9 gratificante\u201d, frisou a lideran\u00e7a.<\/p>\n<p dir=\"ltr\"><strong>Muxirum Digital<\/strong><\/p>\n<p dir=\"ltr\">Com investimento de R$ 390 mil da Funda\u00e7\u00e3o de Amparo \u00e0 Pesquisa de Mato Grosso (Fapemat), o Muxirum digital \u00e9 uma iniciativa da Seciteci, semelhante ao Mais MT Muxirum + Alfabetiza\u00e7\u00e3o, comandado pela Secretaria de Estado de Educa\u00e7\u00e3o (Seduc), para alfabetizar adolescentes e adultos que n\u00e3o aprenderam na idade certa.<\/p>\n<p dir=\"ltr\">A fase piloto do projeto foi realizada nos munic\u00edpios de Cuiab\u00e1, V\u00e1rzea Grande e Santo Ant\u00f4nio de Leverger, onde ocorreram aulas semanais e acompanhamento cont\u00ednuo dos participantes.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">\n<p dir=\"ltr\">MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 \u00a0Ascom Seciteci<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bolsistas participantes do Projeto Muxirum Digital destacaram como o desenvolvimento das atividades durante as aulas &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98528,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"A fase de realiza\u00e7\u00e3o das aulas foi conclu\u00edda em todos os munic\u00edpios atendidos pelo projeto","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98527"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98527\/revisions"}],"predecessor-version":[{"id":98529,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98527\/revisions\/98529"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98528"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}