{"id":98686,"date":"2025-12-05T10:24:33","date_gmt":"2025-12-05T14:24:33","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98686"},"modified":"2025-12-05T10:24:33","modified_gmt":"2025-12-05T14:24:33","slug":"estudantes-vivem-dia-de-imersao-cultural-ambiental-e-historica-no-complexo-cultural-do-porto","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/estudantes-vivem-dia-de-imersao-cultural-ambiental-e-historica-no-complexo-cultural-do-porto\/","title":{"rendered":"Estudantes vivem dia de imers\u00e3o cultural, ambiental e hist\u00f3rica no Complexo Cultural do Porto"},"content":{"rendered":"<p>Na tarde de quarta-feira (3), 120 estudantes da Escola Municipal Jos\u00e9 Leite de Morais embarcaram em uma jornada de aprendizado no Complexo Cultural do Porto. O passeio, que englobou o Aqu\u00e1rio Municipal, o Mercado do Porto, a Orla e o Cais, foi parte de uma iniciativa educacional que integra a teoria aprendida em sala de aula com experi\u00eancias pr\u00e1ticas, promovendo uma viv\u00eancia cultural, hist\u00f3rica e ambiental \u00fanica para os jovens cuiabanos.<\/p>\n<p><strong>O objetivo da visita<\/strong><\/p>\n<p>O foco da visita foi proporcionar aos estudantes uma imers\u00e3o em diversos aspectos da cultura, hist\u00f3ria e biodiversidade de Cuiab\u00e1. O Complexo Cultural do Porto, que integra espa\u00e7os como o Aqu\u00e1rio Municipal e o Mercado do Porto, tem se consolidado como um ponto de aprendizado interdisciplinar, onde os alunos podem vivenciar os conte\u00fados abordados nas aulas de uma forma pr\u00e1tica e envolvente.<\/p>\n<p>De acordo com a coordenadora do Complexo Cultural do Porto, Luana da Cruz Burema, a visita foi pensada de maneira estrat\u00e9gica para envolver os estudantes em um circuito educativo. &#8220;Dividimos os alunos em quatro grupos para que cada um tenha uma experi\u00eancia completa, passando pelo Cais do Porto, o Mercado, o Aqu\u00e1rio e a Orla. Cada um desses espa\u00e7os oferece um aprendizado \u00fanico, que complementa o que os alunos estudam na escola&#8221;, explicou Luana.<\/p>\n<p><strong>A Educa\u00e7\u00e3o Ambiental e a Biodiversidade<\/strong><\/p>\n<p>Uma das paradas mais aguardadas pelos estudantes foi o Aqu\u00e1rio Municipal, onde tiveram a oportunidade de conhecer de perto a fauna aqu\u00e1tica do Pantanal, da Amaz\u00f4nia e do Cerrado. O aqu\u00e1rio, que tem como foco a educa\u00e7\u00e3o ambiental, apresentou aos alunos esp\u00e9cies como o dourado e o tambaqui, entre outras, despertando a curiosidade sobre a preserva\u00e7\u00e3o ambiental.<\/p>\n<p>Luana ressaltou o papel do Aqu\u00e1rio no trabalho de educa\u00e7\u00e3o ambiental. &#8220;Estamos estruturando a parte pedag\u00f3gica do aqu\u00e1rio para que ele seja um espa\u00e7o de conscientiza\u00e7\u00e3o sobre a biodiversidade do nosso estado. Queremos que os alunos saiam daqui com uma maior compreens\u00e3o da import\u00e2ncia de preservar os nossos ecossistemas&#8221;, disse ela.<\/p>\n<p><strong>Educa\u00e7\u00e3o econ\u00f4mica na pr\u00e1tica<\/strong><\/p>\n<p>Outro momento importante da visita foi a explora\u00e7\u00e3o do Mercado do Porto. Os alunos realizaram pesquisas de pre\u00e7os e compara\u00e7\u00f5es com os mercados que frequentam com suas fam\u00edlias, permitindo um aprendizado pr\u00e1tico sobre economia e consumo. Mariana Kelly Campos de Paula, estudante do 6\u00ba ano, ficou impressionada com a variedade e os pre\u00e7os. &#8220;Achei os pre\u00e7os muito bons, a variedade de produtos tamb\u00e9m. Com certeza voltaria aqui&#8221;, comentou.<\/p>\n<p>Esse tipo de atividade tamb\u00e9m tem o objetivo de integrar os conte\u00fados curriculares de disciplinas como Matem\u00e1tica e L\u00edngua Portuguesa, conectando a teoria e a pr\u00e1tica de forma divertida e educativa. &#8220;N\u00e3o \u00e9 uma simples visita. As professoras trabalham com os alunos conceitos de mercado, pre\u00e7os e economia, levando o aprendizado para al\u00e9m da sala de aula&#8221;, afirmou Andreia Freitas, professora de Artes e uma das respons\u00e1veis pela organiza\u00e7\u00e3o do projeto.<\/p>\n<p>Al\u00e9m da parte ambiental e econ\u00f4mica, a visita ao Complexo Cultural do Porto tamb\u00e9m explorou a hist\u00f3ria de Cuiab\u00e1. O Cais do Porto, um dos locais mais emblem\u00e1ticos da cidade, foi apresentado aos estudantes como um ponto chave na forma\u00e7\u00e3o do munic\u00edpio. A professora C\u00e9lia Moura, diretora do complexo, destacou a import\u00e2ncia de integrar esses conhecimentos \u00e0 realidade cotidiana dos alunos. &#8220;Nosso objetivo \u00e9 proporcionar uma viv\u00eancia cultural rica e que os alunos se sintam parte dessa hist\u00f3ria&#8221;, explicou.<\/p>\n<p>Os alunos mostraram-se entusiasmados com a visita e a oportunidade de vivenciar o que estudam na teoria. Ana Vict\u00f3ria Santos Unger, do 6\u00ba ano, foi uma das que mais se impressionaram. &#8220;O que mais me chamou aten\u00e7\u00e3o foi a estrutura do local. Eu nunca imaginei que aqui seria t\u00e3o grande e bonito. O aqu\u00e1rio, especialmente, foi incr\u00edvel&#8221;, comentou.<\/p>\n<p>Outros alunos, como Ana J\u00falia Nunes de Arruda, ficaram encantados com o aprendizado pr\u00e1tico. &#8220;\u00c9 muito bom porque a gente v\u00ea tudo o que aprendemos na escola de uma maneira mais real. L\u00e1 na sala de aula a gente estuda, mas aqui a gente v\u00ea tudo de perto&#8221;, afirmou.<\/p>\n<p><strong>O papel do Complexo Cultural do Porto no desenvolvimento de Cuiab\u00e1<\/strong><\/p>\n<p>O Complexo Cultural do Porto n\u00e3o \u00e9 apenas um centro de visita\u00e7\u00e3o, mas tamb\u00e9m um espa\u00e7o de integra\u00e7\u00e3o entre as diversas \u00e1reas da gest\u00e3o p\u00fablica, como Educa\u00e7\u00e3o, Turismo, Agricultura e Meio Ambiente. Para o secret\u00e1rio municipal de Desenvolvimento Econ\u00f4mico, Trabalho, Turismo e Agricultura, Fernando Medeiros, o Complexo Cultural do Porto tem um papel fundamental no enriquecimento educacional dos estudantes e na promo\u00e7\u00e3o do turismo local.<\/p>\n<p>&#8220;O Aqu\u00e1rio e o Complexo do Museu do Rio oferecem uma experi\u00eancia que vai al\u00e9m do turismo tradicional. Eles funcionam como um espa\u00e7o biocultural, essencial para a educa\u00e7\u00e3o dos nossos jovens. Ao conectar a fauna local, a hist\u00f3ria e o mercado, conseguimos criar uma viv\u00eancia completa que une aprendizado e divers\u00e3o&#8221;, disse o secret\u00e1rio.<\/p>\n<p>A seguran\u00e7a dos estudantes tamb\u00e9m foi uma prioridade durante a visita. Para garantir que todos os alunos estivessem bem acompanhados, cada grupo de 25 estudantes contou com a presen\u00e7a de 6 a 7 monitores. Al\u00e9m disso, a seguran\u00e7a foi refor\u00e7ada com a presen\u00e7a de vigilantes patrimoniais e da For\u00e7a Policial, especialmente durante a travessia at\u00e9 a Feira do Porto.<\/p>\n<p><strong>A visita\u00e7\u00e3o como um modelo de Educa\u00e7\u00e3o e Turismo<\/strong><\/p>\n<p>O Complexo Cultural do Porto tem se consolidado como um modelo de integra\u00e7\u00e3o entre educa\u00e7\u00e3o e turismo, oferecendo um espa\u00e7o \u00fanico para a comunidade cuiabana e os turistas. A Diretora C\u00e9lia Moura convidou a popula\u00e7\u00e3o para que continue a prestigiar o local. &#8220;Estamos preparando uma programa\u00e7\u00e3o especial para as f\u00e9rias, e esperamos que mais fam\u00edlias e estudantes venham conhecer o Complexo. O nosso objetivo \u00e9 que todos saiam enriquecidos com o conhecimento que oferecemos&#8221;, concluiu.<\/p>\n<p>A visita dos alunos da EMB Jos\u00e9 Leite de Morais ao Complexo Cultural do Porto foi uma experi\u00eancia educativa e cultural que transcendeu as barreiras da sala de aula. Integrando hist\u00f3ria, biologia, economia e cultura, a iniciativa reflete a import\u00e2ncia de espa\u00e7os p\u00fablicos que incentivam o aprendizado e a intera\u00e7\u00e3o com a comunidade. Ao promover atividades como essa, Cuiab\u00e1 fortalece sua identidade e cria oportunidades para que os jovens se conectem com sua hist\u00f3ria e com os recursos naturais que tornam a cidade \u00fanica.<\/p>\n<p>Com um trabalho cont\u00ednuo de integra\u00e7\u00e3o entre as \u00e1reas de educa\u00e7\u00e3o, turismo e meio ambiente, o Complexo Cultural do Porto segue sendo um exemplo de como a educa\u00e7\u00e3o pode ser mais do que um conte\u00fado te\u00f3rico, ela pode ser vivida e sentida em cada canto da cidade.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Erlan Aquino<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na tarde de quarta-feira (3), 120 estudantes da Escola Municipal Jos\u00e9 Leite de Morais embarcaram &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98687,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98686"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98686\/revisions"}],"predecessor-version":[{"id":98688,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98686\/revisions\/98688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98687"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}