{"id":98689,"date":"2025-12-05T10:31:49","date_gmt":"2025-12-05T14:31:49","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98689"},"modified":"2025-12-05T10:31:49","modified_gmt":"2025-12-05T14:31:49","slug":"prefeito-e-primeira-dama-participam-destacam-parceria-para-autistas","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeito-e-primeira-dama-participam-destacam-parceria-para-autistas\/","title":{"rendered":"Prefeito e primeira-dama participam destacam parceria para autistas"},"content":{"rendered":"<p data-end=\"545\" data-start=\"89\">O prefeito de Cuiab\u00e1, Abilio Brunini, e sua esposa e vereadora, Samantha Iris, participaram na manh\u00e3 desta sexta-feira (5) da abertura da 6\u00aa edi\u00e7\u00e3o do TJMT Inclusivo \u2013 Capacita\u00e7\u00e3o e Conscientiza\u00e7\u00e3o em Autismo, realizada pelo Tribunal de Justi\u00e7a de Mato Grosso. O evento re\u00fane magistrados, servidores, profissionais da educa\u00e7\u00e3o e sa\u00fade, lideran\u00e7as da comunidade e fam\u00edlias para discutir pr\u00e1ticas inclusivas e qualifica\u00e7\u00e3o no atendimento \u00e0s pessoas autistas.<\/p>\n<p data-end=\"1190\" data-start=\"547\">Ao abrir sua fala de forma leve e descontra\u00edda, o prefeito destacou a import\u00e2ncia da capacita\u00e7\u00e3o cont\u00ednua e da responsabilidade com as crian\u00e7as autistas. \u201cAprender n\u00e3o precisa ser chato. \u00c9 necess\u00e1rio, e quando fazemos isso com responsabilidade, conseguimos transformar realidades. Autismo n\u00e3o \u00e9 brincadeira, nem r\u00f3tulo. \u00c9 compromisso. A qualifica\u00e7\u00e3o muda tudo\u201d, afirmou. Brunini refor\u00e7ou ainda que o trabalho das auxiliares de sala precisa ser valorizado. \u201cQuero que voc\u00eas sejam reconhecidas como auxiliares de desempenho e aprendizado. Estudem, se especializem. Voc\u00eas permanecem na ponta e fazem diferen\u00e7a na vida dessas crian\u00e7as\u201d, completou.<\/p>\n<p data-end=\"1641\" data-start=\"1192\">A primeira-dama tamb\u00e9m destacou que o evento alcan\u00e7a muitas fam\u00edlias e \u00e9 uma oportunidade de inclus\u00e3o real. \u201cEssa parceria \u00e9 essencial, assim a gente consegue alcan\u00e7ar cada vez mais fam\u00edlias e, nesse caso aqui, n\u00f3s estamos alcan\u00e7ando tamb\u00e9m as cuidadoras dos alunos da nossa rede municipal. Ent\u00e3o, \u00e9 importante que a gente tenha momentos como este de capacita\u00e7\u00e3o, de conscientiza\u00e7\u00e3o, para poder colaborar com a sociedade em geral\u201d, emendou Samantha.<\/p>\n<p data-end=\"2147\" data-start=\"1643\">O presidente do TJMT, desembargador Jos\u00e9 Zuquim Nogueira, tamb\u00e9m destacou o car\u00e1ter humano e transformador da iniciativa. \u201cEste n\u00e3o \u00e9 um evento em que o Judici\u00e1rio fala sozinho. \u00c9 um momento em que o Judici\u00e1rio escuta, aprende e se transforma a partir da experi\u00eancia de quem vive o autismo no cotidiano. N\u00e3o tratamos de conceitos abstratos, mas de vidas reais. A voc\u00eas, afirmamos: n\u00e3o est\u00e3o sozinhos\u201d, disse Zuquim, ressaltando que o tribunal busca pr\u00e1ticas inclusivas e atendimento sens\u00edvel \u00e0s fam\u00edlias.<\/p>\n<p data-end=\"2722\" data-start=\"2149\">A vice-presidente do TJMT e presidente da Comiss\u00e3o de Acessibilidade e Inclus\u00e3o, desembargadora Nilza Maria P\u00f4ssas de Carvalho, declarou oficialmente aberta a capacita\u00e7\u00e3o, refor\u00e7ando o compromisso institucional com a causa. \u201cO autismo n\u00e3o \u00e9 limita\u00e7\u00e3o, mas uma forma singular de estar no mundo. Este encontro \u00e9 fundamental para derrubar estigmas, difundir direitos e promover acolhimento. Aqui, ampliamos conhecimento para tomar decis\u00f5es mais humanas e respons\u00e1veis\u201d, afirmou. Nilza agradeceu a parceria do munic\u00edpio e destacou o envolvimento da primeira-dama Samantha Iris.<\/p>\n<p data-end=\"2933\" data-is-last-node=\"\" data-is-only-node=\"\" data-start=\"2724\">O evento segue ao longo de todo o dia com especialistas de diversas \u00e1reas, abordando inclus\u00e3o escolar, desafios familiares, pr\u00e1ticas inclusivas, diagn\u00f3stico diferencial e invisibilidade do autismo em mulheres.<\/p>\n<p data-end=\"2933\" data-is-last-node=\"\" data-is-only-node=\"\" data-start=\"2724\">\n<p data-end=\"2933\" data-is-last-node=\"\" data-is-only-node=\"\" data-start=\"2724\">\n<p data-end=\"2933\" data-is-last-node=\"\" data-is-only-node=\"\" data-start=\"2724\">Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Emanoele Daiane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Cuiab\u00e1, Abilio Brunini, e sua esposa e vereadora, Samantha Iris, participaram na &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98690,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-98689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98689"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98689\/revisions"}],"predecessor-version":[{"id":98691,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98689\/revisions\/98691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98690"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}