{"id":98692,"date":"2025-12-05T10:33:58","date_gmt":"2025-12-05T14:33:58","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98692"},"modified":"2025-12-05T10:33:58","modified_gmt":"2025-12-05T14:33:58","slug":"confira-o-que-abre-e-fecha-em-cuiaba-no-feriado-de-nossa-senhora-da-imaculada-conceicao","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/confira-o-que-abre-e-fecha-em-cuiaba-no-feriado-de-nossa-senhora-da-imaculada-conceicao\/","title":{"rendered":"Confira o que abre e fecha em Cuiab\u00e1 no feriado de Nossa Senhora da Imaculada Concei\u00e7\u00e3o"},"content":{"rendered":"<p>Exceto no caso de atividades consideradas essenciais, os \u00f3rg\u00e3os p\u00fablicos vinculados \u00e0 Prefeitura de Cuiab\u00e1 n\u00e3o ter\u00e3o expediente no feriado municipal desta segunda-feira (8), que evidencia a devo\u00e7\u00e3o religiosa em celebra\u00e7\u00e3o a Nossa Senhora da Imaculada Concei\u00e7\u00e3o.<\/p>\n<p>Os atendimentos nas UPAs (Unidades de Pronto Atendimento) e nas Policl\u00ednicas est\u00e3o mantidos, exceto nos postos de sa\u00fade. Tamb\u00e9m ser\u00e3o mantidas as atividades da Defesa Civil, bem como a fiscaliza\u00e7\u00e3o e a orienta\u00e7\u00e3o do tr\u00e2nsito.<\/p>\n<p>O com\u00e9rcio, tanto as lojas de rua quanto as de shoppings, poder\u00e1 funcionar normalmente, de acordo com os entendimentos estabelecidos entre os sindicatos do setor patronal e laboral. A abertura das lojas \u00e9 opcional, mas, para aquelas que decidirem abrir, \u00e9 fundamental seguir as regras de remunera\u00e7\u00e3o previstas na Conven\u00e7\u00e3o Coletiva de Trabalho (CCT), que determina pagamento em dobro pelas horas trabalhadas no feriado, incluindo as comiss\u00f5es de vendas.<\/p>\n<p>As institui\u00e7\u00f5es banc\u00e1rias e os \u00f3rg\u00e3os estaduais tamb\u00e9m n\u00e3o ter\u00e3o expediente no feriado.<\/p>\n<p>O expediente ser\u00e1 retomado normalmente na ter\u00e7a-feira (9), a partir das 8h.<\/p>\n<p><strong>Espa\u00e7os tur\u00edsticos e de lazer<\/strong><\/p>\n<p>O Mercado Ant\u00f4nio Mois\u00e9s Nadaf, conhecido como Mercado do Porto, funcionar\u00e1 at\u00e9 as 13h no feriado. A partir de ter\u00e7a-feira (9), o espa\u00e7o seguir\u00e1 com atendimento normal das 7h \u00e0s 18h, inclusive aos s\u00e1bados e domingos.<\/p>\n<p>J\u00e1 os atrativos tur\u00edsticos localizados na Orla do Porto, como o Museu do Rio e o Aqu\u00e1rio Municipal, n\u00e3o funcionar\u00e3o no feriado desta segunda-feira (8). O Aqu\u00e1rio Municipal Justino Malheiros \u00e9 normalmente fechado \u00e0s segundas-feiras para manuten\u00e7\u00e3o, mas, de ter\u00e7a a domingo, funciona das 9h \u00e0s 18h, com entrada gratuita.<\/p>\n<p>O Museu da Imagem e do Som L\u00e1zaro Papazian (MISC) e o Museu do Morro da Caixa D\u2019\u00c1gua Velha tamb\u00e9m n\u00e3o funcionar\u00e3o. A partir de ter\u00e7a-feira (9), o Museu do Morro da Caixa D\u2019\u00c1gua Velha estar\u00e1 aberto das 8h \u00e0s 12h e das 13h \u00e0s 17h, com fechamento de uma hora para almo\u00e7o.<\/p>\n<p><strong>Parques Municipais<\/strong><\/p>\n<p>O Parque Tia Nair, localizado na Avenida \u00c9rico Preza, no bairro Jardim It\u00e1lia, oferece op\u00e7\u00f5es gratuitas de lazer, como pista de caminhada e mirante com vista para o lago. O parque permanece aberto das 5h \u00e0s 22h, todos os dias da semana.<\/p>\n<p>J\u00e1 o Parque das \u00c1guas, considerado um dos principais pontos tur\u00edsticos da capital, tem acesso gratuito ao p\u00fablico. O local pode ser acessado pelo Centro Pol\u00edtico Administrativo (em frente \u00e0 Assembleia Legislativa), pelo bairro Paiagu\u00e1s e pela Avenida Dr. H\u00e9lio Ribeiro. O parque funciona das 5h \u00e0s 23h, diariamente.<\/p>\n<p><strong>Programa\u00e7\u00e3o religiosa<\/strong><\/p>\n<p>A Solenidade da Imaculada Concei\u00e7\u00e3o \u00e9 uma data em que os fi\u00e9is da Igreja Cat\u00f3lica celebram, com alegria, durante o per\u00edodo do Advento, o dogma segundo o qual a Virgem Maria foi preservada do pecado original desde o momento de sua concep\u00e7\u00e3o.<\/p>\n<p>Confira a programa\u00e7\u00e3o nas principais par\u00f3quias da capital:<\/p>\n<p>Catedral Bas\u00edlica Senhor Bom Jesus de Cuiab\u00e1 \u2013 As Santas Missas ser\u00e3o celebradas \u00e0s 6h30 e \u00e0s 18h30. Neste dia, a Catedral permanecer\u00e1 aberta somente nos hor\u00e1rios das missas.<\/p>\n<p>Par\u00f3quia Divino Esp\u00edrito Santo \u2013 A Santa Missa ser\u00e1 celebrada \u00e0s 7h na Igreja Matriz. \u00c0s 5h, inicia-se a Alvorada, seguida do Of\u00edcio da Imaculada e do Ch\u00e1 com Bolo na Comunidade Imaculada Concei\u00e7\u00e3o, no CPA 3, Setor 4. A concentra\u00e7\u00e3o para a prociss\u00e3o ser\u00e1 \u00e0s 18h.<\/p>\n<p>Par\u00f3quia S\u00e3o Jo\u00e3o Bosco \u2013 A Festa da Imaculada Concei\u00e7\u00e3o come\u00e7a no dia 5 e segue at\u00e9 7 de dezembro. A Santa Missa ser\u00e1 celebrada \u00e0s 19h.<\/p>\n<p>Par\u00f3quia Nossa Senhora Medianeira de Todas as Gra\u00e7as \u2013 A programa\u00e7\u00e3o na igreja matriz inicia \u00e0s 6h, com a Santa Missa. \u00c0s 9h, tem in\u00edcio a Hora da Gra\u00e7a, com Cen\u00e1culo Mariano, ora\u00e7\u00e3o do Ter\u00e7o da Miseric\u00f3rdia e da Rosa M\u00edstica. Ao meio-dia, haver\u00e1 a Santa Missa pela Hora da Gra\u00e7a Universal. \u00c0s 19h30, ser\u00e1 celebrada a Santa Missa em comemora\u00e7\u00e3o aos 46 anos da eleva\u00e7\u00e3o da Medianeira ao t\u00edtulo de Par\u00f3quia.<\/p>\n<p>Outras par\u00f3quias como: Cora\u00e7\u00e3o Imaculado de Maria ter\u00e1 santa missa \u00e0s 7h; Nossa Senhora Aparecida (Coxip\u00f3) ter\u00e1 solenidade \u00e0s 19h30; Nossa Senhora da Medalha Milagrosa ter\u00e1 missa \u00e0s 19h30 e a Par\u00f3quia Nossa Senhora de Guadalupe ter\u00e1 santa missa \u00e0s 19h na Comunidade Nossa Senhora da Penha.<\/p>\n<p>A Par\u00f3quia Sagrada Fam\u00edlia ter\u00e1 santa missa na comunidade e a solenidade ocorrer\u00e1 ap\u00f3s a prociss\u00e3o luminosa, \u00e0s 18h30.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 |\u00a0 Emanoele Daiane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exceto no caso de atividades consideradas essenciais, os \u00f3rg\u00e3os p\u00fablicos vinculados \u00e0 Prefeitura de Cuiab\u00e1 &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98693,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98692"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98692\/revisions"}],"predecessor-version":[{"id":98694,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98692\/revisions\/98694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98693"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}