{"id":98790,"date":"2025-12-11T12:24:28","date_gmt":"2025-12-11T16:24:28","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98790"},"modified":"2025-12-11T12:24:28","modified_gmt":"2025-12-11T16:24:28","slug":"saude-digital-de-mato-grosso-adquire-250-retinografos-portateis-eyer2","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/saude-digital-de-mato-grosso-adquire-250-retinografos-portateis-eyer2\/","title":{"rendered":"Sa\u00fade Digital de Mato Grosso adquire 250 retin\u00f3grafos port\u00e1teis Eyer2"},"content":{"rendered":"<section id=\"content\" class=\"\">\n<div id=\"main-content\" class=\"layout-content portlet-layout\" role=\"main\">\n<div class=\"lfr-layout-structure-item-basic-component-html lfr-layout-structure-item-bda1c57d-ebfb-7ab5-34ae-f5ebeccc3ede \">\n<div id=\"fragment-3bcba102-ff6a-318e-8ca3-020d604ffd12\">\n<div class=\"component-html\" data-lfr-editable-id=\"element-html\" data-lfr-editable-type=\"html\">\n<div class=\"container-fluid viewNoticia mt-4 mb-5\">\n<div class=\"container mt-5\">\n<div class=\"row justify-content-md-center\">\n<div class=\"col-sm-11 conteudo\">\n<p>A Secretaria de Estado de Sa\u00fade (SES-MT), por meio do programa de Sa\u00fade Digital, adquiriu 250 retin\u00f3grafos port\u00e1teis Eyer2. A entrega desses aparelhos foi realizada nesta quinta-feira (11.12), no Hotel Fazenda Mato Grosso, durante a \u00faltima reuni\u00e3o da Comiss\u00e3o Intergestores Bipartite (CIB) de 2025.<\/p>\n<p>Nesta primeira etapa de entrega, 70 aparelhos foram distribu\u00eddos \u00e0 69 munic\u00edpios do Estado. Al\u00e9m disso, 100 profissionais da Aten\u00e7\u00e3o Prim\u00e1ria \u00e0 Sa\u00fade receber\u00e3o treinamento te\u00f3rico e pr\u00e1tico para operar o equipamento, realizar exames e conduzir o fluxo seguro. Cada profissional ser\u00e1 um multiplicador municipal, garantindo expans\u00e3o r\u00e1pida e sustent\u00e1vel do servi\u00e7o.<\/p>\n<picture data-fileentryid=\"76085035\"><source srcset=\"\/o\/adaptive-media\/image\/76085035\/Thumbnail-1024x1024\/aparelho.jfif?t=1765465791185\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.secom.mt.gov.br\/documents\/d\/mt\/aparelho?imageThumbnail=3\" alt=\"\" height=\"267\" \/><\/picture>\n&#8220;Estamos descentralizando o cuidado e garantindo que a preven\u00e7\u00e3o de patologias oculares em pacientes de diversos munic\u00edpios de Mato Grosso. A tecnologia aproxima o cidad\u00e3o do diagn\u00f3stico, fortalece os munic\u00edpios e cria uma rede humanizada\u201d, destacou o secret\u00e1rio de Estado de Sa\u00fade, Gilberto Figueiredo.<\/p>\n<p>A aquisi\u00e7\u00e3o dos aparelhos e a capacita\u00e7\u00e3o desses profissionais da sa\u00fade tem como objetivo detectar precocemente doen\u00e7as oculares graves\u00a0 como a retinopatia diab\u00e9tica, glaucoma, degenera\u00e7\u00e3o macular e les\u00f5es de c\u00f3rnea,\u00a0 especialmente entre popula\u00e7\u00f5es de maior risco e regi\u00f5es com oferta limitada de especialistas.<\/p>\n<p>Os grupos com mais riscos de patologias oculares s\u00e3o diab\u00e9ticos, hipertensos em est\u00e1gio 2 e idosos. A Teleretinografia ir\u00e1 garantir que os pacientes n\u00e3o necessitem de grandes deslocamentos para realizarem o exame, que agora poder\u00e3o ser realizados diretamente nas unidades b\u00e1sicas, com laudos emitidos digitalmente em um curto per\u00edodo de tempo pelo Sistema \u00danico de Sa\u00fade (SUS).<\/p>\n<p>Os resultados dos exames ser\u00e3o processados no Centro Estadual de Telediagn\u00f3stico Oftalmol\u00f3gico, com sede em C\u00e1ceres. O centro funcionar\u00e1 como n\u00facleo oficial de leitura dos exames realizados nos munic\u00edpios, garantindo interpreta\u00e7\u00e3o especializada com rapidez e seguran\u00e7a, integra\u00e7\u00e3o ensino\u2013servi\u00e7o, padroniza\u00e7\u00e3o diagn\u00f3stica, suporte t\u00e9cnico aos munic\u00edpios, monitoramento cont\u00ednuo da qualidade dos exames e sustentabilidade assistencial a longo prazo.<\/p>\n<p>A gestora da Sa\u00fade Digital, Dra. V\u00e2nia Berti, ressalta que a iniciativa \u00e9 um avan\u00e7o para a sa\u00fade de Mato Grosso. \u201cA aquisi\u00e7\u00e3o desses aparelhos e a capacita\u00e7\u00e3o desses profissionais da sa\u00fade \u00e9 imprescind\u00edvel para garantir que pacientes de diversas regi\u00f5es do Estado tenham acesso \u00e0 diagn\u00f3sticos de patologias relacionadas \u00e0 vis\u00e3o, garantindo o tratamento precoce evitando assim que esses pacientes percam a vis\u00e3o\u201d, concluiu.<\/p>\n<p><strong>Sobre o Sa\u00fade Digital MT<\/strong><\/p>\n<p>O programa de Sa\u00fade Digital de Mato Grosso \u00e9 uma estrat\u00e9gia que moderniza e integra a rede de sa\u00fade, com foco em telemedicina, telediagn\u00f3stico, interoperabilidade e amplia\u00e7\u00e3o do acesso. O programa fortalece a resolutividade da Aten\u00e7\u00e3o Prim\u00e1ria, reduz desigualdades e acelera a oferta de servi\u00e7os de qualidade em todo o territ\u00f3rio mato-grossense, al\u00e9m de gerar a economia de recursos p\u00fablicos.<\/p>\n<p><em>*Sob a supervis\u00e3o de Ana Lazarini<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/section>\n<div class=\"container-fluid\"><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>MTGOV\u00a0 |\u00a0 Foto:\u00a0 SES &#8211; MT<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Sa\u00fade (SES-MT), por meio do programa de Sa\u00fade Digital, adquiriu &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98791,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Entrega ocorreu na reuni\u00e3o da CIB, com a distribui\u00e7\u00e3o de 70 aparelhos a 69 munic\u00edpios de MT; 100 profissionais da Aten\u00e7\u00e3o Prim\u00e1ria ser\u00e3o capacitados para a utiliza\u00e7\u00e3o do aparelho","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98790"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98790\/revisions"}],"predecessor-version":[{"id":98792,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98790\/revisions\/98792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98791"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}