{"id":98805,"date":"2025-12-11T12:36:27","date_gmt":"2025-12-11T16:36:27","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98805"},"modified":"2025-12-11T12:36:27","modified_gmt":"2025-12-11T16:36:27","slug":"saude-de-cuiaba-recupera-r-1-milhao-e-recebe-reforco-mensal-do-estado","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/saude-de-cuiaba-recupera-r-1-milhao-e-recebe-reforco-mensal-do-estado\/","title":{"rendered":"Sa\u00fade de Cuiab\u00e1 recupera R$ 1 milh\u00e3o e recebe refor\u00e7o mensal do Estado"},"content":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por meio da Secretaria Municipal de Sa\u00fade, garantiu a recomposi\u00e7\u00e3o do cofinanciamento estadual do MAC Hospitalar, M\u00e9dia e Alta Complexidade, durante a 10\u00aa Reuni\u00e3o Ordin\u00e1ria da Comiss\u00e3o Intergestores Bipartite do Estado de Mato Grosso (CIB\/MT), realizada nesta quinta-feira (11), no Hotel Fazenda Mato Grosso.<\/p>\n<p>Com a pactua\u00e7\u00e3o, o valor destinado mensalmente ao munic\u00edpio passa de R$ 2,3 milh\u00f5es para R$ 3,3 milh\u00f5es, representando um aumento de R$ 1 milh\u00e3o no apoio ao custeio das a\u00e7\u00f5es e servi\u00e7os hospitalares de refer\u00eancia.<\/p>\n<p>A reuni\u00e3o contou com a participa\u00e7\u00e3o da secret\u00e1ria municipal de Sa\u00fade, Danielle Carmona, que destacou a import\u00e2ncia da recomposi\u00e7\u00e3o para fortalecer a rede hospitalar de Cuiab\u00e1 e assegurar a continuidade dos servi\u00e7os prestados \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>Apesar de o Estado j\u00e1 repassar historicamente R$ 3,3 milh\u00f5es ao munic\u00edpio, a gest\u00e3o anterior perdeu R$ 1 milh\u00e3o do montante por falta de presta\u00e7\u00e3o de contas, fazendo com que o valor fosse reduzido para R$ 2,3 milh\u00f5es.<\/p>\n<p>Segundo a Secretaria Municipal de Sa\u00fade, a atual gest\u00e3o realizou a recomposi\u00e7\u00e3o dos servi\u00e7os, ordenou as pend\u00eancias e apresentou ao Estado os elementos t\u00e9cnicos necess\u00e1rios para recuperar a integralidade do recurso.<\/p>\n<p>\u201cConseguimos reorganizar os servi\u00e7os, corrigir distor\u00e7\u00f5es e demonstrar ao Estado a real necessidade do financiamento integral. \u00c9 um ganho importante para a rede municipal e para os hospitais contratualizados\u201d, explicou a secret\u00e1ria Danielle Carmona.<\/p>\n<p><strong>Com a aprova\u00e7\u00e3o, a CIB\/MT oficializou:<\/strong><\/p>\n<p>Art. 1\u00ba \u2014 Altera\u00e7\u00e3o do valor do cofinanciamento estadual n\u00e3o obrigat\u00f3rio de R$ 2.300.000,00 para R$ 3.300.000,00, destinado ao custeio mensal das a\u00e7\u00f5es de Aten\u00e7\u00e3o Hospitalar de Refer\u00eancia (MAC) no munic\u00edpio de Cuiab\u00e1.<\/p>\n<p>Art. 2\u00ba \u2014 O repasse ser\u00e1 realizado na modalidade fundo a fundo, do Fundo Estadual de Sa\u00fade para o Fundo Municipal, conforme a Portaria n\u00ba 200\/2024\/GBSES e mediante assinatura do Termo de Compromisso atualizado.<\/p>\n<p>Os recursos ser\u00e3o aplicados nas unidades hospitalares contratualizadas pelo munic\u00edpio, conforme detalhamento previsto no Anexo \u00danico da resolu\u00e7\u00e3o da CIB\/MT.<\/p>\n<p>A Comiss\u00e3o Intergestores Bipartite \u00e9 reconhecida como um dos principais f\u00f3runs de pactua\u00e7\u00e3o do Sistema \u00danico de Sa\u00fade, reunindo gestores estaduais e municipais para decis\u00f5es conjuntas que garantem transpar\u00eancia e efici\u00eancia na gest\u00e3o p\u00fablica.<\/p>\n<p>Durante o encontro, foi refor\u00e7ada a parceria entre a Prefeitura de Cuiab\u00e1 e o Governo do Estado de Mato Grosso.<\/p>\n<p>\u201cO Estado tem sido um parceiro fundamental nesse processo de reorganiza\u00e7\u00e3o e fortalecimento da sa\u00fade p\u00fablica. Esta recomposi\u00e7\u00e3o \u00e9 resultado de di\u00e1logo, responsabilidade t\u00e9cnica e compromisso conjunto com a popula\u00e7\u00e3o\u201d, ressaltou Danielle Carmona.<\/p>\n<p>O MAC (M\u00e9dia e Alta Complexidade) \u00e9 respons\u00e1vel por financiar procedimentos hospitalares e ambulatoriais essenciais, como cirurgias, atendimentos especializados, exames de maior complexidade e servi\u00e7os de emerg\u00eancia.<\/p>\n<p>Seu custeio \u00e9 compartilhado entre Uni\u00e3o, Estados e Munic\u00edpios, conforme previsto na Constitui\u00e7\u00e3o Federal e na Lei Org\u00e2nica da Sa\u00fade.<\/p>\n<p>Com o refor\u00e7o de R$ 1 milh\u00e3o, a rede hospitalar de Cuiab\u00e1 passa a ter maior seguran\u00e7a financeira para manter e ampliar a oferta de servi\u00e7os.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0 |\u00a0 \u00a0Foto:\u00a0 Mauro Torcates<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por meio da Secretaria Municipal de Sa\u00fade, garantiu a recomposi\u00e7\u00e3o do &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98806,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98805"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98805\/revisions"}],"predecessor-version":[{"id":98807,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98805\/revisions\/98807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98806"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}