{"id":98808,"date":"2025-12-11T12:41:18","date_gmt":"2025-12-11T16:41:18","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98808"},"modified":"2025-12-11T12:41:18","modified_gmt":"2025-12-11T16:41:18","slug":"procon-leva-orientacao-e-acolhimento-aos-idosos-no-cci-aidee-pereira","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/procon-leva-orientacao-e-acolhimento-aos-idosos-no-cci-aidee-pereira\/","title":{"rendered":"Procon leva orienta\u00e7\u00e3o e acolhimento aos idosos no CCI Aidee Pereira"},"content":{"rendered":"<p>O Centro de Conviv\u00eancia Intergeracional Aidee Pereira, no bairro Novo Horizonte, recebeu nesta quarta-feira (10) a equipe do Procon Cuiab\u00e1 para mais uma etapa da agenda municipal de a\u00e7\u00f5es voltadas \u00e0 prote\u00e7\u00e3o, informa\u00e7\u00e3o e fortalecimento dos direitos da pessoa idosa. A atividade faz parte do cronograma iniciado no fim de novembro nos CCIs da capital, que tem buscado aproximar o \u00f3rg\u00e3o fiscalizador do p\u00fablico mais vulner\u00e1vel a golpes, abusos de consumo e contrata\u00e7\u00f5es indevidas.<\/p>\n<p>A programa\u00e7\u00e3o do dia reuniu palestra educativa com a secret\u00e1ria-adjunta do Procon, Mariana Almeida Borges; teatro tem\u00e1tico sobre preven\u00e7\u00e3o a golpes, encenado pela pr\u00f3pria equipe do \u00f3rg\u00e3o; orienta\u00e7\u00f5es individuais; sorteio de brindes; e dois momentos de conviv\u00eancia com lanche. O atendimento presencial aos idosos continua nesta quinta-feira (11), das 13h \u00e0s 17h.<\/p>\n<p>\u201cOs idosos s\u00e3o, muitas vezes, o principal alvo de golpes. Estar perto deles, explicar seus direitos e mostrar que o Procon est\u00e1 acess\u00edvel \u00e9 fundamental. N\u00f3s queremos orientar, proteger e ouvir cada pessoa que procura ajuda\u201d, destacou Mariana Borges. Aos participantes, ela refor\u00e7ou ainda a import\u00e2ncia de compartilhar as informa\u00e7\u00f5es com familiares: \u201cDivulguem isso para os filhos, netos e vizinhos. Quanto mais gente souber, menos pessoas sofrer\u00e3o golpes\u201d.<\/p>\n<p><strong>Cuidado cont\u00ednuo nos CCIs e estrutura fortalecida<\/strong><\/p>\n<p>A secret\u00e1ria municipal de Assist\u00eancia Social, Direitos Humanos e Inclus\u00e3o, H\u00e9lida Vilela, acompanhou a atividade e ressaltou a import\u00e2ncia da presen\u00e7a do Procon dentro dos Centros de Conviv\u00eancia. \u201c\u00c9 um momento em que a equipe pode estar pr\u00f3xima dos idosos, ouvir e dar aten\u00e7\u00e3o \u00e0s necessidades de cada unidade.\u201d<\/p>\n<p>No CCI Aidee Pereira, ela elogiou o trabalho da gerente Ivania Alves Tito, especialista em gerontologia \u2014 \u00e1rea que estuda o envelhecimento e busca melhorar a qualidade de vida das pessoas idosas. \u201cEssa forma\u00e7\u00e3o espec\u00edfica \u00e9 uma honra para a unidade e essencial para um atendimento cuidadoso. Mas o mais importante \u00e9 estarmos aqui, ouvindo diretamente as pessoas.\u201d<\/p>\n<p>A gest\u00e3o tamb\u00e9m aproveitou a visita para levantar demandas estruturais. J\u00e1 est\u00e1 em andamento o or\u00e7amento para manuten\u00e7\u00e3o dos telhados e forros, comprometidos pelas \u00faltimas chuvas, e um estudo para climatizar a \u00e1rea externa. \u201cO diretor de gest\u00e3o e a equipe de engenharia estiveram aqui e verificaram a possibilidade de fechar e climatizar o espa\u00e7o para oferecer mais conforto aos idosos\u201d, explicou H\u00e9lida.<\/p>\n<p>Outro avan\u00e7o previsto \u00e9 o projeto \u201cCosturando Amizades\u201d, que deve ser implantado em 2026. O CCI possui cinco m\u00e1quinas industriais que est\u00e3o sendo revisadas. \u201cA sala j\u00e1 est\u00e1 preparada e temos at\u00e9 uma professora de corte e costura. Assim que concluirmos o conserto das m\u00e1quinas, o projeto come\u00e7a a funcionar\u201d, adiantou a secret\u00e1ria.<\/p>\n<p><strong>Atendimento e rotina do CCI Aidee Pereira<\/strong><\/p>\n<p>O CCI Aidee atende hoje 266 idosos cadastrados, com m\u00e9dia di\u00e1ria de 65 frequentadores. As atividades ocorrem de segunda a quinta-feira, das 7h \u00e0s 9h, com oficinas de gin\u00e1stica, gin\u00e1stica de sal\u00e3o, siriri, inclus\u00e3o digital, alfabetiza\u00e7\u00e3o e croch\u00ea. Cerca de 40% dos participantes est\u00e3o matriculados na alfabetiza\u00e7\u00e3o, ampliada em 2025 e respons\u00e1vel por duplicar o n\u00famero de atendimentos da unidade.<\/p>\n<p>Para a gerente Ivania Alves Tito, rec\u00e9m-chegada ao cargo, trabalhar com idosos \u00e9 uma voca\u00e7\u00e3o. \u201cEu j\u00e1 atuo h\u00e1 20 anos com envelhecimento e estou muito feliz com a participa\u00e7\u00e3o dos idosos. J\u00e1 estamos planejando 2026, incluindo a profissionaliza\u00e7\u00e3o do coral e novos cursos de artes.\u201d<\/p>\n<p>A equipe t\u00e9cnica conta com seis profissionais das \u00e1reas de assist\u00eancia social, pedagogia e educa\u00e7\u00e3o f\u00edsica. A unidade tamb\u00e9m mant\u00e9m acompanhamento individualizado dos usu\u00e1rios, com liga\u00e7\u00f5es e visitas quando h\u00e1 aus\u00eancia prolongada.<\/p>\n<p><strong>Depoimentos: seguran\u00e7a, informa\u00e7\u00e3o e pertencimento<\/strong><\/p>\n<p>A a\u00e7\u00e3o do Procon despertou forte participa\u00e7\u00e3o dos idosos, que relataram experi\u00eancias pessoais com golpes e destacaram a import\u00e2ncia da informa\u00e7\u00e3o acess\u00edvel.<\/p>\n<p>Zeny Deusana, 53, afirmou que as orienta\u00e7\u00f5es foram fundamentais: sua m\u00e3e foi v\u00edtima de um empr\u00e9stimo fraudulento de R$ 5 mil.<\/p>\n<p>J\u00e1 Teresa Luiz da Silva, 69, contou que quase caiu em um golpe de entrega falsa. \u201cQueriam tirar minha foto e pedir assinatura. Eu n\u00e3o aceitei. O idoso precisa ter muito cuidado\u201d, alertou.<\/p>\n<p>Entre os depoimentos mais emocionados, o de Samuel Pereira J\u00fanior Alves do Bonfim, 68, chamou aten\u00e7\u00e3o. Vi\u00favo, ele encontrou no CCI um espa\u00e7o de acolhimento. \u201cAqui \u00e9 uma riqueza. Entre dores e incha\u00e7os, cheguei ruim\u2026 e hoje estou renovado. Os professores fazem um \u2018concerto\u2019 na gente\u201d, disse.<\/p>\n<p>O sentimento \u00e9 compartilhado por muitos, como explica o educador f\u00edsico e especialista em desenvolvimento social Douglas Vin\u00edcius Silva Lenzi, que atua h\u00e1 tr\u00eas anos e meio na unidade. \u201cUsamos o movimento e a conviv\u00eancia para devolver autonomia e autoestima. O sedentarismo adoece; aqui, o idoso volta a se sentir parte da sociedade, cria la\u00e7os e recupera sua mobilidade e alegria.\u201d<\/p>\n<p><strong>Agenda das a\u00e7\u00f5es do Procon nos CCIs<\/strong><\/p>\n<p>A a\u00e7\u00e3o no CCI Aidee integra um calend\u00e1rio iniciado no fim de novembro, nos CCIs Padre Firmo (26 e 27\/11), Jo\u00e3o Guerreiro (03 e 04\/12), Aidee Pereira (10 e 11\/12) e, por fim, Maria Inez (17 e 18\/12).<\/p>\n<p><strong>Compromisso com a popula\u00e7\u00e3o idosa<\/strong><\/p>\n<p>As a\u00e7\u00f5es refor\u00e7am a orienta\u00e7\u00e3o da Prefeitura de Cuiab\u00e1 para aproximar pol\u00edticas p\u00fablicas do cotidiano dos idosos, de forma pr\u00e1tica, cuidadosa e acess\u00edvel, inclusive traduzindo temas complexos, como direitos do consumidor e termos jur\u00eddicos, para uma linguagem simples e \u00fatil \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>Com iniciativas que unem preven\u00e7\u00e3o, acolhimento e promo\u00e7\u00e3o da autonomia, o Procon e os CCIs encerram o ano refor\u00e7ando o compromisso de proteger e valorizar quem ajudou a construir a cidade.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0 |\u00a0 \u00a0Foto:\u00a0 Emanoele Daiane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Centro de Conviv\u00eancia Intergeracional Aidee Pereira, no bairro Novo Horizonte, recebeu nesta quarta-feira (10) &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98809,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98808"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98808\/revisions"}],"predecessor-version":[{"id":98810,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98808\/revisions\/98810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98809"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}