{"id":98900,"date":"2025-12-17T16:52:20","date_gmt":"2025-12-17T20:52:20","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98900"},"modified":"2025-12-17T16:52:20","modified_gmt":"2025-12-17T20:52:20","slug":"vigia-mais-mt-auxilia-na-prisao-de-158-procurados-da-justica-em-mato-grosso","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/vigia-mais-mt-auxilia-na-prisao-de-158-procurados-da-justica-em-mato-grosso\/","title":{"rendered":"Vigia Mais MT auxilia na pris\u00e3o de 158 procurados da Justi\u00e7a em Mato Grosso"},"content":{"rendered":"<p>O programa de v\u00eddeomonitoramento Vigia Mais MT, criado pelo Governo de Mato Grosso, auxiliou as for\u00e7as de seguran\u00e7a na pris\u00e3o de 158 procurados da Justi\u00e7a de Mato Grosso e de outros estados, entre janeiro e 15 de dezembro de 2025.<\/p>\n<p>Um balan\u00e7o parcial do Centro Integrado de Opera\u00e7\u00f5es de Seguran\u00e7a P\u00fablica (Ciosp), da Secretaria de Seguran\u00e7a P\u00fablica (Sesp-MT), revela que do total de pris\u00f5es registradas, 43 ocorreram por meio do sistema de reconhecimento facial e 115 foram identificadas a partir da leitura de placas de ve\u00edculos.\u00a0 O levantamento mostra como a integra\u00e7\u00e3o de dados e monitoramento eletr\u00f4nico tem se consolidado como ferramenta estrat\u00e9gica para a seguran\u00e7a p\u00fablica em Mato Grosso.<\/p>\n<p>O secret\u00e1rio Adjunto de Integra\u00e7\u00e3o Operacional (Saiop), coronel PM Fernando Augustinho, destacou que o sistema de monitoramento forma uma muralha digital e fecha o cerco contra os criminosos foragidos da Justi\u00e7a.<\/p>\n<p>\u201cO sistema de reconhecimento facial possui intelig\u00eancia artificial que amplia a capacidade das for\u00e7as de seguran\u00e7a de retirar das ruas criminosos condenados foragidos da Justi\u00e7a,\u00a0para dar espa\u00e7o para que os cidad\u00e3os mato-grossenses possam ir em vir com liberdade e mais seguran\u00e7a\u201d, destacou.<\/p>\n<picture data-fileentryid=\"76290727\"><source srcset=\"\/o\/adaptive-media\/image\/76290727\/Thumbnail-1024x1024\/9A3A2810.jpg?t=1765980829163\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.sesp.mt.gov.br\/documents\/d\/sesp\/9a3a2810-jpg-2?imageThumbnail=3\" alt=\"\" height=\"267\" \/><\/picture>\nDentre os presos com ajuda do programa est\u00e1 um homem, de 44 anos, condenado a mais de 18 anos por estupro de vulner\u00e1vel contra duas v\u00edtimas. Ele foi identificado pelas c\u00e2meras de reconhecimento facial durante o Festival de Inverno, em Chapada dos Guimar\u00e3es.<\/p>\n<p>Em V\u00e1rzea Grande, um homem de 39 anos, foragido da Justi\u00e7a e procurado por homic\u00eddio foi preso e encaminhado \u00e0 delegacia, ap\u00f3s ser identificado pelo programa. Al\u00e9m disso, em Cuiab\u00e1, outro homem, procurado pelas Justi\u00e7a de Mato Grosso e Mato Grosso do Sul, por tr\u00e1fico e furto, tamb\u00e9m foi identificado e preso.<\/p>\n<p>O secret\u00e1rio adjunto refor\u00e7ou que esses s\u00e3o apenas os primeiros resultados do programa, lan\u00e7ado em 2023 e que neste ano j\u00e1 se tornou destaque nacional.<\/p>\n<p>\u201cAs fun\u00e7\u00f5es do programa v\u00e3o al\u00e9m da capacidade humana e essa jun\u00e7\u00e3o de tecnologia com as nossas for\u00e7as vem trazendo resultados positivos. Tanto que o Vigia Mais MT \u00e9 reconhecido no \u00e2mbito nacional e est\u00e1 servindo de modelo para outros estados\u201d, completou Fernando Augustinho.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Christiano Antonucci &#8211; Secom MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O programa de v\u00eddeomonitoramento Vigia Mais MT, criado pelo Governo de Mato Grosso, auxiliou as &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98901,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-98900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Entre janeiro a dezembro deste ano, 43 pris\u00f5es ocorreram por meio de sistema de reconhecimento facial e 115 a partir de leitura de placas de ve\u00edculos","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98900"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98900\/revisions"}],"predecessor-version":[{"id":98902,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98900\/revisions\/98902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98901"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}