{"id":98952,"date":"2025-12-18T14:36:26","date_gmt":"2025-12-18T18:36:26","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=98952"},"modified":"2025-12-18T14:36:26","modified_gmt":"2025-12-18T18:36:26","slug":"prefeitura-de-cuiaba-convoca-1-205-aprovados-para-tecnico-em-desenvolvimento-infantil","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeitura-de-cuiaba-convoca-1-205-aprovados-para-tecnico-em-desenvolvimento-infantil\/","title":{"rendered":"Prefeitura de Cuiab\u00e1 convoca 1.205 aprovados para T\u00e9cnico em Desenvolvimento Infantil"},"content":{"rendered":"<section class=\"innerpage-text-content\">\n<div class=\"container\">\n<div class=\"content clearfix\">\n<div class=\"content-text text-break clearfix\">\n<p>A Prefeitura de Cuiab\u00e1 publica nesta quinta feira (18), os editais de convoca\u00e7\u00e3o de candidatos aprovados no Processo Seletivo Simplificado para Contratos Tempor\u00e1rios de Presta\u00e7\u00e3o de Servi\u00e7os por Tempo Determinado e Forma\u00e7\u00e3o de Cadastro de Reserva N\u00ba 04\/2025\/GS\/SME, publicado na Gazeta Municipal n\u00ba 1190 &#8211; Suplementar, de 28 de agosto de 2025, para atuarem em unidades educacionais da rede municipal, no ano letivo 2026.<\/p>\n<p>Est\u00e3o sendo convocados aprovados na fun\u00e7\u00e3o de T\u00e9cnico em Desenvolvimento Infantil.<\/p>\n<p>Os candidatos convocados devem se cadastrar e\u00a0enviar a documenta\u00e7\u00e3o listada nos editais de convoca\u00e7\u00e3o no endere\u00e7o eletr\u00f4nico: https:\/\/cidadao.cuiaba.mt.gov.br\/servico_resumido.aspx?cod_assunto_documento_tipo=495 \u00a0e \u00a0ap\u00f3s o deferimento, deve comparecer \u00e0 Secretaria Municipal de Educa\u00e7\u00e3o, localizada na Rua Diogo Domingos Ferreira, n\u00ba 292, bairro Bandeirantes, de acordo com as datas e hor\u00e1rios previstos nos Editais de convoca\u00e7\u00e3o, para atribui\u00e7\u00e3o.<\/p>\n<p><strong>Orienta\u00e7\u00f5es<\/strong><\/p>\n<p>Os convocados devem ler atentamente os editais. O candidato que n\u00e3o comparecer no dia e hor\u00e1rio previstos nos Editais ou n\u00e3o entregar no sistema toda a documenta\u00e7\u00e3o exigida ser\u00e1 eliminado, pois n\u00e3o haver\u00e1 segunda chamada e nesse caso, ser\u00e1 convocado o candidato classificado na sequ\u00eancia.<\/p>\n<p>Os documentos que devem ser enviados digitalizados (originais), de acordo com os Editais s\u00e3o: RG, CPF, T\u00edtulo de Eleitor, PIS ou PASEP, Certificado de Reservista, Conta Corrente no Banco do Brasil (caso houver), comprovante de resid\u00eancia, diploma ou certificado de conclus\u00e3o de curso acompanhado do Hist\u00f3rico Escolar, exame admissional e certid\u00f5es negativas.<\/p>\n<p>A Secretaria Municipal de Educa\u00e7\u00e3o informa que o candidato que chegar atrasado e seu nome j\u00e1 tenha sido chamado, ser\u00e1 realocado ao final da lista de chamamento. O comparecimento em hor\u00e1rio diferente da convoca\u00e7\u00e3o acarretar\u00e1 em elimina\u00e7\u00e3o do certame conforme item 13.3 do edital.<\/p>\n<p>Os candidatos listados nas convoca\u00e7\u00f5es dever\u00e3o fazer o exame admissional no local de sua prefer\u00eancia, devendo constar o cargo e aptid\u00e3o.<\/p>\n<p><strong>Processo Seletivo<\/strong><\/p>\n<p>O certame realizado em 2025, ofertou 1985 vagas para contrata\u00e7\u00e3o imediata de tempor\u00e1rios e forma\u00e7\u00e3o de cadastro reserva de n\u00edveis m\u00e9dio e superior, para atuarem nas unidades educacionais da rede p\u00fablica municipal de educa\u00e7\u00e3o em substitui\u00e7\u00e3o de servidores efetivos, a fim de atender \u00e0 necessidade tempor\u00e1ria de excepcional interesse p\u00fablico.<\/p>\n<p>Nesta 2\u00aa convoca\u00e7\u00e3o est\u00e3o sendo convocados 1205 candidatos para os cargos de Professor e TDI<\/p>\n<p>Confira em anexo os editais de convoca\u00e7\u00e3o.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<ul class=\"container\">\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/12\/18\/outros\/2025-12-18-13-52-1-convocacao-tdi-regional-oeste-05-01-26-manha-69443f713a4ae.pdf\" target=\"_blank\" rel=\"noopener\">1_CONVOCA\u00c7\u00c3O_TDI_Regional Oeste_05-01-26 MANH\u00c3.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/12\/18\/outros\/2025-12-18-13-52-2-convocacao-tdi-regional-sul-05-01-26-tarde-69443f713db35.pdf\" target=\"_blank\" rel=\"noopener\">2_CONVOCA\u00c7\u00c3O_TDI_Regional Sul_05-01-26 TARDE.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/12\/18\/outros\/2025-12-18-13-52-3-convocacao-tdi-regional-sul-06-01-26-manha-69443f714eff6.pdf\" target=\"_blank\" rel=\"noopener\">3_CONVOCA\u00c7\u00c3O_TDI_Regional Sul_06-01-26 MANH\u00c3.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/12\/18\/outros\/2025-12-18-13-52-4-convocacao-tdi-regional-sul-06-01-26-tarde-69443f7151d29.pdf\" target=\"_blank\" rel=\"noopener\">4_CONVOCA\u00c7\u00c3O_TDI_Regional Sul_06-01-26 TARDE.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/12\/18\/outros\/2025-12-18-13-52-6-convocacao-tdi-regional-norte-07-01-26-tarde-69443f71547ff.pdf\" target=\"_blank\" rel=\"noopener\">6_CONVOCA\u00c7\u00c3O_TDI_Regional NORTE_07-01-26 TARDE.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/12\/18\/outros\/2025-12-18-13-52-7-convocacao-tdi-regional-norte-08-01-26-manha-69443f7156d80.pdf\" target=\"_blank\" rel=\"noopener\">7_CONVOCA\u00c7\u00c3O_TDI_Regional NORTE_08-01-26 MANHA.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/12\/18\/outros\/2025-12-18-13-52-5-convocacao-tdi-regional-sul-07-01-26-manha-69443f7159145.pdf\" target=\"_blank\" rel=\"noopener\">5_CONVOCA\u00c7\u00c3O_TDI_Regional Sul_07-01-26 MANH\u00c3.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/12\/18\/outros\/2025-12-18-13-52-8-convocacao-tdi-regional-norte-08-01-26-tarde-69443f715b7c3.pdf\" target=\"_blank\" rel=\"noopener\">8_CONVOCA\u00c7\u00c3O_TDI_Regional NORTE_08-01-26 TARDE.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/12\/18\/outros\/2025-12-18-13-52-9-convocacao-tdi-regional-leste-09-01-26-manha-69443f7163a8c.pdf\" target=\"_blank\" rel=\"noopener\">9_CONVOCA\u00c7\u00c3O_TDI_Regional LESTE_09-01-26 MANH\u00c3.pdf<\/a><\/li>\n<li class=\"mb-3\"><a href=\"https:\/\/www.cuiaba.mt.gov.br\/storage\/webdisco\/2025\/12\/18\/outros\/2025-12-18-13-52-10-convocacao-tdi-regional-leste-09-01-26-tarde-69443f7165975.pdf\" target=\"_blank\" rel=\"noopener\">10_CONVOCA\u00c7\u00c3O_TDI_Regional LESTE_09-01-26 TARDE.pdf<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Rennan Oliveira<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cuiab\u00e1 publica nesta quinta feira (18), os editais de convoca\u00e7\u00e3o de candidatos &hellip;<\/p>\n","protected":false},"author":4,"featured_media":98953,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-98952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=98952"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98952\/revisions"}],"predecessor-version":[{"id":98954,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/98952\/revisions\/98954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/98953"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=98952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=98952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=98952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}