{"id":99020,"date":"2026-01-05T10:04:18","date_gmt":"2026-01-05T14:04:18","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99020"},"modified":"2026-01-05T10:04:18","modified_gmt":"2026-01-05T14:04:18","slug":"semana-sera-de-calor-e-chuva-em-cuiaba-com-maximas-de-ate-32c","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/semana-sera-de-calor-e-chuva-em-cuiaba-com-maximas-de-ate-32c\/","title":{"rendered":"Semana ser\u00e1 de calor e chuva em Cuiab\u00e1, com m\u00e1ximas de at\u00e9 32\u00b0C"},"content":{"rendered":"<p>Cuiab\u00e1 deve enfrentar uma semana marcada por calor e alta umidade, com possibilidade de chuva em todos os dias, segundo previs\u00e3o do ClimaTempo. As temperaturas m\u00e1ximas podem chegar a 32\u00b0C, enquanto as m\u00ednimas permanecem pr\u00f3ximas dos 23\u00b0C.<\/p>\n<p>Nesta segunda-feira (5), a temperatura varia entre 23\u00b0C e 32\u00b0C, com 67% de chance de chuva, principalmente \u00e0 noite. Na ter\u00e7a-feira (6), os term\u00f4metros devem marcar m\u00ednima de 23\u00b0C e m\u00e1xima de 31\u00b0C, e a probabilidade de precipita\u00e7\u00f5es sobe para 79%, podendo ocorrer ao longo do dia.<\/p>\n<p>Na quarta-feira (7), a previs\u00e3o indica temperaturas entre 23\u00b0C e 30\u00b0C, com 83% de chance de chuva r\u00e1pida. J\u00e1 na quinta-feira (8), a m\u00e1xima se mant\u00e9m em 30\u00b0C e a m\u00ednima em 23\u00b0C, com 74% de probabilidade de chuva no fim do dia. Na sexta-feira (9), a temperatura varia de 24\u00b0C a 31\u00b0C, com 65% de chance de pancadas r\u00e1pidas.<\/p>\n<p>Em Chapada dos Guimar\u00e3es, destino tur\u00edstico a 66 km da capital, as temperaturas devem ser mais amenas ao longo da semana, com chuvas r\u00e1pidas em diferentes per\u00edodos. As m\u00ednimas variam entre 21\u00b0C e 22\u00b0C, e as m\u00e1ximas ficam entre 28\u00b0C e 30\u00b0C, com chances de chuva que chegam a 89%, especialmente entre ter\u00e7a e quarta-feira.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuiab\u00e1 deve enfrentar uma semana marcada por calor e alta umidade, com possibilidade de chuva &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99021,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-99020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99020"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99020\/revisions"}],"predecessor-version":[{"id":99022,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99020\/revisions\/99022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99021"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}