{"id":99042,"date":"2026-01-05T15:34:07","date_gmt":"2026-01-05T19:34:07","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99042"},"modified":"2026-01-05T15:34:07","modified_gmt":"2026-01-05T19:34:07","slug":"prefeitura-de-cuiaba-mantem-operacao-cata-treco-com-atendimento-em-seis-bairros-nesta-semana","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/prefeitura-de-cuiaba-mantem-operacao-cata-treco-com-atendimento-em-seis-bairros-nesta-semana\/","title":{"rendered":"Prefeitura de Cuiab\u00e1 mant\u00e9m opera\u00e7\u00e3o Cata-treco com atendimento em seis bairros nesta semana"},"content":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por meio da Empresa Cuiabana de Zeladoria e Servi\u00e7os Urbanos (Limpurb), d\u00e1 continuidade \u00e0 opera\u00e7\u00e3o Cata-treco, com atendimento programado em diversos bairros da capital entre os dias 5 e 10 de janeiro. A iniciativa tem como objetivo facilitar o descarte correto de m\u00f3veis e materiais inserv\u00edveis, contribuindo para a limpeza urbana e o combate ao descarte irregular.<\/p>\n<p>O servi\u00e7o \u00e9 totalmente gratuito e recolhe itens que n\u00e3o s\u00e3o atendidos pela coleta convencional, como sof\u00e1s, camas, colch\u00f5es, geladeiras, arm\u00e1rios, mesas, entre outros objetos de grande volume. A a\u00e7\u00e3o tamb\u00e9m auxilia na preven\u00e7\u00e3o de doen\u00e7as, como a dengue, ao eliminar poss\u00edveis focos de prolifera\u00e7\u00e3o do mosquito Aedes aegypti.<\/p>\n<p>Cronograma da semana<\/p>\n<p>&#8211; Segunda-feira (5): Pascoal Ramos e Parque Nova Esperan\u00e7a I<\/p>\n<p>&#8211; Ter\u00e7a-feira (6): Parque Nova Esperan\u00e7a II<\/p>\n<p>&#8211; Quarta-feira (7): CPA IV \u2013 4\u00aa e 5\u00aa Etapas<\/p>\n<p>&#8211; Quinta-feira (8): Altos da Serra I<\/p>\n<p>&#8211; Sexta-feira (9): Altos da Serra II<\/p>\n<p>&#8211;\u00a0 S\u00e1bado (10): Jardim Shangri-l\u00e1<\/p>\n<p>Para garantir o recolhimento, os moradores devem deixar os materiais em frente \u00e0s resid\u00eancias at\u00e9 as 7h da manh\u00e3 do dia programado, organizados de forma vis\u00edvel e acess\u00edvel \u00e0s equipes.<\/p>\n<p>De acordo com a Limpurb, cerca de 20 trabalhadores atuam diariamente na opera\u00e7\u00e3o, que tem in\u00edcio \u00e0s 7h e segue at\u00e9 a conclus\u00e3o dos trabalhos em cada bairro atendido.<\/p>\n<p>A empresa refor\u00e7a que n\u00e3o ser\u00e3o recolhidos res\u00edduos como entulho de constru\u00e7\u00e3o civil, restos de poda de \u00e1rvores, pneus, pilhas, baterias, vidros, latas de tinta e madeira. Esses materiais devem ser destinados aos ecopontos ou locais apropriados para descarte.<\/p>\n<p>A popula\u00e7\u00e3o pode acompanhar o cronograma semanal do Cata-treco por meio dos canais oficiais da Prefeitura de Cuiab\u00e1.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 \u00a0Foto:\u00a0 Emanoele Daiane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por meio da Empresa Cuiabana de Zeladoria e Servi\u00e7os Urbanos (Limpurb), &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99043,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-99042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99042"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99042\/revisions"}],"predecessor-version":[{"id":99044,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99042\/revisions\/99044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99043"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}