{"id":99189,"date":"2026-01-13T10:43:43","date_gmt":"2026-01-13T14:43:43","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99189"},"modified":"2026-01-13T10:43:43","modified_gmt":"2026-01-13T14:43:43","slug":"defaz-aumenta-representacoes-judiciais-em-341-e-bloqueia-mais-de-r-620-milhoes-em-operacoes-em-2025","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/defaz-aumenta-representacoes-judiciais-em-341-e-bloqueia-mais-de-r-620-milhoes-em-operacoes-em-2025\/","title":{"rendered":"Defaz aumenta representa\u00e7\u00f5es judiciais em 341% e bloqueia mais de R$ 620 milh\u00f5es em opera\u00e7\u00f5es em 2025"},"content":{"rendered":"<p>A Delegacia Especializada em Crimes Fazend\u00e1rios (Defaz), da Pol\u00edcia Civil de Mato Grosso, fechou 2025 com 12 opera\u00e7\u00f5es realizadas, um aumento de 341% nas representa\u00e7\u00f5es judiciais da delegacia, que passaram de 12 em 2024 para 53 em 2025.<\/p>\n<p>Nessas opera\u00e7\u00f5es, a Defaz investigou esquemas de fraudes tribut\u00e1rias (Rent a Business), em hortifrutigranjeiros (Hortifraude), em cr\u00e9ditos tribut\u00e1rios e multas decorrentes de empresas fantasmas (Falsus Granum), em empresas do segmento de combust\u00edveis (D\u00edvida Inflam\u00e1vel), entre outras.<\/p>\n<p>Ao todo, foram bloqueados e sequestrados R$ 625,53 milh\u00f5es. Somente na \u00faltima opera\u00e7\u00e3o do ano, D\u00edvida Inflam\u00e1vel, que investigou uma empresa de combust\u00edveis de Mato Grosso, foram bloqueados R$ 78 milh\u00f5es.<\/p>\n<p>Al\u00e9m de buscar garantir a recupera\u00e7\u00e3o de ativos, intensificar o combate \u00e0 sonega\u00e7\u00e3o fiscal e desmontar esquemas milion\u00e1rios de fraudes, as opera\u00e7\u00f5es da Especializada tamb\u00e9m proporcionaram a suspens\u00e3o de registros de contadores, pris\u00f5es preventivas e o compartilhamento de provas com \u00f3rg\u00e3os federais e o Minist\u00e9rio P\u00fablico.<\/p>\n<p>A equipe da Defaz realizou 1.271 intima\u00e7\u00f5es, 1.857 relat\u00f3rios e 578 ordens de servi\u00e7o em 2025. Al\u00e9m disso, instaurou 50 inqu\u00e9ritos policiais e relatou 115, 74% a mais do que em 2024.<\/p>\n<picture data-fileentryid=\"76684895\"><source srcset=\"\/o\/adaptive-media\/image\/76684895\/Thumbnail-1024x1024\/Defaz.jpeg?t=1768307633007\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.pjc.mt.gov.br\/documents\/d\/pjc\/defaz-jpeg?imageThumbnail=3\" alt=\"\" height=\"267\" \/><\/picture>\n<p>Segundo o delegado Valter de Melo Fonseca J\u00fanior, titular da Defaz, em 2026 a delegacia quer manter o foco nas investiga\u00e7\u00f5es de blindagem patrimonial.<\/p>\n<p>\u201cGarantindo que recursos desviados retornem ao er\u00e1rio e fortale\u00e7am ainda mais a integra\u00e7\u00e3o entre \u00f3rg\u00e3os parceiros. Tamb\u00e9m ser\u00e3o ampliadas as opera\u00e7\u00f5es conjuntas de fiscaliza\u00e7\u00e3o tribut\u00e1ria, verificando o cumprimento das obriga\u00e7\u00f5es fiscais e identificando poss\u00edveis irregularidades\u201d, afirmou o delegado.<\/p>\n<p>O esperado \u00e9 que haja aumento na arrecada\u00e7\u00e3o de tributos, recupera\u00e7\u00e3o de ativos desviados, redu\u00e7\u00e3o na sonega\u00e7\u00e3o de impostos e fortalecimento da transpar\u00eancia e da integridade da gest\u00e3o p\u00fablica.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 |\u00a0 Foto:\u00a0 Pol\u00edcia Civil &#8211; MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Delegacia Especializada em Crimes Fazend\u00e1rios (Defaz), da Pol\u00edcia Civil de Mato Grosso, fechou 2025 &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99190,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-99189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Somente na \u00faltima opera\u00e7\u00e3o do ano, foram bloqueados R$ 78 milh\u00f5es","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99189"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99189\/revisions"}],"predecessor-version":[{"id":99191,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99189\/revisions\/99191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99190"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}