{"id":99192,"date":"2026-01-13T10:57:03","date_gmt":"2026-01-13T14:57:03","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99192"},"modified":"2026-01-13T10:57:03","modified_gmt":"2026-01-13T14:57:03","slug":"trump-anuncia-tarifa-de-25-para-paises-que-negociarem-com-ira-brasil-pode-ser-afetado","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/trump-anuncia-tarifa-de-25-para-paises-que-negociarem-com-ira-brasil-pode-ser-afetado\/","title":{"rendered":"Trump anuncia tarifa de 25% para pa\u00edses que negociarem com Ir\u00e3; Brasil pode ser afetado"},"content":{"rendered":"<p>O governo brasileiro acompanha a publica\u00e7\u00e3o da ordem executiva do presidente dos Estados Unidos, Donald Trump, que estabelece uma tarifa de 25% para pa\u00edses que mantiverem neg\u00f3cios com o Ir\u00e3. A medida, anunciada nas redes sociais do mandat\u00e1rio nesta segunda-feira (12), entra em vigor de forma imediata.<\/p>\n<p>O Brasil pode ser impactado devido \u00e0 rela\u00e7\u00e3o comercial com o Ir\u00e3. Em 2025, o pa\u00eds importou US$ 84,5 milh\u00f5es do Ir\u00e3, principalmente ureia, pistache e uvas secas, e exportou US$ 2,9 bilh\u00f5es, destacando-se milho, soja e a\u00e7\u00facar. Apesar disso, o Ir\u00e3 n\u00e3o est\u00e1 entre os 20 principais parceiros comerciais do Brasil, segundo dados do Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os.<\/p>\n<p>Trump n\u00e3o detalhou se a tarifa vale para pa\u00edses que j\u00e1 mant\u00eam rela\u00e7\u00f5es comerciais com o Ir\u00e3 ou apenas para novas transa\u00e7\u00f5es. Procurados pelo g1, Itamaraty e Presid\u00eancia da Rep\u00fablica n\u00e3o se manifestaram at\u00e9 o momento.<\/p>\n<p>O Brasil j\u00e1 sofre impactos de tarifas aplicadas pelos EUA desde 2025. Inicialmente, Trump aplicou sobretaxa de 10% sobre produtos brasileiros, seguida de aumento de at\u00e9 50% em julho, com exce\u00e7\u00f5es para itens como suco de laranja, aeronaves civis, petr\u00f3leo e ve\u00edculos. Atualmente, cerca de 22% das exporta\u00e7\u00f5es brasileiras ainda est\u00e3o sujeitas a tarifas elevadas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo brasileiro acompanha a publica\u00e7\u00e3o da ordem executiva do presidente dos Estados Unidos, Donald &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99193,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-99192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99192"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99192\/revisions"}],"predecessor-version":[{"id":99194,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99192\/revisions\/99194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99193"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}