{"id":99408,"date":"2026-01-20T14:16:11","date_gmt":"2026-01-20T18:16:11","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99408"},"modified":"2026-01-20T14:16:11","modified_gmt":"2026-01-20T18:16:11","slug":"fachin-retorna-a-brasilia-para-lidar-com-impactos-da-atuacao-de-toffoli-no-caso-banco-master","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/fachin-retorna-a-brasilia-para-lidar-com-impactos-da-atuacao-de-toffoli-no-caso-banco-master\/","title":{"rendered":"Fachin retorna a Bras\u00edlia para lidar com impactos da atua\u00e7\u00e3o de Toffoli no caso Banco Master"},"content":{"rendered":"<p>O presidente do Supremo Tribunal Federal (STF), Edson Fachin, antecipou seu retorno a Bras\u00edlia para esta semana, em meio \u00e0 crise causada pelas decis\u00f5es do ministro Dias Toffoli no caso do Banco Master. Fachin tem se reunido com colegas e mantido contato telef\u00f4nico para discutir o epis\u00f3dio e seus efeitos na imagem da Corte.<\/p>\n<p>O ponto central \u00e9 a manuten\u00e7\u00e3o de Toffoli \u00e0 frente do inqu\u00e9rito, que concentrou no STF todas as decis\u00f5es relacionadas \u00e0 investiga\u00e7\u00e3o, incluindo dilig\u00eancias que antes tramitavam na primeira inst\u00e2ncia. A medida, tomada ap\u00f3s pedido das defesas de diretores do banco, determinou sigilo sobre processos, decis\u00f5es e materiais, limitando o acesso de autoridades e do p\u00fablico \u00e0s informa\u00e7\u00f5es.<\/p>\n<p>Decis\u00f5es incomuns de Toffoli, como a determina\u00e7\u00e3o inicial de que todo o material apreendido fosse enviado ao STF e o controle sobre peritos e lacra\u00e7\u00e3o de objetos, geraram cr\u00edticas da Pol\u00edcia Federal e da Procuradoria-Geral da Rep\u00fablica. A ADPF classificou essas medidas como \u201cat\u00edpicas\u201d e alertou que afastam o planejamento investigativo padr\u00e3o da PF.<\/p>\n<p>Apesar das controv\u00e9rsias, Fachin segue com reuni\u00f5es estrat\u00e9gicas, inclusive com o ministro Fl\u00e1vio Dino em S\u00e3o Lu\u00eds, e busca coordenar a postura da Corte diante do caso, enquanto o julgamento e o andamento das investiga\u00e7\u00f5es continuam sob sigilo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente do Supremo Tribunal Federal (STF), Edson Fachin, antecipou seu retorno a Bras\u00edlia para &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99409,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-99408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99408"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99408\/revisions"}],"predecessor-version":[{"id":99410,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99408\/revisions\/99410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99409"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}