{"id":99470,"date":"2026-01-22T10:45:26","date_gmt":"2026-01-22T14:45:26","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99470"},"modified":"2026-01-22T10:45:26","modified_gmt":"2026-01-22T14:45:26","slug":"cuiaba-mantem-vacinacao-contra-a-dengue-para-criancas-e-adolescentes-de-10-a-14-anos","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/cuiaba-mantem-vacinacao-contra-a-dengue-para-criancas-e-adolescentes-de-10-a-14-anos\/","title":{"rendered":"Cuiab\u00e1 mant\u00e9m vacina\u00e7\u00e3o contra a dengue para crian\u00e7as e adolescentes de 10 a 14 anos"},"content":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por meio da Secretaria Municipal de Sa\u00fade (SMS), segue intensificando a vacina\u00e7\u00e3o contra a dengue em toda a capital. O imunizante est\u00e1 dispon\u00edvel nas 68 Unidades de Sa\u00fade da Fam\u00edlia (USFs) espalhadas pelo munic\u00edpio, garantindo acesso f\u00e1cil e descentralizado \u00e0 popula\u00e7\u00e3o.<\/p>\n<p>A vacina\u00e7\u00e3o \u00e9 destinada a crian\u00e7as e adolescentes de 10 a 14 anos, p\u00fablico-alvo definido pelo Minist\u00e9rio da Sa\u00fade para a aplica\u00e7\u00e3o da vacina Qdenga. O esquema vacinal \u00e9 composto por duas doses, e \u00e9 fundamental que pais e respons\u00e1veis fiquem atentos ao prazo para completar a imuniza\u00e7\u00e3o.<\/p>\n<p>Cuiab\u00e1 dobrou a cobertura na atual gest\u00e3o. Dados do Minist\u00e9rio da Sa\u00fade apontam que, enquanto 9.989 crian\u00e7as e adolescentes receberam a primeira dose da vacina no ano passado, o n\u00famero saltou para 17.209 doses aplicadas em 2025 \u2014 mais do que o dobro do volume registrado anteriormente. A popula\u00e7\u00e3o-alvo, formada por crian\u00e7as e adolescentes de 10 a 14 anos, \u00e9 estimada em 44.306 pessoas, segundo o IBGE.<\/p>\n<p>Para receber a vacina, \u00e9 necess\u00e1rio apresentar documento pessoal da crian\u00e7a ou adolescente, cart\u00e3o do SUS e a caderneta de vacina\u00e7\u00e3o.<\/p>\n<p>A secret\u00e1ria municipal de Sa\u00fade, Danielle Carmona, refor\u00e7a a import\u00e2ncia da ades\u00e3o da popula\u00e7\u00e3o \u00e0 campanha.<\/p>\n<p>\u201cA vacina Qdenga \u00e9 uma ferramenta fundamental na preven\u00e7\u00e3o contra a dengue. N\u00f3s conseguimos avan\u00e7ar muito na cobertura vacinal, mas ainda precisamos que os pais e respons\u00e1veis levem seus filhos \u00e0s unidades de sa\u00fade para garantir a prote\u00e7\u00e3o completa, principalmente com a aplica\u00e7\u00e3o da segunda dose dentro do prazo recomendado\u201d, destacou.<\/p>\n<p>A SMS mant\u00e9m polos fixos de vacina\u00e7\u00e3o, com atendimento regular ao longo da semana, com hor\u00e1rio de atendimento: das 7h \u00e0s 11h e das 13h \u00e0s 17h<\/p>\n<p><strong>Locais de vacina\u00e7\u00e3o em Cuiab\u00e1<\/strong><\/p>\n<p>&#8211; Cl\u00ednica da Fam\u00edlia CPA I<\/p>\n<p>&#8211; USF Tijucal<\/p>\n<p>&#8211; USF Jardim Florian\u00f3polis\/Uni\u00e3o<\/p>\n<p>&#8211; USF Bela Vista\/Carumb\u00e9<\/p>\n<p>&#8211; UBS Nova Esperan\u00e7a<\/p>\n<p>-UBS 1\u00ba de Mar\u00e7o<\/p>\n<p>&#8211; UBS Novo Horizonte<\/p>\n<p>&#8211; UBS Parque Ohara<\/p>\n<p>&#8211; UBS Grande Terceiro<\/p>\n<p>&#8211; UBS Cidade Alta\/Cidade Verde<\/p>\n<p>&#8211; UBS Residencial Coxip\u00f3 III<\/p>\n<p>&#8211; UBS CPA III<\/p>\n<p>&#8211; UBS Quilombo<\/p>\n<p>&#8211; UBS Santa Terezinha<\/p>\n<p>&#8211; UBS Pedra 90 I e II<\/p>\n<p>&#8211; UBS Campo Velho<\/p>\n<p>&#8211; UBS Jardim Leblon<\/p>\n<p>&#8211; UBS Pico do Amor<\/p>\n<p>&#8211; UBS Iza Terezinha Picolli<\/p>\n<p>&#8211; UBS Paiagu\u00e1s<\/p>\n<p>&#8211; UBS Novo Colorado II<\/p>\n<p>&#8211; USF Pico do Amor<\/p>\n<p>&#8211; USF Residencial Paiagu\u00e1s<\/p>\n<p>&#8211; USF Jardim Imperial<\/p>\n<p>&#8211; USF Despraiado<\/p>\n<p>A amplia\u00e7\u00e3o da cobertura vacinal faz parte do conjunto de a\u00e7\u00f5es da Prefeitura de Cuiab\u00e1 para manter os \u00edndices da doen\u00e7a sob controle. Em 2025, o munic\u00edpio mais que dobrou o n\u00famero de doses aplicadas em rela\u00e7\u00e3o ao ano anterior. J\u00e1 em 2026, os dados epidemiol\u00f3gicos apontam uma redu\u00e7\u00e3o expressiva nos casos de dengue, reflexo direto das a\u00e7\u00f5es integradas de vacina\u00e7\u00e3o e combate ao mosquito.<\/p>\n<p>Mesmo com o cen\u00e1rio de controle, a Secretaria Municipal de Sa\u00fade refor\u00e7a que a popula\u00e7\u00e3o n\u00e3o deve relaxar nas medidas de preven\u00e7\u00e3o. Al\u00e9m da vacina\u00e7\u00e3o, \u00e9 essencial eliminar focos de \u00e1gua parada e, ao apresentar sintomas como febre, dor no corpo e dor atr\u00e1s dos olhos, procurar imediatamente uma unidade de sa\u00fade.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prefeitura de Cuiab\u00e1\u00a0 \u00a0|\u00a0 Foto:\u00a0 Jeziel Monteiro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cuiab\u00e1, por meio da Secretaria Municipal de Sa\u00fade (SMS), segue intensificando a &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99472,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-99470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99470"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99470\/revisions"}],"predecessor-version":[{"id":99473,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99470\/revisions\/99473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99472"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}