{"id":99612,"date":"2026-01-30T16:53:05","date_gmt":"2026-01-30T20:53:05","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99612"},"modified":"2026-01-30T16:53:05","modified_gmt":"2026-01-30T20:53:05","slug":"policia-militar-reforca-policiamento-nos-142-municipios-do-estado-com-duas-operacoes","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/policia-militar-reforca-policiamento-nos-142-municipios-do-estado-com-duas-operacoes\/","title":{"rendered":"Pol\u00edcia Militar refor\u00e7a policiamento nos 142 munic\u00edpios do Estado com duas opera\u00e7\u00f5es"},"content":{"rendered":"<p>A Pol\u00edcia Militar de Mato Grosso deflagrou, na manh\u00e3 desta sexta-feira (30.1), a 7\u00aa edi\u00e7\u00e3o da Opera\u00e7\u00e3o Centro Seguro e a 23\u00aa edi\u00e7\u00e3o da Opera\u00e7\u00e3o For\u00e7a Total. Em Cuiab\u00e1, a solenidade ocorreu na Pra\u00e7a da Rep\u00fablica, regi\u00e3o central. As a\u00e7\u00f5es de fortalecimento do policiamento t\u00e1tico e ostensivo, nos 142 munic\u00edpios do Estado, integram o Programa Toler\u00e2ncia Zero Contra as Fac\u00e7\u00f5es Criminosas, criado pelo Governo de Mato Grosso, no combate \u00e0 criminalidade.<\/p>\n<p>At\u00e9 o dia 7 de fevereiro, ser\u00e3o realizadas diversas a\u00e7\u00f5es preventivas como pontos demonstrativos, satura\u00e7\u00f5es e abordagens policiais, com objetivo de garantir a ordem p\u00fablica e combater crimes de roubos, furtos e outras pr\u00e1ticas. A Opera\u00e7\u00e3o For\u00e7a Total \u00e9 realizada em todo o territ\u00f3rio nacional com apoio do Conselho Nacional dos Comandantes-Gerais das Pol\u00edcias Militares (CNCG-PM), e ocorre somente nesta sexta (30).<\/p>\n<picture data-fileentryid=\"77082707\"><source srcset=\"\/o\/adaptive-media\/image\/77082707\/Thumbnail-1024x1024\/WhatsApp+Image+2026-01-30+at+09.34.57+%282%29.jpeg?t=1769780254671\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.pm.mt.gov.br\/documents\/d\/pm\/whatsapp-image-2026-01-30-at-09-34-57-2-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\nO subchefe do Estado Maior, coronel Anderson Luiz do Prado destacou que s\u00e3o duas grandes opera\u00e7\u00f5es de ocorrem de forma simult\u00e2nea em todo o Estado, com o objetivo de intensificar o combate \u00e0 criminalidade e refor\u00e7ar a presen\u00e7a policial em \u00e1reas estrat\u00e9gicas, especialmente em regi\u00f5es com maior fluxo de pessoas e \u00edndices de ocorr\u00eancias.<\/p>\n<p>\u201cAs opera\u00e7\u00f5es Centro Seguro e For\u00e7a Total refor\u00e7am a presen\u00e7a da Pol\u00edcia Militar nas ruas e ampliam nossa capacidade de resposta contra a criminalidade. Com os investimentos realizados pelo Governo do Estado, por meio do programa Toler\u00e2ncia Zero, temos conseguido intensificar as a\u00e7\u00f5es preventivas e repressivas, garantindo mais seguran\u00e7a e tranquilidade \u00e0 popula\u00e7\u00e3o de Mato Grosso\u201d, destacou o coronel Anderson Luiz do Prado.<\/p>\n<p>O policiamento ser\u00e1 refor\u00e7ado com equipes dos batalh\u00f5es de \u00e1rea do 1\u00ba Comando Regional, Cavalaria, Batalh\u00e3o de Rondas Ostensiva T\u00e1tica M\u00f3vel (Rotam), Batalh\u00e3o de Opera\u00e7\u00f5es Especiais (Bope), Batalh\u00e3o de Tr\u00e2nsito Urbano e Rodovi\u00e1rio (BPMTran), Batalh\u00e3o Ambiental (BPMPA), For\u00e7a T\u00e1tica e Companhia de Rondas e a A\u00e7\u00f5es Intensivas Ostensivas (Raio).<\/p>\n<p>&#8220;O planejamento operacional foi estruturado para atuar de forma integrada e estrat\u00e9gica, com emprego de efetivo e recursos em pontos sens\u00edveis. Nosso objetivo \u00e9 prevenir crimes, aumentar as abordagens e garantir mais seguran\u00e7a \u00e0 popula\u00e7\u00e3o. O programa Toler\u00e2ncia Zero tem permitido \u00e0 Pol\u00edcia Militar ampliar sua capacidade de atua\u00e7\u00e3o&#8221;, enfatizou o comandante do Comando Regional de Cuiab\u00e1, coronel Lima J\u00fanior.<\/p>\n<picture data-fileentryid=\"77082944\"><source srcset=\"\/o\/adaptive-media\/image\/77082944\/Thumbnail-1024x1024\/WhatsApp+Image+2026-01-30+at+09.34.57+%283%29.jpeg?t=1769780271752\" media=\"(max-width:1024px)\" \/><img decoding=\"async\" src=\"https:\/\/www.pm.mt.gov.br\/documents\/d\/pm\/whatsapp-image-2026-01-30-at-09-34-57-3-jpeg?imageThumbnail=3\" alt=\"\" height=\"266\" \/><\/picture>\n&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Militar de Mato Grosso deflagrou, na manh\u00e3 desta sexta-feira (30.1), a 7\u00aa edi\u00e7\u00e3o &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99613,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[],"class_list":["post-99612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"wps_subtitle":"Em Cuiab\u00e1, a solenidade ocorreu na Pra\u00e7a da Rep\u00fablica, regi\u00e3o central da Capital","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99612"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99612\/revisions"}],"predecessor-version":[{"id":99614,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99612\/revisions\/99614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99613"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}