{"id":99635,"date":"2026-02-02T10:40:40","date_gmt":"2026-02-02T14:40:40","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99635"},"modified":"2026-02-02T10:40:40","modified_gmt":"2026-02-02T14:40:40","slug":"tempo-de-resposta-ao-cidadao-em-licenciamento-convencional-reduz-em-mais-de-78-em-oito-anos","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/tempo-de-resposta-ao-cidadao-em-licenciamento-convencional-reduz-em-mais-de-78-em-oito-anos\/","title":{"rendered":"Tempo de resposta ao cidad\u00e3o em licenciamento convencional reduz em mais de 78%, em oito anos"},"content":{"rendered":"<p>A Secretaria de Estado de Meio Ambiente (Sema-MT) concluiu quase seis mil processos de licenciamento em 2025. Se comparado a 2018, o tempo m\u00e9dio para an\u00e1lise do licenciamento trif\u00e1sico (sem Estudo e Relat\u00f3rio de Impacto Ambiental) reduziu em mais de 78%, saindo de 230 dias para 50 dias, no \u00faltimo ano.<\/p>\n<p>O licenciamento trif\u00e1sico convencional abrange as licen\u00e7as pr\u00e9via (LP), de instala\u00e7\u00e3o (LI) e opera\u00e7\u00e3o (LO). O tempo m\u00e9dio de resposta ao cidad\u00e3o registrado no ano passado variou entre dois a 50 dias. Ao todo, foram conclu\u00eddos 5.745 processos.<\/p>\n<p>De acordo com a secret\u00e1ria de Estado de Meio Ambiente, Mauren Lazzaretti, o Governo de Mato Grosso vem, desde 2019, aprimorando a gest\u00e3o para dar mais celeridade \u00e0s an\u00e1lises de licenciamento, proporcionado ao cidad\u00e3o o acesso \u00e0 legaliza\u00e7\u00e3o.<\/p>\n<p>Al\u00e9m de adotar novas ferramentas para acelerar o atendimento \u00e0s demandas, o Estado de Mato Grosso tamb\u00e9m promoveu altera\u00e7\u00f5es na legisla\u00e7\u00e3o, estabelecendo prazos de an\u00e1lise diferenciados para cada modalidade de licen\u00e7a de acordo com as peculiaridades da atividade ou empreendimento.<\/p>\n<p>A secret\u00e1ria destaca que em 2020 foram institu\u00eddas duas novas modalidades de licen\u00e7as ambientais, a simplificada (LAS) e por ades\u00e3o e compromisso (LAC) , al\u00e9m das modalidades j\u00e1 previstas na legisla\u00e7\u00e3o federal (LP, LI e LO).<\/p>\n<p>\u201cA legisla\u00e7\u00e3o federal estabelece o prazo de 180 dias para an\u00e1lise conclusiva da LP, LI e LO. Em Mato Grosso, institu\u00edmos prazos menores para as duas novas modalidades institu\u00eddas. Para a LAS, o prazo \u00e9 de 60 dias, e para LAC 30 dias\u201d, explica a secret\u00e1ria.<\/p>\n<p>Ela afirma, no entanto, que devido \u00e0 moderniza\u00e7\u00e3o da gest\u00e3o, as an\u00e1lises est\u00e3o ainda mais c\u00e9leres. \u201cNos processos de LAC (Licen\u00e7a por Ades\u00e3o e Compromisso) o tempo m\u00e9dio \u00e9 de dois dias, sendo que a maioria dos processos \u00e9 analisado no mesmo dia que \u00e9 apresentado. Na LAS (Licen\u00e7a Ambiental Simplificada) esse tempo \u00e9 de 25 dias\u201d.<\/p>\n<p>Para este ano, conforme a secret\u00e1ria, o \u00f3rg\u00e3o ambiental se prepara para incorporar as novas regras da Lei Geral do Licenciamento Ambiental. Ainda no primeiro bimestre, o Governo de Mato Grosso deve lan\u00e7ar dois m\u00f3dulos atualizados de licenciamento florestal e de empreendimentos.<\/p>\n<p>\u201cAs medidas implementadas nos \u00faltimos anos garantem ao \u00f3rg\u00e3o ambiental as condi\u00e7\u00f5es necess\u00e1rias para adequa\u00e7\u00e3o \u00e0s exig\u00eancias previstas na Lei Geral do Licenciamento Ambiental (Lei 15.190\/2025)\u201d, adianta.<\/p>\n<p>Segundo ela, algumas inova\u00e7\u00f5es trazidas pela lei, a exemplo da Licen\u00e7a por Ades\u00e3o e Compromisso (LAC), j\u00e1 s\u00e3o realidade em Mato Grosso.<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 |\u00a0 Foto:\u00a0 Karla Silva<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Meio Ambiente (Sema-MT) concluiu quase seis mil processos de licenciamento &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99636,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-99635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"O licenciamento trif\u00e1sico convencional abrange as licen\u00e7as pr\u00e9via (LP), de instala\u00e7\u00e3o (LI) e opera\u00e7\u00e3o (LO). O tempo m\u00e9dio de resposta ao cidad\u00e3o em 2025 variou entre dois a 50 dias","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99635"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99635\/revisions"}],"predecessor-version":[{"id":99637,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99635\/revisions\/99637"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99636"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}