{"id":99846,"date":"2026-02-11T09:30:48","date_gmt":"2026-02-11T13:30:48","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99846"},"modified":"2026-02-11T09:30:48","modified_gmt":"2026-02-11T13:30:48","slug":"hospital-central-faz-primeira-cirurgia-robotica-pelo-sus-em-mato-grosso","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/hospital-central-faz-primeira-cirurgia-robotica-pelo-sus-em-mato-grosso\/","title":{"rendered":"Hospital Central faz primeira cirurgia rob\u00f3tica pelo SUS em Mato Grosso"},"content":{"rendered":"<p>O Hospital Central de Alta Complexidade do Estado, unidade do Governo de Mato Grosso administrada pelo Einstein, realiza nesta quarta-feira (11.2) a primeira cirurgia rob\u00f3tica do Sistema \u00danico de Sa\u00fade (SUS) de Mato Grosso. Al\u00e9m dessa, ser\u00e3o realizados outros 13 procedimentos cir\u00fargicos nesta semana, em pacientes adultos e crian\u00e7as.<\/p>\n<p>O secret\u00e1rio de Estado de Sa\u00fade, Gilberto Figueiredo, destacou o ineditismo da a\u00e7\u00e3o. \u201cAl\u00e9m de ser a primeira cirurgia rob\u00f3tica pelo SUS em Mato Grosso, \u00e9 tamb\u00e9m uma das primeiras cirurgias deste emblem\u00e1tico hospital, projeto que ficou abandonado por 34 anos em Cuiab\u00e1, mas que foi retomado e entregue pela atual gest\u00e3o do Governo do Estado. \u00c9 emocionante e hist\u00f3rico ver o Hospital Central iniciar as cirurgias com um procedimento tamb\u00e9m in\u00e9dito no SUS do nosso estado. Quem ganha \u00e9 a popula\u00e7\u00e3o\u201d, avalia.<\/p>\n<p>A cirurgia rob\u00f3tica ser\u00e1 uma prostatectomia para remo\u00e7\u00e3o total da pr\u00f3stata, para tratamento de c\u00e2ncer. De acordo com o urologista e cirurgi\u00e3o rob\u00f3tico Fernando Le\u00e3o, do Einstein Hospital Israelita, organiza\u00e7\u00e3o gestora do Hospital Central, esse tipo de interven\u00e7\u00e3o apresenta diversos benef\u00edcios para os pacientes, assim como para os m\u00e9dicos.<\/p>\n<p>\u201cUsando o rob\u00f4, o cirurgi\u00e3o atua de forma mais precisa, o que minimiza os efeitos da cirurgia para o paciente. Al\u00e9m disso, o m\u00e9dico tem seu campo de vis\u00e3o ampliado em at\u00e9 dez vezes e ganha mais amplitude de movimentos devido \u00e0 pin\u00e7a rob\u00f3tica flex\u00edvel\u201d, explica Le\u00e3o, que se tornou cirurgi\u00e3o rob\u00f3tico pelo Programa de Rob\u00f3tica do Einstein.<\/p>\n<p>Al\u00e9m dele, pelo menos seis outros profissionais (anestesiologistas, instrumentadores, enfermeiros e t\u00e9cnicos de enfermagem) participam do primeiro procedimento cir\u00fargico a utilizar rob\u00f3tica no SUS de Mato Grosso.<\/p>\n<p>O in\u00edcio das cirurgias \u00e9 um importante marco na hist\u00f3ria do Hospital Central, que come\u00e7ou a atender em 19 de janeiro de 2026. O atendimento est\u00e1 sendo feito por fases, iniciando com pediatria, urologia, ortopedia e cardiologia. Gradativamente, a unidade est\u00e1 ampliando tanto a oferta de especialidades m\u00e9dicas quanto a de tipos de procedimentos.<\/p>\n<p>\u201cAgora, ampliamos o cuidado aos pacientes em todas as etapas: atendimento ambulatorial, diagn\u00f3stico e cirurgia\u201d, explica a diretora hospitalar da unidade, Alessandra Bokor.<\/p>\n<p>A previs\u00e3o \u00e9 de que, ainda no primeiro semestre, o hospital atinja a capacidade plena, abrangendo especialidades como cirurgia geral e do aparelho digestivo, ginecologia, mastologia, cardiologia, cirurgia vascular, neurocirurgia, onco-ortopedia e cirurgia cardiovascular.<\/p>\n<p>\u201cEstamos trazendo para Mato Grosso toda a expertise em cirurgia rob\u00f3tica do Einstein. Com a rob\u00f3tica, a pr\u00e1tica m\u00e9dica ganha mais precis\u00e3o nas cirurgias, porque o cirurgi\u00e3o tem uma visualiza\u00e7\u00e3o melhor de tecidos e mais controle dos movimentos. Com isso, diminui o risco de complica\u00e7\u00f5es e o paciente tem o per\u00edodo de recupera\u00e7\u00e3o reduzido\u201d, conclui Alessandra Bokor.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 |\u00a0 Foto:\u00a0 Tonico Pinheiro | Secom-MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Hospital Central de Alta Complexidade do Estado, unidade do Governo de Mato Grosso administrada &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-99846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Nesta semana, outros 13 procedimentos ser\u00e3o realizados na unidade, entre cirurgias urol\u00f3gicas e pedi\u00e1tricas ","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99846"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99846\/revisions"}],"predecessor-version":[{"id":99848,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99846\/revisions\/99848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99847"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}