{"id":99927,"date":"2026-02-13T10:39:41","date_gmt":"2026-02-13T14:39:41","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99927"},"modified":"2026-02-13T10:39:41","modified_gmt":"2026-02-13T14:39:41","slug":"mato-grosso-cria-comissao-de-fertilidade-do-solo-para-fortalecer-producao-agricola","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mato-grosso-cria-comissao-de-fertilidade-do-solo-para-fortalecer-producao-agricola\/","title":{"rendered":"Mato Grosso cria Comiss\u00e3o de Fertilidade do Solo para fortalecer produ\u00e7\u00e3o agr\u00edcola"},"content":{"rendered":"<p>Mato Grosso deu mais um passo para fortalecer a base t\u00e9cnica da sua produ\u00e7\u00e3o agr\u00edcola com a cria\u00e7\u00e3o da Comiss\u00e3o de Fertilidade do Solo do Estado (CFS-MT). A iniciativa foi institu\u00edda durante a 1\u00aa reuni\u00e3o ordin\u00e1ria do Comit\u00ea Gestor de Fertilizantes e Bioinsumos de Mato Grosso, realizada nesta quinta-feira (12.2), e busca ampliar a efici\u00eancia no uso de fertilizantes, elevar a produtividade no campo e contribuir para a competitividade do agroneg\u00f3cio mato-grossense.<\/p>\n<p>Maior produtor agr\u00edcola do pa\u00eds, Mato Grosso demanda grandes volumes de fertilizantes para sustentar sua produ\u00e7\u00e3o. Nesse contexto, iniciativas voltadas ao fortalecimento t\u00e9cnico e cient\u00edfico da cadeia produtiva s\u00e3o estrat\u00e9gicas para ampliar a efici\u00eancia e a sustentabilidade no campo. A cria\u00e7\u00e3o da comiss\u00e3o tamb\u00e9m busca avan\u00e7ar na padroniza\u00e7\u00e3o de m\u00e9todos e recomenda\u00e7\u00f5es, promovendo maior seguran\u00e7a e precis\u00e3o nas an\u00e1lises e no manejo do solo, com reflexos positivos na produtividade e na rentabilidade dos produtores.<\/p>\n<p>A coordena\u00e7\u00e3o da CFS-MT ficar\u00e1 a cargo do engenheiro agr\u00f4nomo e t\u00e9cnico agr\u00edcola Milton Moraes, que destacou a relev\u00e2ncia estrat\u00e9gica da iniciativa diante do cen\u00e1rio nacional de produ\u00e7\u00e3o e importa\u00e7\u00e3o de fertilizantes. \u201cHoje, importamos 90% e produzimos 10% dos fertilizantes consumidos aqui no Brasil. O plano \u00e9 que, em 2050, estaremos importando 50%. N\u00e3o \u00e9 uma tarefa t\u00e3o f\u00e1cil. Diante disso, o plano nacional e os planos estaduais est\u00e3o sendo criados. Mato Grosso foi o segundo estado a criar um plano estadual\u201d, afirmou.<\/p>\n<p>Entre os objetivos da comiss\u00e3o est\u00e3o a elabora\u00e7\u00e3o e atualiza\u00e7\u00e3o das recomenda\u00e7\u00f5es oficiais de corre\u00e7\u00e3o do solo e de aduba\u00e7\u00e3o, a padroniza\u00e7\u00e3o e atualiza\u00e7\u00e3o dos m\u00e9todos oficiais de an\u00e1lise de solos, tecido vegetal, corretivos, fertilizantes e outros materiais de interesse agr\u00edcola e a defini\u00e7\u00e3o de demandas priorit\u00e1rias de pesquisa em fertilidade do solo e nutri\u00e7\u00e3o mineral de plantas, para financiamento por institui\u00e7\u00f5es de fomento.<\/p>\n<p>A comiss\u00e3o ser\u00e1 composta por representantes de institui\u00e7\u00f5es de ensino, pesquisa, assist\u00eancia t\u00e9cnica e extens\u00e3o rural, produtores rurais, \u00f3rg\u00e3os de fiscaliza\u00e7\u00e3o e demais entidades sediadas ou atuantes em Mato Grosso na \u00e1rea de ci\u00eancia do solo, com \u00eanfase em fertilidade, nutri\u00e7\u00e3o de plantas e aduba\u00e7\u00e3o.<\/p>\n<p>Para a secret\u00e1ria adjunta de Agroneg\u00f3cios, Cr\u00e9dito e Energia da Secretaria de Estado de Desenvolvimento Econ\u00f4mico (Sedec-MT), Linacis Silva Vogel Lisboa, a cria\u00e7\u00e3o da comiss\u00e3o representa um avan\u00e7o importante para o fortalecimento do setor produtivo.<\/p>\n<p>\u201cA cria\u00e7\u00e3o dessa comiss\u00e3o \u00e9 estrat\u00e9gica para Mato Grosso, porque fortalece as bases t\u00e9cnicas e cient\u00edficas que orientam o uso mais eficiente dos insumos e o manejo sustent\u00e1vel da produ\u00e7\u00e3o. Ao reunir institui\u00e7\u00f5es de pesquisa, ensino e o setor produtivo, a iniciativa amplia a gera\u00e7\u00e3o de conhecimento, incentiva a inova\u00e7\u00e3o e cria condi\u00e7\u00f5es para aumentar a competitividade do agroneg\u00f3cio, com reflexos diretos na produtividade e na seguran\u00e7a da produ\u00e7\u00e3o no estado\u201d, destacou.<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mato Grosso deu mais um passo para fortalecer a base t\u00e9cnica da sua produ\u00e7\u00e3o agr\u00edcola &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99928,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-99927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Iniciativa busca padronizar an\u00e1lises, atualizar recomenda\u00e7\u00f5es t\u00e9cnicas e fortalecer a base cient\u00edfica que orienta o manejo do solo","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99927"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99927\/revisions"}],"predecessor-version":[{"id":99929,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99927\/revisions\/99929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99928"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}