{"id":99985,"date":"2026-02-19T09:01:19","date_gmt":"2026-02-19T13:01:19","guid":{"rendered":"https:\/\/www.cfnews.com.br\/portal\/?p=99985"},"modified":"2026-02-19T09:01:19","modified_gmt":"2026-02-19T13:01:19","slug":"mato-grosso-divulga-resultado-da-fluencia-leitora-2025-e-registra-maior-avanco-em-cinco-anos","status":"publish","type":"post","link":"https:\/\/www.cfnews.com.br\/portal\/mato-grosso-divulga-resultado-da-fluencia-leitora-2025-e-registra-maior-avanco-em-cinco-anos\/","title":{"rendered":"Mato Grosso divulga resultado da flu\u00eancia leitora 2025 e registra maior avan\u00e7o em cinco anos"},"content":{"rendered":"<p>A Secretaria de Estado de Educa\u00e7\u00e3o de Mato Grosso (Seduc-MT) divulgou os resultados da Avalia\u00e7\u00e3o de Flu\u00eancia Leitora \u2013 Sa\u00edda 2025, com foco nos estudantes do 2\u00ba ano do Ensino Fundamental da rede p\u00fablica estadual e municipal.<\/p>\n<p>Aplicada desde 2021, a avalia\u00e7\u00e3o \u00e9 uma ferramenta diagn\u00f3stica que mede a capacidade de leitura em voz alta, considerando precis\u00e3o, velocidade e pros\u00f3dia, permitindo classificar os alunos em perfis como pr\u00e9-leitor, iniciante ou fluente.<\/p>\n<p>Para a Seduc, os dados de 2025 confirmam um avan\u00e7o hist\u00f3rico na alfabetiza\u00e7\u00e3o em Mato Grosso. O \u00cdndice de Flu\u00eancia Leitora (IFL) apresentou crescimento progressivo nos \u00faltimos tr\u00eas anos, saindo de 5,9 em 2023 para 6,2 em 2024 e alcan\u00e7ando 6,9 em 2025, em uma escala que vai at\u00e9 10.<\/p>\n<p>A participa\u00e7\u00e3o dos estudantes se manteve acima de 95%, refor\u00e7ando o engajamento das redes e a confiabilidade dos resultados.<\/p>\n<p>A s\u00e9rie hist\u00f3rica tamb\u00e9m evidencia a redu\u00e7\u00e3o significativa do n\u00famero de alunos classificados como pr\u00e9-leitores nos n\u00edveis 1, 2 e 3, ao mesmo tempo em que cresce o percentual de estudantes leitores. Esse desempenho representa o maior avan\u00e7o registrado nos \u00faltimos cinco anos do programa Alfabetiza MT, consolidando uma pol\u00edtica p\u00fablica focada em resultados concretos na aprendizagem.<\/p>\n<p>O grande diferencial de 2025 foi a amplia\u00e7\u00e3o da avalia\u00e7\u00e3o de flu\u00eancia leitora para alunos do 5\u00ba, 7\u00ba e 9\u00ba ano do Ensino Fundamental. A iniciativa oferece \u00e0s escolas mais um instrumento de an\u00e1lise pedag\u00f3gica, permitindo identificar estudantes que ainda apresentam defasagens na alfabetiza\u00e7\u00e3o e, assim, planejar a\u00e7\u00f5es de interven\u00e7\u00e3o e recomposi\u00e7\u00e3o das habilidades ainda n\u00e3o consolidadas.<\/p>\n<p>Para o secret\u00e1rio de Estado de Educa\u00e7\u00e3o, Alan Porto, os resultados da avalia\u00e7\u00e3o, divulgados em 13 de fevereiro, evidenciam o impacto direto do esfor\u00e7o coletivo das redes de ensino. Segundo ele, os indicadores confirmam o comprometimento de gestores, professores e equipes pedag\u00f3gicas com a melhoria da aprendizagem e o fortalecimento das pol\u00edticas educacionais voltadas \u00e0 alfabetiza\u00e7\u00e3o.<\/p>\n<p>\u201cEsse crescimento expressivo \u00e9 fruto direto do regime de colabora\u00e7\u00e3o entre o Estado e os munic\u00edpios. O m\u00e9rito \u00e9 dos professores alfabetizadores e das Secretarias Municipais de Educa\u00e7\u00e3o, que abra\u00e7aram a pol\u00edtica de alfabetiza\u00e7\u00e3o na idade certa e fazem a diferen\u00e7a dentro da sala de aula\u201d, destacou.<\/p>\n<p>Por fim, ele acrescenta que \u201cos avan\u00e7os comprovam a for\u00e7a da parceria Estado-Munic\u00edpio em Mato Grosso e reafirma o compromisso de seguir investindo em pol\u00edticas educacionais que garantam a alfabetiza\u00e7\u00e3o na idade certa, assegurando que cada estudante tenha acesso a uma aprendizagem de qualidade desde os primeiros anos escolares\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MTGOV\u00a0 |\u00a0 Foto:\u00a0 Seduc<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Educa\u00e7\u00e3o de Mato Grosso (Seduc-MT) divulgou os resultados da Avalia\u00e7\u00e3o &hellip;<\/p>\n","protected":false},"author":4,"featured_media":99986,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-99985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cf-news"],"wps_subtitle":"Avalia\u00e7\u00e3o do 2\u00ba ano alcan\u00e7a mais de 95% de participa\u00e7\u00e3o; \u00edndice de flu\u00eancia leitora chega a 6,9","_links":{"self":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/comments?post=99985"}],"version-history":[{"count":1,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99985\/revisions"}],"predecessor-version":[{"id":99987,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/posts\/99985\/revisions\/99987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media\/99986"}],"wp:attachment":[{"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/media?parent=99985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/categories?post=99985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cfnews.com.br\/portal\/wp-json\/wp\/v2\/tags?post=99985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}